{"id":108136,"date":"2021-08-30T12:46:00","date_gmt":"2021-08-30T10:46:00","guid":{"rendered":"https:\/\/brand24.com\/blog\/?p=108136"},"modified":"2026-04-13T14:24:29","modified_gmt":"2026-04-13T12:24:29","slug":"3-ejemplos-reales-de-empresas-grandes-y-pequenas-que-ofrecen-un-buen-servicio-de-atencion-al-cliente-en-el-sector-minorista","status":"publish","type":"post","link":"https:\/\/brand24.com\/blog\/es\/3-real-life-examples-of-good-customer-service-in-retail-from-companies-large-and-small\/","title":{"rendered":"8 ejemplos reales de buen servicio al cliente en el comercio minorista, de empresas grandes y peque\u00f1as"},"content":{"rendered":"<p class=\"wp-block-paragraph\">\u00bfQu\u00e9 empresa destaca inmediatamente cuando piensa en ejemplos de buen servicio al cliente en el comercio minorista?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tal vez est\u00e9 pensando en una empresa que haya puesto en pr\u00e1ctica una de sus sugerencias y haya mejorado su producto.\u00a0<em>y<\/em>\u00a0\u00bfha demostrado que los formularios de opini\u00f3n de sus clientes no son s\u00f3lo una fachada? \u00bfO tuvo una experiencia memorable\u00a0<em>cancelaci\u00f3n<\/em>-experiencia relacionada con el servicio de atenci\u00f3n al cliente con un minorista online - y te demostr\u00f3 que estos tipos (a diferencia del resto)\u00a0<em>no<\/em> para intentar dejarte seco, convirti\u00e9ndolos en tu nuevo mercado online? <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O <em>tal vez<\/em>\u00a0su mejor experiencia de atenci\u00f3n al cliente fue un poco m\u00e1s personal (m\u00e1s\u00a0<em>humano)<\/em>\u00a0\u00bfy fue s\u00f3lo porque te trataron como algo m\u00e1s que otra muesca en su cintur\u00f3n de captaci\u00f3n de clientes?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Independientemente de cu\u00e1l haya sido su experiencia personal con un buen servicio de atenci\u00f3n al cliente, no cabe duda de que le caus\u00f3 una impresi\u00f3n positiva y tambi\u00e9n hizo que esa empresa en concreto destacara como una <em>mejor<\/em> opci\u00f3n que el resto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No son pocas las formas en que las marcas y las empresas destacan entre la multitud con un servicio de atenci\u00f3n al cliente impresionante. \u00bfC\u00f3mo?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eche un vistazo a estos ejemplos de buena atenci\u00f3n al cliente en el comercio minorista que se han difundido ONLINE <em>(\u00bfno es ah\u00ed donde todo acaba, al final?)<\/em>:<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"index\">8 ejemplos reales de buen servicio de atenci\u00f3n al cliente en el comercio minorista, de empresas grandes y peque\u00f1as<\/h2>\n\n\n\n<ol class=\"wp-block-list\">\n<li><a href=\"#how_amazon_and_virgin_trains_east_coast_provide_good_service_by_making_their_customers_feel_special\">C\u00f3mo Amazon y Virgin Trains East Coast ofrecen un buen servicio haciendo que sus clientes se sientan especiales<\/a><\/li>\n\n\n\n<li><a href=\"#how_raos_delivers_good_service_by_helping_their_customers_save_time\">C\u00f3mo Rao's ofrece un buen servicio ayudando a sus clientes a ahorrar tiempo<\/a><\/li>\n\n\n\n<li><a href=\"#how_kershaw_knives_excels_in_customer_service_with_excellent_aftercare\">C\u00f3mo sobresale Kershaw Knives en servicio al cliente con un excelente servicio postventa<\/a><\/li>\n\n\n\n<li><a href=\"#how_this_hotel_makes_its_customers_think_why_would_you_want_to_go_anywhere_else\">C\u00f3mo este hotel hace pensar a sus clientes&nbsp;<em>'\u00bfpor qu\u00e9 querr\u00edas ir a otro sitio<\/em><em>?\u2019<\/em><\/a><\/li>\n\n\n\n<li><a href=\"#how_this_candy_store_provides_great_service_by_making_a_positive_impact_on_its_customers_lives\">C\u00f3mo esta tienda de golosinas presta un gran servicio influyendo positivamente en la vida de sus clientes.<\/a><\/li>\n\n\n\n<li><a href=\"#how_side_project_brewery_wins_their_customers_affections_by_implementing_customer_feedback\">C\u00f3mo la cervecer\u00eda Side Project se gana el afecto de sus clientes aplicando las opiniones de \u00e9stos<\/a><\/li>\n\n\n\n<li><a href=\"#how_real_canadian_superstore_provides_awesome_service_by_interacting_with_their_customers\">C\u00f3mo Real Canadian Superstore ofrece un servicio incre\u00edble interactuando con sus clientes<\/a><\/li>\n\n\n\n<li><a href=\"#how_deep_sea_headquarters_avoided_disaster_for_their_business_by_providing_good_customer_service_on_a_regular_basis\">C\u00f3mo Deep Sea Headquarters evit\u00f3 el desastre para su negocio ofreciendo un buen servicio al cliente de forma regular<\/a><\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\">Ofrecer un buen servicio de atenci\u00f3n al cliente puede suponer una gran diferencia a la hora de fidelizar a los clientes, aumentar las ventas y reducir la p\u00e9rdida de clientes. Porque la gente habla y comparte sus experiencias positivas y negativas en Internet, especialmente en las redes sociales. Las opiniones personales, las cr\u00edticas y otros tipos de comentarios de los clientes circulan por Internet, <em>aunque hayan ocurrido fuera de l\u00ednea<\/em>.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">La investigaci\u00f3n de ThinkJar muestra que 13% de los clientes compartir\u00e1n una experiencia negativa de atenci\u00f3n al cliente con 15 o m\u00e1s personas. Por otro lado, 72% de los consumidores compartir\u00e1n una experiencia positiva con 6 o m\u00e1s personas.<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Hagamos cuentas: si tiene 100 clientes y 13 de ellos comparten una experiencia negativa de atenci\u00f3n al cliente con 15 personas cada uno, <strong>195 personas<\/strong>&nbsp;<strong>conocer las opiniones negativas de los clientes sobre su empresa<\/strong>aunque <em>s\u00f3lo 13<\/em> tenido malas experiencias.&nbsp;<em>Ese es el poder de Internet.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Supongamos que tiene 100 clientes y que 72 de ellos comparten una experiencia positiva con 6 personas cada uno,&nbsp;<strong>432 personas<\/strong>&nbsp;<strong>conocer\u00e1n experiencias positivas con su empresa<\/strong> (mucho m\u00e1s de 72).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los comentarios de sus clientes en l\u00ednea tienen un <em>lote<\/em> m\u00e1s alcance que los 13 o 72 clientes originales a los que su empresa prest\u00f3 realmente servicios.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Adem\u00e1s, seg\u00fan un estudio de American Express, 86% de los consumidores est\u00e1n dispuestos a pagar m\u00e1s por una buena experiencia GARANTIZADA.<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">El \u00e9nfasis en <em>garantizado<\/em> nos dice que la promesa de una buena experiencia es esperada y no destaca para los consumidores. Quieren <em>prueba<\/em> que habr\u00e1 un buen servicio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La prueba m\u00e1s convincente del buen servicio garantizado que puede ofrecer a sus clientes potenciales es mostrarles opiniones positivas de otros clientes, sobre todo si se trata de historias y comentarios sinceros sobre la buena atenci\u00f3n al cliente que recibe de su empresa. Puede incrustar comentarios positivos de diversos clientes y plataformas directamente en su propio sitio web con un <a href=\"https:\/\/brand24.com\/es\/widget\/\" target=\"_blank\" rel=\"noreferrer noopener\">Widget<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Acu\u00e9rdate:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>No tener noticias de sus clientes no significa que est\u00e9n satisfechos.<\/li>\n\n\n\n<li><em>Prometedor<\/em> que ofrecer\u00e1 un buen servicio al cliente no es suficiente. Los consumidores quieren una garant\u00eda, o <em>prueba,&nbsp;<\/em>que tengan una buena experiencia.<\/li>\n\n\n\n<li>La gente no s\u00f3lo habla de sus experiencias en la tienda mientras est\u00e1 en ella. Lo comentan en Internet, en las redes sociales, en foros, en sitios de opiniones, en persona, etc. Tanto si se trata de 195 clientes enfadados como de 432 clientes satisfechos, aseg\u00farese de que est\u00e1 escuchando: las herramientas adecuadas pueden ayudarle a conocer todas las opiniones de sus clientes en Internet para que no tenga que perder tiempo busc\u00e1ndolas.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Escuchar eficazmente con la supervisi\u00f3n de los medios (sociales)<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La forma m\u00e1s r\u00e1pida y sencilla de averiguar qu\u00e9 dicen los clientes de su empresa es a trav\u00e9s de la monitorizaci\u00f3n de las redes sociales, tambi\u00e9n conocida como \"monitorizaci\u00f3n de las redes sociales\". <a href=\"https:\/\/brand24.com\/blog\/es\/que-es-la-escucha-social\/\" target=\"_blank\" rel=\"noreferrer noopener\" title=\"social listening\">social listening<\/a>. Una herramienta de seguimiento de medios como <a href=\"https:\/\/brand24.com\/blog\/es\/\" target=\"_blank\" rel=\"noreferrer noopener\">Brand24<\/a> rastrea la web y recupera las menciones p\u00fablicas disponibles de sus palabras clave (rastrea cosas como su empresa, marca o producto) para que sepa <em>qui\u00e9n, d\u00f3nde, cu\u00e1ndo<\/em> y <em>por qu\u00e9<\/em> la gente est\u00e1 hablando de ti... as\u00ed como el tipo de historias que se est\u00e1n compartiendo <em>(\u00a1Control de da\u00f1os!)<\/em>. As\u00ed es como funciona:<\/p>\n\n\n\n<figure><\/figure>\n\n\n\n<p class=\"has-text-align-center has-white-color has-text-color has-background wp-block-paragraph\" style=\"background-color:#1e2c48\"><strong><a href=\"https:\/\/app.brand24.com\/user\/register-account\/?custom_form=10\" target=\"_blank\" rel=\"noreferrer noopener\" title=\"https:\/\/app.brand24.com\/user\/register-account\/?custom_form=10\">Lleve su servicio de atenci\u00f3n al cliente al siguiente nivel con la supervisi\u00f3n de los medios de comunicaci\u00f3n<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las empresas que realmente <i>escuche<\/i> a sus clientes son las que tienen los clientes m\u00e1s fieles. Y cuantos m\u00e1s comentarios positivos de los clientes pueda encontrar, m\u00e1s pruebas de una <i>garantizado<\/i> buena experiencia que pueda mostrar a sus clientes potenciales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">He aqu\u00ed 8 ejemplos, de empresas grandes y peque\u00f1as, que realmente entienden lo que significa ofrecer un buen servicio de atenci\u00f3n al cliente en el comercio minorista. Vea c\u00f3mo marcan la pauta y aprenda c\u00f3mo&nbsp;<em>su<\/em>&nbsp;empresa tambi\u00e9n podr\u00eda ser un ejemplo de buen servicio al cliente...<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"how_amazon_and_virgin_trains_east_coast_provide_good_service_by_making_their_customers_feel_special\">1. Sea un ejemplo de buen servicio al cliente en el comercio minorista haciendo todo lo posible para que sus clientes se sientan especiales.<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Porque las reglas se hicieron para romperlas.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfCu\u00e1ntas veces has prometido en silencio tu lealtad a una marca o empresa porque se han saltado las normas por ti (aunque s\u00f3lo fuera por algo insignificante)?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eso me ha pasado recientemente con Amazon. Me hab\u00eda suscrito a Prime, pero decid\u00ed cancelarlo porque hab\u00edan dejado de vender el producto que normalmente les ped\u00eda. Me hab\u00eda pasado un d\u00eda del periodo de renovaci\u00f3n mensual, pero tras ponerme en contacto con su servicio de atenci\u00f3n al cliente, me reembolsaron r\u00e1pidamente la cuota de suscripci\u00f3n de ese mes y cancelaron inmediatamente mi cuenta. Todo en menos de 10 minutos y sin ning\u00fan problema.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>S\u00e9 que llegu\u00e9 un d\u00eda tarde, pero lo lograron.<\/em> Es como si hubieran hecho una excepci\u00f3n, s\u00f3lo para m\u00ed. Y definitivamente no dudar\u00e9 en volver a hacer negocios con ellos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hacer peque\u00f1os \"favores\" de este tipo a sus clientes puede aumentar significativamente la fidelidad y la confianza de \u00e9stos en su marca.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sobre todo si ves situaciones en las que saltarse un poco las normas puede marcar la diferencia en la vida de alguien:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote twitter-tweet is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Muchas gracias al incre\u00edble servicio de atenci\u00f3n al cliente de <a href=\"https:\/\/twitter.com\/Virgin_TrainsEC?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">@Virgin_TrainsEC<\/a> personal, no s\u00f3lo nos han permitido amablemente cambiar el d\u00eda de viaje despu\u00e9s de la cita de nuestro hijo en el hospital, sino que el jefe de tren nos ha trasladado a 1\u00aa clase para que mi hijo pueda sentarse y dormir c\u00f3modamente. <a href=\"https:\/\/t.co\/FhL6bmWomy\">pic.twitter.com\/FhL6bmWomy<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">- Craig Larkin (@clarkin1984) <a href=\"https:\/\/twitter.com\/clarkin1984\/status\/990585717536559105?ref_src=twsrc%5Etfw\">29 de abril de 2018<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&lt;\/p&gt;<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Este pasajero de Virgin Trains East Coast lo experiment\u00f3 en primera persona cuando el gerente del tren le permiti\u00f3 cambiar la fecha de su viaje para adaptarse a la estancia de su hijo en el hospital, e incluso les traslad\u00f3 a primera clase para que el peque\u00f1o paciente pudiera estar m\u00e1s c\u00f3modo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Compartieron este impresionante ejemplo de buen servicio al cliente en Twitter y la publicaci\u00f3n ha recibido desde entonces m\u00e1s de 1.200 millones de me gusta, 94 comentarios y 77 retweets. Las redes sociales son incre\u00edbles y han permitido que mucha gente se entere de c\u00f3mo Virgin Trains trata a sus clientes.<\/p>\n\n\n\n<p class=\"has-text-align-center has-white-color has-text-color has-background wp-block-paragraph\" style=\"background-color:#1e2c48\"><a href=\"https:\/\/app.brand24.com\/user\/register-account\/?custom_form=38\" target=\"_blank\" rel=\"noreferrer noopener\" title=\"https:\/\/app.brand24.com\/user\/register-account\/?custom_form=38\"><strong>Reaccione a las menciones de su empresa en tiempo real<\/strong><\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"how_raos_delivers_good_service_by_helping_their_customers_save_time\">2. Sea un ejemplo de buen servicio al cliente en el comercio minorista dando prioridad al tiempo de sus clientes.<\/h3>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\"Trabajar con sentido de urgencia es, para m\u00ed, una se\u00f1al de respeto por el tiempo del cliente, y un aspecto obligatorio de un buen servicio de atenci\u00f3n. Algunos trabajadores creen que tener sentido de la urgencia es denigrante o una especie de sacrificio personal; eso est\u00e1 muy lejos de la realidad; es un signo de dedicaci\u00f3n, respeto y profesionalidad.\" - Scott Rao, consultor de caf\u00e9 y autor, fundador de Rao's en Amherst, MA.<\/p>\n<\/blockquote>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a98b78e94e0d&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a98b78e94e0d\" class=\"wp-block-image aligncenter size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1140\" height=\"735\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/brand24.com\/blog\/wp-content\/uploads\/2021\/11\/instagram-8-real-life-examples-of-good-customer-service-01-min-1-1140x735.jpg\" alt=\"\" class=\"wp-image-150773\" srcset=\"https:\/\/brand24.com\/blog\/app\/uploads\/2021\/11\/instagram-8-real-life-examples-of-good-customer-service-01-min-1-1140x735.jpg 1140w, https:\/\/brand24.com\/blog\/app\/uploads\/2021\/11\/instagram-8-real-life-examples-of-good-customer-service-01-min-1-300x193.jpg 300w, https:\/\/brand24.com\/blog\/app\/uploads\/2021\/11\/instagram-8-real-life-examples-of-good-customer-service-01-min-1.jpg 1208w\" sizes=\"auto, (max-width: 1140px) 100vw, 1140px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Todos hemos estado en esa situaci\u00f3n: de pie detr\u00e1s de una larga cola en el mostrador mientras los empleados charlan despreocupadamente entre ellos y no parecen tener prisa por atender al siguiente cliente... O de pie en la sala de espera de un restaurante vac\u00edo mientras el personal sigue apoyado contra la pared, continuando su conversaci\u00f3n sobre no se sabe qu\u00e9 mientras usted espera una de las muchas mesas vac\u00edas que puede ver claramente... O incluso por tel\u00e9fono, despu\u00e9s de explicar pacientemente tu situaci\u00f3n a un representante, pero te ponen en espera durante media hora, tiempo durante el cual nadie se ocupa de ti, as\u00ed que no tienes ni idea de si debes seguir esperando...<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Podr\u00eda seguir, pero no lo har\u00e9, porque <em>que<\/em> ser\u00eda una p\u00e9rdida de tiempo (por cierto, tengo <em>nunca<\/em> vuelto a ese restaurante que he mencionado). Por eso no podr\u00eda estar m\u00e1s de acuerdo con la cita anterior.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hay<em> nada<\/em> negativo de mostrar a sus clientes que respeta su tiempo. No hay necesidad de agotarse funcionando a toda velocidad 24\/7, pero mostrar a sus clientes que est\u00e1 trabajando activamente para ayudarles es sin duda una de las mejores maneras en que su empresa puede ser un ejemplo de buen servicio al cliente en el comercio minorista.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"how_kershaw_knives_excels_in_customer_service_with_excellent_aftercare\">3. Ser un ejemplo de buen servicio al cliente en el comercio minorista, sin preocuparse por los peque\u00f1os detalles (es decir, los gastos menores).<\/h3>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\"El mejor cuchillo que he llevado es un Kershaw. El servicio de atenci\u00f3n al cliente es estupendo. Romp\u00ed mi clip de bolsillo y ten\u00eda otro en mi puerta dentro de una semana, de forma gratuita. Orgulloso de llevar una Kershaw\" - cliente Allen A.<\/p>\n<\/blockquote>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a98b78e9589b&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a98b78e9589b\" class=\"wp-block-image aligncenter size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1140\" height=\"740\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/brand24.com\/blog\/wp-content\/uploads\/2021\/11\/instagram-8-real-life-examples-of-good-customer-service-02-min-1140x740.jpg\" alt=\"\" class=\"wp-image-150775\" srcset=\"https:\/\/brand24.com\/blog\/app\/uploads\/2021\/11\/instagram-8-real-life-examples-of-good-customer-service-02-min-1140x740.jpg 1140w, https:\/\/brand24.com\/blog\/app\/uploads\/2021\/11\/instagram-8-real-life-examples-of-good-customer-service-02-min-300x195.jpg 300w, https:\/\/brand24.com\/blog\/app\/uploads\/2021\/11\/instagram-8-real-life-examples-of-good-customer-service-02-min.jpg 1190w\" sizes=\"auto, (max-width: 1140px) 100vw, 1140px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Kershaw Knives es el ejemplo perfecto de una empresa dispuesta a embolsarse gastos menores para poder ofrecer un buen servicio de atenci\u00f3n al cliente y posventa. La imagen de arriba es un testimonio genuino de un cliente que experiment\u00f3 un excelente servicio post-venta de Kershaw Knives despu\u00e9s de que se le rompiera el clip de bolsillo de su navaja. Kershaw le envi\u00f3 inmediatamente un nuevo clip sin ning\u00fan coste adicional, y se asegur\u00f3 de que lo recibiera en el plazo de una semana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u00a1Es un gran servicio!<\/em>&nbsp;Hay muchas marcas que, incluso cuando sus productos est\u00e1n en garant\u00eda, exigen a los clientes que paguen los gastos de env\u00edo si es necesario repararlos o revisarlos. Lo cual no es del todo injusto. Y tambi\u00e9n es exactamente lo que hace que la generosidad de Kershaw destaque a\u00fan m\u00e1s. El hecho de que est\u00e9n dispuestos a embolsarse los costes menores indica a sus clientes que cuando compran un art\u00edculo de esta empresa, obtienen m\u00e1s de lo que pagan. No s\u00f3lo obtienen una navaja nueva y resistente, sino tambi\u00e9n la tranquilidad y la seguridad de que se ocupar\u00e1n de ellos en caso de que ocurra algo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfImporta? Desde luego:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\"A\u00fan no he tenido ning\u00fan problema, pero es bueno saber que cuando se os necesita, est\u00e1is ah\u00ed\" - comentario de un cliente en el post de Kershaw anterior.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/blockquote>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"how_this_hotel_makes_its_customers_think_why_would_you_want_to_go_anywhere_else\">4. Ser un ejemplo de buen servicio al cliente en el comercio minorista prestando atenci\u00f3n a los detalles.<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Porque son las peque\u00f1as cosas las que importan.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al igual que en un restaurante, donde la forma de presentar la comida puede afectar a la satisfacci\u00f3n del cliente, lo mismo ocurre con la forma en que el personal se presenta a los clientes. Y esto se aplica a cualquier tipo de empresa que preste servicios de atenci\u00f3n al cliente, ya sea en el comercio minorista fuera de l\u00ednea, en el comercio minorista en l\u00ednea, en la hosteler\u00eda o en cualquier otro sector.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por ejemplo, el siguiente cliente no paraba de hablar maravillas de todos los peque\u00f1os detalles del servicio que le hac\u00edan decir \"\u00bfpor qu\u00e9 querr\u00edas ir a otro sitio?\" cuando publicaba sobre su estancia en un hotel concreto.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\"1. \u00a1Cambian el felpudo del suelo del ascensor para decir \"Buenos d\u00edas\" o \"Buenas noches\" seg\u00fan la hora del d\u00eda!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">2. Sus ascensores tienen un horario impecable; nunca esperas mucho a que venga uno aunque el hotel est\u00e9 ocupado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">3. Todo el personal lleva una fragancia muy agradable en todo el hotel.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">4. Tanto si llamas al servicio de habitaciones, a recepci\u00f3n, al garaje, etc., siempre te llaman por tu nombre completo<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">5. Se adaptan a cualquier petici\u00f3n que tengas, grande o peque\u00f1a.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfPor qu\u00e9 querr\u00edas ir a otro sitio?\".<\/p>\n<\/blockquote>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large\"><a href=\"https:\/\/www.instagram.com\/p\/Bh7wJReHmiL\/\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1140\" height=\"742\" src=\"https:\/\/brand24.com\/blog\/wp-content\/uploads\/2021\/11\/instagram-8-real-life-examples-of-good-customer-service-03-min-1140x742.jpg\" alt=\"\" class=\"wp-image-150777\" srcset=\"https:\/\/brand24.com\/blog\/app\/uploads\/2021\/11\/instagram-8-real-life-examples-of-good-customer-service-03-min-1140x742.jpg 1140w, https:\/\/brand24.com\/blog\/app\/uploads\/2021\/11\/instagram-8-real-life-examples-of-good-customer-service-03-min-300x195.jpg 300w, https:\/\/brand24.com\/blog\/app\/uploads\/2021\/11\/instagram-8-real-life-examples-of-good-customer-service-03-min.jpg 1198w\" sizes=\"auto, (max-width: 1140px) 100vw, 1140px\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque no te dediques a la hosteler\u00eda, puedes poner en pr\u00e1ctica toques personales como \u00e9ste en cualquier negocio.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Puede que no tenga ascensor, pero puede cambiar los felpudos de la entrada para que digan \"buenos d\u00edas\" o \"buenas noches\", o incluir saludos m\u00e1s personalizados en su marketing por correo electr\u00f3nico.<\/li>\n\n\n\n<li>Puede intentar abrir m\u00e1s cajas registradoras para que sus clientes no tengan que esperar largas colas para pagar sus art\u00edculos (una preocupaci\u00f3n mayor que los ascensores para la mayor\u00eda de los minoristas).<\/li>\n\n\n\n<li>Algunos clientes pueden ser al\u00e9rgicos a ciertas fragancias, pero usted podr\u00eda introducir pol\u00edticas que hagan a su personal m\u00e1s presentable en general.<\/li>\n\n\n\n<li>Si conoce los nombres de sus clientes, \u00a1pruebe a utilizarlos! Est\u00e1 demostrado que a la gente le gusta o\u00edr sus nombres.<\/li>\n\n\n\n<li>Y la flexibilidad es clave. Si puedes ayudar a tus clientes sin que ello afecte negativamente a tu trabajo, \u00bfpor qu\u00e9 no? Da cambio si tienes suficientes billetes peque\u00f1os en ese momento. Permite a tus clientes usar el ba\u00f1o si lo necesitan. Ofr\u00e9celes una cuchara si ves que han comprado un producto listo para comer (como helado o sopa). Nada de esto le llevar\u00e1 m\u00e1s de un par de minutos (o segundos), y sus clientes apreciar\u00e1n su consideraci\u00f3n, e incluso empezar\u00e1n a pensar... <em>\u00bfpor qu\u00e9 ir a otro sitio?&nbsp;<\/em><\/li>\n<\/ol>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"how_this_candy_store_provides_great_service_by_making_a_positive_impact_on_its_customers_lives\">5. Ofrecer un buen servicio de atenci\u00f3n al cliente en el comercio minorista, incluso cuando el cliente se equivoca<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><em>El cliente siempre tiene raz\u00f3n.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este es un mantra popular de atenci\u00f3n al cliente por el que se rigen la mayor\u00eda de las empresas. Pero, \u00bfqu\u00e9 ocurre cuando el cliente se equivoca?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si tiene o gestiona una tienda, es probable que haya tenido que hacer frente a casos de hurto, en <em>menos<\/em> una vez. Muchos empresarios dejan clara su postura frente al hurto exhibiendo carteles como los que se muestran a continuaci\u00f3n en el interior de sus establecimientos:<\/p>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a98b78e966e2&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a98b78e966e2\" class=\"wp-block-image aligncenter wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"376\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/brand24.com\/blog\/wp-content\/uploads\/2017\/08\/8-real-life-examples-of-good-customer-service-from-companies-large-small-min.jpg\" alt=\"Los ladrones ser\u00e1n perseguidos con todo el peso de la ley.\" class=\"wp-image-112758\" srcset=\"https:\/\/brand24.com\/blog\/app\/uploads\/2017\/08\/8-real-life-examples-of-good-customer-service-from-companies-large-small-min.jpg 500w, https:\/\/brand24.com\/blog\/app\/uploads\/2017\/08\/8-real-life-examples-of-good-customer-service-from-companies-large-small-min-300x226.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a98b78e96fc1&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a98b78e96fc1\" class=\"wp-block-image aligncenter wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"647\" height=\"320\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/brand24.com\/blog\/wp-content\/uploads\/2017\/08\/8-real-life-examples-of-good-customer-service-from-companies-large-small-2-min.jpg\" alt=\"robar en tiendas es un delito, pulseras gratis con cada robo\" class=\"wp-image-112761\" srcset=\"https:\/\/brand24.com\/blog\/app\/uploads\/2017\/08\/8-real-life-examples-of-good-customer-service-from-companies-large-small-2-min.jpg 647w, https:\/\/brand24.com\/blog\/app\/uploads\/2017\/08\/8-real-life-examples-of-good-customer-service-from-companies-large-small-2-min-300x148.jpg 300w\" sizes=\"auto, (max-width: 647px) 100vw, 647px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El mensaje es claro: <em>si roba en una tienda, prep\u00e1rese para afrontar las consecuencias legales de sus actos.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Suena justo, pero... no siempre es tan sencillo. Incluso en las situaciones m\u00e1s dif\u00edciles, puede haber una forma mejor. Si tratas a tus clientes como personas de verdad y simplemente<em> escuche<\/em> y reacciona de forma compasiva, puede que encuentres una soluci\u00f3n mejor que beneficie a todas las partes (e incluso que tenga un impacto positivo en la vida de alguien), como hizo un inteligente gerente de tienda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Escucha la historia. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una madre descubri\u00f3 que su hijo hab\u00eda robado una piruleta en la tienda. Llev\u00f3 a su hijo a la tienda e hizo que se disculpara ante el dependiente. Cuando se avis\u00f3 al director de la tienda, en lugar de seguir las normas y llamar a la polic\u00eda, le dijo al ni\u00f1o que pod\u00eda quedarse con la piruleta si estaba dispuesto a trabajar por ella. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hicieron un trato: el ni\u00f1o ten\u00eda que recoger 10 piezas de basura en el aparcamiento y se habr\u00eda ganado la piruleta. Sali\u00f3 y recogi\u00f3 la basura, incluso algo m\u00e1s de 10 piezas. Despu\u00e9s, el castigo le hizo sentirse mejor, porque pudo decir a los dem\u00e1s que se hab\u00eda ganado el caramelo, en lugar de robarlo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Historias como esta tienen una forma de difundirse en Internet, aunque hayan ocurrido fuera de la red. Puede que solo fuera un comentario en un post mucho m\u00e1s grande, pero ya ha tenido 1,2 mil reacciones en tres semanas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y tambi\u00e9n ha recibido numerosos comentarios positivos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"#index\">Volver al \u00edndice<\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"how_side_project_brewery_wins_their_customers_affections_by_implementing_customer_feedback\">6. Ser un ejemplo de buen servicio al cliente en el comercio minorista poniendo en pr\u00e1ctica las opiniones de los clientes.<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Es muy sencillo. Sus clientes quieren que se les valore. Esto empieza por escuchar sus comentarios y ponerlos en pr\u00e1ctica siempre que sea posible. Un punto clave de un buen servicio al cliente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El mero acto de escuchar&nbsp;<em>(y demostrar que escucha poniendo en pr\u00e1ctica las sugerencias de los clientes)<\/em>&nbsp;puede aumentar la fidelidad de sus clientes, hacer que su empresa reciba elogios y cr\u00edticas positivas en las redes sociales, y aumentar sus ingresos. <a href=\"https:\/\/brand24.com\/blog\/es\/notoriedad-de-marca\/\" target=\"_blank\" rel=\"noopener\" title=\"\">notoriedad de marca<\/a> - todos ellos contribuyen directa o indirectamente a sus ventas e ingresos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuanta m\u00e1s gente conozca su marca y hable positivamente de ella, m\u00e1s personas se animar\u00e1n a probarla (y quedar\u00e1n impresionadas por su incre\u00edble servicio de atenci\u00f3n al cliente).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Podemos ver la importancia de un buen servicio de atenci\u00f3n al cliente en la secci\u00f3n de comentarios del siguiente post. Un experto en cerveza cont\u00f3 su excelente experiencia con una empresa de cerveza artesana y lo raro que es recibir un servicio de atenci\u00f3n al cliente de tan alta calidad. Los comentarios se hacen eco de esta opini\u00f3n.<\/p>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a98b78e97b13&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a98b78e97b13\" class=\"wp-block-image aligncenter size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1042\" height=\"773\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/brand24.com\/blog\/wp-content\/uploads\/2021\/11\/instagram-8-real-life-examples-of-good-customer-service-04-min.jpg\" alt=\"\" class=\"wp-image-150783\" srcset=\"https:\/\/brand24.com\/blog\/app\/uploads\/2021\/11\/instagram-8-real-life-examples-of-good-customer-service-04-min.jpg 1042w, https:\/\/brand24.com\/blog\/app\/uploads\/2021\/11\/instagram-8-real-life-examples-of-good-customer-service-04-min-300x223.jpg 300w\" sizes=\"auto, (max-width: 1042px) 100vw, 1042px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<p class=\"has-text-align-center has-white-color has-text-color has-background wp-block-paragraph\" style=\"background-color:#1e2c48\"><strong><a href=\"https:\/\/app.brand24.com\/user\/register-account\/?custom_form=5\" target=\"_blank\" rel=\"noreferrer noopener\" title=\"https:\/\/app.brand24.com\/user\/register-account\/?custom_form=5\">Escuche las opiniones de sus clientes y descubra nuevas perspectivas con Brand24<\/a><\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"how_real_canadian_superstore_provides_awesome_service_by_interacting_with_their_customers\">7. Sea un ejemplo de buen servicio al cliente en el comercio minorista interactuando con sus clientes y manteni\u00e9ndolos informados.<\/h3>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Seg\u00fan un estudio reciente de BigCommerce, 96% de los estadounidenses compran en l\u00ednea.<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Hay muchas razones para comprar a trav\u00e9s de Internet: ahorrar tiempo, evitar las aglomeraciones, comparar precios... Sea cual sea el motivo, casi todos los consumidores estadounidenses han comprado en l\u00ednea alguna vez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed trata a sus clientes el minorista de alimentaci\u00f3n Real Canadian Superstore.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una de las clientas describi\u00f3 en su Instagram su experiencia con el servicio online click &amp; collect.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> Como describe en su post, todo lo que tuvo que hacer fue hacer su pedido en l\u00ednea, seleccionar una franja horaria para recogerlo y, cuando lleg\u00f3, un representante del servicio de atenci\u00f3n al cliente le llev\u00f3 el pedido directamente a su coche. Le impresion\u00f3 especialmente la forma en que el minorista manej\u00f3 la situaci\u00f3n cuando descubrieron que algunos art\u00edculos que hab\u00eda pedido estaban agotados. Un amable representante del servicio de atenci\u00f3n al cliente la llam\u00f3 para informarle de que los art\u00edculos estaban agotados y le sugiri\u00f3 algunas alternativas posibles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No soy ajeno a la compra de comestibles en l\u00ednea (ahorra MUCHO tiempo), pero nunca he recibido ninguna <a href=\"https:\/\/www.cloudtalk.io\/virtual-call-center-software\" target=\"_blank\" rel=\"noreferrer noopener\">llamadas telef\u00f3nicas de representantes del servicio de atenci\u00f3n al cliente<\/a> sobre art\u00edculos que estaban agotados (ojo, estaban <em>no<\/em> agotado seg\u00fan su p\u00e1gina web <a href=\"https:\/\/katanamrp.com\/inventory-management-guide\/\" target=\"_blank\" rel=\"noopener\" title=\"\">inventario<\/a>). Los minoristas casi siempre los sustituyen autom\u00e1ticamente por otras marcas o art\u00edculos similares.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>No siempre estoy contento con esto<\/strong> ya que prefiero evitar algunas marcas (de hecho, he dejado de hacer pedidos a determinados minoristas en l\u00ednea por ese motivo concreto). Hubiera agradecido una llamada telef\u00f3nica, un mensaje de texto o un correo electr\u00f3nico preguntando si estar\u00eda bien sustituir los art\u00edculos agotados por otras marcas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero \u00e9sa es una de las principales diferencias entre un servicio de atenci\u00f3n al cliente normal y corriente en el comercio minorista y un servicio de atenci\u00f3n al cliente de verdad. <a href=\"https:\/\/totalityservices.co.uk\/\" target=\"_blank\" rel=\"noreferrer noopener\">buen servicio al cliente<\/a> de los minoristas: \u00a1escuchen a sus clientes y averig\u00fcen lo que quieren!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tenlo en cuenta:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">67% de los consumidores citan las malas experiencias en el servicio de atenci\u00f3n al cliente como motivo de abandono<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Un paso clave para ofrecer un buen servicio de atenci\u00f3n al cliente en el comercio minorista empieza por recordar que los clientes son humanos y conectar con ellos... de forma <em>humano<\/em> manera.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Esto significa que <em>escuche<\/em> a ellos.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>S\u00f3lo entonces podr\u00e1 comprender realmente lo que quieren sus clientes y empezar a entablar relaciones con ellos.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Esto funciona en ambos sentidos.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cosas que pasan. Los desastres ocurren. Cuando cambian las tornas, \u00bfc\u00f3mo quiere que reaccionen sus clientes?<\/p>\n\n\n\n<p class=\"has-text-align-center has-white-color has-text-color has-background wp-block-paragraph\" style=\"background-color:#1e2c48\"><strong><a href=\"https:\/\/app.brand24.com\/user\/register-account\/?custom_form=10\" target=\"_blank\" rel=\"noreferrer noopener\" title=\"https:\/\/app.brand24.com\/user\/register-account\/?custom_form=10\">Utilice una herramienta de seguimiento de medios para interactuar con sus clientes en l\u00ednea<\/a><\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"how_deep_sea_headquarters_avoided_disaster_for_their_business_by_providing_good_customer_service_on_a_regular_basis\">8. S\u00e9 un ejemplo de buen servicio al cliente en el comercio minorista... porque no puedes permitirte&nbsp;<em>no<\/em> a<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Deep Sea Headquarters, una agencia de excursiones en barco de Port Aransas (Texas), fue duramente golpeada por el hurac\u00e1n Harvey. Este fue el caso de muchos particulares y empresas, que se quedaron pr\u00e1cticamente sin nada tras la cat\u00e1strofe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Casi de inmediato, Deep Sea Headquarters empez\u00f3 a recibir solicitudes de reembolso por excursiones en barco interrumpidas a causa del hurac\u00e1n Harvey. Se vieron incapaces de emitir los reembolsos con su velocidad habitual, ya que sus empleados ahora estaban luchando ellos mismos para hacer frente a la p\u00e9rdida de la casa y el hogar en las secuelas del desastre. Por no hablar de la escasez de agua, electricidad y telefon\u00eda m\u00f3vil en la zona.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una breve publicaci\u00f3n en Facebook explicando la situaci\u00f3n y pidiendo a sus clientes un poco de comprensi\u00f3n y compasi\u00f3n humana puso r\u00e1pidamente de manifiesto las s\u00f3lidas relaciones que ya hab\u00edan establecido con sus clientes gracias a un excelente servicio de atenci\u00f3n al cliente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La gente empez\u00f3 r\u00e1pidamente a compartir sus experiencias positivas de navegaci\u00f3n con la tripulaci\u00f3n en la secci\u00f3n de comentarios y asegur\u00f3 a la empresa que recibir los reembolsos a tiempo no era ni mucho menos una prioridad durante este tiempo.<\/p>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a98b78e9899f&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a98b78e9899f\" class=\"wp-block-image aligncenter size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"758\" height=\"366\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/brand24.com\/blog\/wp-content\/uploads\/2021\/11\/facebook-8-real-life-examples-of-good-customer-service-01-min.jpg\" alt=\"\" class=\"wp-image-150788\" srcset=\"https:\/\/brand24.com\/blog\/app\/uploads\/2021\/11\/facebook-8-real-life-examples-of-good-customer-service-01-min.jpg 758w, https:\/\/brand24.com\/blog\/app\/uploads\/2021\/11\/facebook-8-real-life-examples-of-good-customer-service-01-min-300x145.jpg 300w\" sizes=\"auto, (max-width: 758px) 100vw, 758px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando llegue el momento (y llegar\u00e1) y su empresa necesite la comprensi\u00f3n y la compasi\u00f3n humana de sus clientes, espere: sus reacciones y su apoyo reflejar\u00e1n la solidez de sus relaciones con los clientes y lo bien que ha estado prestando el servicio de atenci\u00f3n al cliente en todo momento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con un poco de suerte, se encontrar\u00e1 en el mismo barco que la sede de Deep Sea.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Proporcionar un buen servicio al cliente en el comercio minorista con seguimiento de las redes sociales<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El primer paso para ofrecer un buen servicio de atenci\u00f3n al cliente en el comercio minorista empieza por <em>escuchar a sus clientes<\/em>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sus clientes no siempre se dirigir\u00e1n a usted directamente, por lo que puede que tenga que indagar un poco para descubrir <a href=\"https:\/\/usersnap.com\/blog\/customer-feedback\/\" target=\"_blank\" rel=\"noreferrer noopener\" title=\"comentarios de los clientes\">comentarios de los clientes<\/a> o utiliza una herramienta de seguimiento de redes sociales para que investigue por ti.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tenga en cuenta que su empresa no siempre ser\u00e1 etiquetada cuando sus clientes la mencionen. Aqu\u00ed es donde <a href=\"https:\/\/brand24.com\/blog\/es\/herramientas-de-escucha-social\/\" target=\"_blank\" rel=\"noopener\">herramientas de social listening<\/a> puede echarte una mano. Configura proyectos de seguimiento de medios para rastrear las menciones de tu marca, producto, sector, etc... y recibe notificaciones instant\u00e1neas cada vez que tus clientes te mencionen en l\u00ednea, te hayan etiquetado o no.<\/p>\n\n\n\n<p class=\"has-text-align-center has-white-color has-text-color has-background wp-block-paragraph\" style=\"background-color:#1e2c48\"><strong><a href=\"https:\/\/app.brand24.com\/user\/register-account\/?custom_form=5\" target=\"_blank\" rel=\"noreferrer noopener\" title=\"https:\/\/app.brand24.com\/user\/register-account\/?custom_form=5\">Empieza a monitorizar las redes sociales gratis<\/a><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una herramienta de seguimiento de medios potente y f\u00e1cil de usar como Brand24 simplifica enormemente el seguimiento de los comentarios de los clientes:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Paso 1: Configure sus proyectos de escucha social<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Comience por seleccionar las palabras clave que desea rastrear.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter\"><a href=\"https:\/\/app.brand24.com\/user\/register-account\/\"><img loading=\"lazy\" decoding=\"async\" width=\"579\" height=\"448\" src=\"https:\/\/brand24.com\/blog\/wp-content\/uploads\/2017\/08\/t-mobile.png\" alt=\"Paso 1: configurar los proyectos de escucha social\" class=\"wp-image-108154\" srcset=\"https:\/\/brand24.com\/blog\/app\/uploads\/2017\/08\/t-mobile.png 579w, https:\/\/brand24.com\/blog\/app\/uploads\/2017\/08\/t-mobile-300x232.png 300w\" sizes=\"auto, (max-width: 579px) 100vw, 579px\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Crear un proyecto lleva menos de 3 minutos:<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"\u00bfC\u00f3mo crear un proyecto? Optimice los resultados de su seguimiento en Internet | Tutoriales Brand24\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/H-7_UXOQKxg?list=PLsrLHBOEUlPyyUG1BMNIHXqAvHTNhj37f\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Si no est\u00e1 seguro de qu\u00e9 palabras clave debe rastrear, <a href=\"https:\/\/brand24.com\/blog\/es\/8-palabras-clave-que-no-son-el-nombre-de-su-marca-y-que-debe-seguir-a-traves-de-la-monitorizacion-de-redes-sociales\/\" target=\"_blank\" rel=\"noreferrer noopener\">este recurso le dar\u00e1 algunas ideas<\/a>.<\/p>\n\n\n\n<p class=\"has-text-align-center has-white-color has-text-color has-background wp-block-paragraph\" style=\"background-color:#1e2c48\"><strong><a href=\"https:\/\/app.brand24.com\/user\/register-account\/?custom_form=5\" target=\"_blank\" rel=\"noreferrer noopener\" title=\"https:\/\/app.brand24.com\/user\/register-account\/?custom_form=5\">Comience su prueba gratuita (no necesita tarjeta de cr\u00e9dito).<\/a><\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Paso 2: Vigila tus proyectos de escucha social<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Una vez que hayas puesto en marcha tus proyectos de escucha social, no pierdas de vista los datos que recopiles. <a href=\"https:\/\/brand24.com\/blog\/es\/\" target=\"_blank\" rel=\"noreferrer noopener\">Brand24<\/a> tiene una \u00fatil pesta\u00f1a de resumen en el panel de control que muestra aspectos importantes de tus datos de un vistazo.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter\"><a href=\"https:\/\/app.brand24.com\/user\/register-account\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1195\" height=\"632\" src=\"https:\/\/brand24.com\/blog\/wp-content\/uploads\/2017\/08\/Summary-Tab-1.png\" alt=\"Paso 2: vigila tus proyectos de escucha social\" class=\"wp-image-108155\" srcset=\"https:\/\/brand24.com\/blog\/app\/uploads\/2017\/08\/Summary-Tab-1.png 1195w, https:\/\/brand24.com\/blog\/app\/uploads\/2017\/08\/Summary-Tab-1-1140x603.png 1140w, https:\/\/brand24.com\/blog\/app\/uploads\/2017\/08\/Summary-Tab-1-300x159.png 300w, https:\/\/brand24.com\/blog\/app\/uploads\/2017\/08\/Summary-Tab-1-750x397.png 750w\" sizes=\"auto, (max-width: 1195px) 100vw, 1195px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image aligncenter\"><a href=\"https:\/\/app.brand24.com\/user\/register-account\/\"><img loading=\"lazy\" decoding=\"async\" width=\"1186\" height=\"575\" src=\"https:\/\/brand24.com\/blog\/wp-content\/uploads\/2017\/08\/Summary-Tab-2.png\" alt=\"Paso 2: vigila tus proyectos de escucha social\" class=\"wp-image-108156\" srcset=\"https:\/\/brand24.com\/blog\/app\/uploads\/2017\/08\/Summary-Tab-2.png 1186w, https:\/\/brand24.com\/blog\/app\/uploads\/2017\/08\/Summary-Tab-2-1140x553.png 1140w, https:\/\/brand24.com\/blog\/app\/uploads\/2017\/08\/Summary-Tab-2-300x145.png 300w, https:\/\/brand24.com\/blog\/app\/uploads\/2017\/08\/Summary-Tab-2-750x364.png 750w\" sizes=\"auto, (max-width: 1186px) 100vw, 1186px\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Personalice las notificaciones para que le avisen cuando se produzca un aumento repentino de los resultados de su empresa o de determinados tipos de resultados (como resultados negativos o positivos, o para #hashtags espec\u00edficos, etc.).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Brand24 tambi\u00e9n incluye una variedad de filtros que puedes utilizar para separar las menciones seg\u00fan su relevancia. Y los informes de an\u00e1lisis en PDF te ayudan a comprender los datos. Estos son algunos consejos que le ayudar\u00e1n a sacar el m\u00e1ximo partido de su <a href=\"https:\/\/brand24.com\/blog\/es\/seguimiento-de-las-redes-sociales\/\" target=\"_blank\" rel=\"noopener\">seguimiento de las redes sociales<\/a> herramienta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Todas estas funciones est\u00e1n disponibles en <a href=\"https:\/\/app.brand24.com\/user\/register-account\/\" target=\"_blank\" rel=\"noreferrer noopener\">prueba gratuita<\/a>. Ponga en marcha ahora un proyecto de escucha social y averig\u00fce qu\u00e9 dicen de usted sus clientes. \u00bfSu empresa <em>realmente<\/em> \u00bfha prestado un buen servicio al cliente en el comercio minorista?<span style=\"border-radius: 2px;text-indent: 20px;width: auto;padding: 0px 4px 0px 0px;text-align: center;font: bold 11px\/20px 'Helvetica Neue',Helvetica,sans-serif;color: #ffffff;background: #bd081c no-repeat scroll 3px 50% \/ 14px 14px;position: absolute;z-index: 8675309;cursor: pointer;top: 5571px;left: 20px\">GuardarAhorrar<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>Nuestros 8 ejemplos favoritos de buen servicio de atenci\u00f3n al cliente en el sector minorista: descubra c\u00f3mo estas empresas aumentan la fidelidad de sus clientes y reducen la rotaci\u00f3n con un servicio excelente.<\/p>","protected":false},"author":20,"featured_media":108186,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[4147],"tags":[58,2084,2085,2082,2081,2080,2083,34,2074,682,764],"class_list":["post-108136","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pr-and-crisis","tag-customer-service","tag-examples-of-customer-service","tag-examples-of-customer-service-in-retail","tag-good-example-of-customer-service","tag-good-examples-of-customer-service","tag-good-examples-of-customer-service-in-retail","tag-service","tag-social-listening","tag-social-listening-customer-service","tag-social-listening-tool","tag-social-listening-tools"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"These 8 examples of good customer service in retail illustrate exactly how companies can increase customer loyalty and decrease churn with great service!\" \/>\n\t<meta name=\"robots\" content=\"max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n\t<meta name=\"author\" content=\"Chia\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/brand24.com\/blog\/es\/3-real-life-examples-of-good-customer-service-in-retail-from-companies-large-and-small\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Brand24 Blog\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"8 Examples of Good Customer Service in Retail | Brand24\" \/>\n\t\t<meta property=\"og:description\" content=\"These 8 examples of good customer service in retail illustrate exactly how companies can increase customer loyalty and decrease churn with great service!\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/brand24.com\/blog\/es\/3-real-life-examples-of-good-customer-service-in-retail-from-companies-large-and-small\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/brand24.com\/blog\/app\/uploads\/2017\/08\/header.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/brand24.com\/blog\/app\/uploads\/2017\/08\/header.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1300\" \/>\n\t\t<meta property=\"og:image:height\" content=\"975\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2021-08-30T10:46:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-03-20T13:42:30+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"8 Examples of Good Customer Service in Retail | Brand24\" \/>\n\t\t<meta name=\"twitter:description\" content=\"These 8 examples of good customer service in retail illustrate exactly how companies can increase customer loyalty and decrease churn with great service!\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/brand24.com\/blog\/app\/uploads\/2017\/08\/header.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/brand24.com\\\/blog\\\/es\\\/3-real-life-examples-of-good-customer-service-in-retail-from-companies-large-and-small\\\/#article\",\"name\":\"8 Examples of Good Customer Service in Retail | Brand24\",\"headline\":\"8 real life examples of good customer service in retail, from companies large and small\",\"author\":{\"@id\":\"https:\\\/\\\/brand24.com\\\/blog\\\/es\\\/author\\\/chia-lee\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/brand24.com\\\/blog\\\/es\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/brand24.com\\\/blog\\\/app\\\/uploads\\\/2017\\\/08\\\/header.jpg\",\"width\":1300,\"height\":975,\"caption\":\"8 real life examples of good customer service in retail: from companies large & small\"},\"datePublished\":\"2021-08-30T12:46:00+02:00\",\"dateModified\":\"2026-04-13T14:24:29+02:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/brand24.com\\\/blog\\\/es\\\/3-real-life-examples-of-good-customer-service-in-retail-from-companies-large-and-small\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/brand24.com\\\/blog\\\/es\\\/3-real-life-examples-of-good-customer-service-in-retail-from-companies-large-and-small\\\/#webpage\"},\"articleSection\":\"PR &amp; Crisis Management, customer service, examples of customer service, examples of customer service in retail, good example of customer service, good examples of customer service, good examples of customer service in retail, service, social listening, social listening customer service, social listening tool, social listening tools\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/brand24.com\\\/blog\\\/es\\\/3-real-life-examples-of-good-customer-service-in-retail-from-companies-large-and-small\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/brand24.com\\\/blog\\\/es#listItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/brand24.com\\\/blog\\\/es\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/brand24.com\\\/blog\\\/es\\\/category\\\/pr-and-crisis\\\/#listItem\",\"name\":\"PR &amp; Crisis Management\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/brand24.com\\\/blog\\\/es\\\/category\\\/pr-and-crisis\\\/#listItem\",\"position\":2,\"name\":\"PR &amp; Crisis Management\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/brand24.com\\\/blog\\\/es#listItem\",\"name\":\"Blog\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/brand24.com\\\/blog\\\/es\\\/#organization\",\"name\":\"Brand24\",\"description\":\"Insights, analyses & case studies\",\"url\":\"https:\\\/\\\/brand24.com\\\/blog\\\/es\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/brand24.com\\\/blog\\\/es\\\/author\\\/chia-lee\\\/#author\",\"url\":\"https:\\\/\\\/brand24.com\\\/blog\\\/es\\\/author\\\/chia-lee\\\/\",\"name\":\"Chia\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/chia-luen-lee-b72b7b132\\\/details\\\/languages\\\/\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/brand24.com\\\/blog\\\/es\\\/3-real-life-examples-of-good-customer-service-in-retail-from-companies-large-and-small\\\/#webpage\",\"url\":\"https:\\\/\\\/brand24.com\\\/blog\\\/es\\\/3-real-life-examples-of-good-customer-service-in-retail-from-companies-large-and-small\\\/\",\"name\":\"8 Examples of Good Customer Service in Retail | Brand24\",\"description\":\"These 8 examples of good customer service in retail illustrate exactly how companies can increase customer loyalty and decrease churn with great service!\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/brand24.com\\\/blog\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/brand24.com\\\/blog\\\/es\\\/3-real-life-examples-of-good-customer-service-in-retail-from-companies-large-and-small\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/brand24.com\\\/blog\\\/es\\\/author\\\/chia-lee\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/brand24.com\\\/blog\\\/es\\\/author\\\/chia-lee\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/brand24.com\\\/blog\\\/app\\\/uploads\\\/2017\\\/08\\\/header.jpg\",\"@id\":\"https:\\\/\\\/brand24.com\\\/blog\\\/es\\\/3-real-life-examples-of-good-customer-service-in-retail-from-companies-large-and-small\\\/#mainImage\",\"width\":1300,\"height\":975,\"caption\":\"8 real life examples of good customer service in retail: from companies large & small\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/brand24.com\\\/blog\\\/es\\\/3-real-life-examples-of-good-customer-service-in-retail-from-companies-large-and-small\\\/#mainImage\"},\"datePublished\":\"2021-08-30T12:46:00+02:00\",\"dateModified\":\"2026-04-13T14:24:29+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/brand24.com\\\/blog\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/brand24.com\\\/blog\\\/es\\\/\",\"name\":\"Brand24\",\"description\":\"Insights, analyses & case studies\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/brand24.com\\\/blog\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"8 ejemplos de buen servicio de atenci\u00f3n al cliente en el sector minorista | Brand24","description":"Estos 8 ejemplos de buen servicio de atenci\u00f3n al cliente en el sector minorista ilustran exactamente c\u00f3mo las empresas pueden aumentar la fidelidad de sus clientes y reducir la rotaci\u00f3n con un servicio excelente.","canonical_url":"https:\/\/brand24.com\/blog\/es\/3-real-life-examples-of-good-customer-service-in-retail-from-companies-large-and-small\/","robots":"max-snippet:-1, max-image-preview:large, max-video-preview:-1","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/brand24.com\/blog\/es\/3-real-life-examples-of-good-customer-service-in-retail-from-companies-large-and-small\/#article","name":"8 Examples of Good Customer Service in Retail | Brand24","headline":"8 real life examples of good customer service in retail, from companies large and small","author":{"@id":"https:\/\/brand24.com\/blog\/es\/author\/chia-lee\/#author"},"publisher":{"@id":"https:\/\/brand24.com\/blog\/es\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/brand24.com\/blog\/app\/uploads\/2017\/08\/header.jpg","width":1300,"height":975,"caption":"8 real life examples of good customer service in retail: from companies large & small"},"datePublished":"2021-08-30T12:46:00+02:00","dateModified":"2026-04-13T14:24:29+02:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/brand24.com\/blog\/es\/3-real-life-examples-of-good-customer-service-in-retail-from-companies-large-and-small\/#webpage"},"isPartOf":{"@id":"https:\/\/brand24.com\/blog\/es\/3-real-life-examples-of-good-customer-service-in-retail-from-companies-large-and-small\/#webpage"},"articleSection":"PR &amp; Crisis Management, customer service, examples of customer service, examples of customer service in retail, good example of customer service, good examples of customer service, good examples of customer service in retail, service, social listening, social listening customer service, social listening tool, social listening tools"},{"@type":"BreadcrumbList","@id":"https:\/\/brand24.com\/blog\/es\/3-real-life-examples-of-good-customer-service-in-retail-from-companies-large-and-small\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/brand24.com\/blog\/es#listItem","position":1,"name":"Blog","item":"https:\/\/brand24.com\/blog\/es","nextItem":{"@type":"ListItem","@id":"https:\/\/brand24.com\/blog\/es\/category\/pr-and-crisis\/#listItem","name":"PR &amp; Crisis Management"}},{"@type":"ListItem","@id":"https:\/\/brand24.com\/blog\/es\/category\/pr-and-crisis\/#listItem","position":2,"name":"PR &amp; Crisis Management","previousItem":{"@type":"ListItem","@id":"https:\/\/brand24.com\/blog\/es#listItem","name":"Blog"}}]},{"@type":"Organization","@id":"https:\/\/brand24.com\/blog\/es\/#organization","name":"Brand24","description":"Insights, analyses & case studies","url":"https:\/\/brand24.com\/blog\/es\/"},{"@type":"Person","@id":"https:\/\/brand24.com\/blog\/es\/author\/chia-lee\/#author","url":"https:\/\/brand24.com\/blog\/es\/author\/chia-lee\/","name":"Chia","sameAs":["https:\/\/www.linkedin.com\/in\/chia-luen-lee-b72b7b132\/details\/languages\/"]},{"@type":"WebPage","@id":"https:\/\/brand24.com\/blog\/es\/3-real-life-examples-of-good-customer-service-in-retail-from-companies-large-and-small\/#webpage","url":"https:\/\/brand24.com\/blog\/es\/3-real-life-examples-of-good-customer-service-in-retail-from-companies-large-and-small\/","name":"8 Examples of Good Customer Service in Retail | Brand24","description":"These 8 examples of good customer service in retail illustrate exactly how companies can increase customer loyalty and decrease churn with great service!","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/brand24.com\/blog\/es\/#website"},"breadcrumb":{"@id":"https:\/\/brand24.com\/blog\/es\/3-real-life-examples-of-good-customer-service-in-retail-from-companies-large-and-small\/#breadcrumblist"},"author":{"@id":"https:\/\/brand24.com\/blog\/es\/author\/chia-lee\/#author"},"creator":{"@id":"https:\/\/brand24.com\/blog\/es\/author\/chia-lee\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/brand24.com\/blog\/app\/uploads\/2017\/08\/header.jpg","@id":"https:\/\/brand24.com\/blog\/es\/3-real-life-examples-of-good-customer-service-in-retail-from-companies-large-and-small\/#mainImage","width":1300,"height":975,"caption":"8 real life examples of good customer service in retail: from companies large & small"},"primaryImageOfPage":{"@id":"https:\/\/brand24.com\/blog\/es\/3-real-life-examples-of-good-customer-service-in-retail-from-companies-large-and-small\/#mainImage"},"datePublished":"2021-08-30T12:46:00+02:00","dateModified":"2026-04-13T14:24:29+02:00"},{"@type":"WebSite","@id":"https:\/\/brand24.com\/blog\/es\/#website","url":"https:\/\/brand24.com\/blog\/es\/","name":"Brand24","description":"Insights, analyses & case studies","inLanguage":"es-ES","publisher":{"@id":"https:\/\/brand24.com\/blog\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Brand24 Blog","og:type":"article","og:title":"8 Examples of Good Customer Service in Retail | Brand24","og:description":"These 8 examples of good customer service in retail illustrate exactly how companies can increase customer loyalty and decrease churn with great service!","og:url":"https:\/\/brand24.com\/blog\/es\/3-real-life-examples-of-good-customer-service-in-retail-from-companies-large-and-small\/","og:image":"https:\/\/brand24.com\/blog\/app\/uploads\/2017\/08\/header.jpg","og:image:secure_url":"https:\/\/brand24.com\/blog\/app\/uploads\/2017\/08\/header.jpg","og:image:width":1300,"og:image:height":975,"article:published_time":"2021-08-30T10:46:00+00:00","article:modified_time":"2024-03-20T13:42:30+00:00","twitter:card":"summary_large_image","twitter:title":"8 Examples of Good Customer Service in Retail | Brand24","twitter:description":"These 8 examples of good customer service in retail illustrate exactly how companies can increase customer loyalty and decrease churn with great service!","twitter:image":"https:\/\/brand24.com\/blog\/app\/uploads\/2017\/08\/header.jpg"},"aioseo_meta_data":{"post_id":"108136","title":"8 ejemplos de buen servicio al cliente en el sector minorista | #site_title","description":"Estos 8 ejemplos de buen servicio de atenci\u00f3n al cliente en el sector minorista ilustran exactamente c\u00f3mo las empresas pueden aumentar la fidelidad de sus clientes y reducir la rotaci\u00f3n con un servicio excelente.","keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"article","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"summary_large_image","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":{"id":"aioseo-article-634e572b0d3b3","slug":"article","graphName":"Article","label":"Article","properties":{"type":"BlogPosting","name":"#post_title","headline":"#post_title","description":"#post_excerpt","image":"","keywords":"","author":{"name":"#author_name","url":"#author_url"},"dates":{"include":true,"datePublished":"","dateModified":""}}},"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"},\"blockGraphs\":[]}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2021-04-08 15:13:37","updated":"2026-04-13 12:34:49","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/brand24.com\/blog\/es\" title=\"Blog\">Blog<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">\/<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/brand24.com\/blog\/es\/category\/pr-and-crisis\/\" title=\"PR &amp; Crisis Management\">PR &amp; Crisis Management<\/a>\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Blog","link":"https:\/\/brand24.com\/blog\/es"},{"label":"PR &amp; Crisis Management","link":"https:\/\/brand24.com\/blog\/es\/category\/pr-and-crisis\/"}],"cf_author_first_name":"Chia","cf_author_last_name":"Lee","_links":{"self":[{"href":"https:\/\/brand24.com\/blog\/es\/wp-json\/wp\/v2\/posts\/108136","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/brand24.com\/blog\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/brand24.com\/blog\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/brand24.com\/blog\/es\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/brand24.com\/blog\/es\/wp-json\/wp\/v2\/comments?post=108136"}],"version-history":[{"count":81,"href":"https:\/\/brand24.com\/blog\/es\/wp-json\/wp\/v2\/posts\/108136\/revisions"}],"predecessor-version":[{"id":183236,"href":"https:\/\/brand24.com\/blog\/es\/wp-json\/wp\/v2\/posts\/108136\/revisions\/183236"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/brand24.com\/blog\/es\/wp-json\/wp\/v2\/media\/108186"}],"wp:attachment":[{"href":"https:\/\/brand24.com\/blog\/es\/wp-json\/wp\/v2\/media?parent=108136"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/brand24.com\/blog\/es\/wp-json\/wp\/v2\/categories?post=108136"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/brand24.com\/blog\/es\/wp-json\/wp\/v2\/tags?post=108136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}