{"id":173047,"date":"2025-03-06T17:56:26","date_gmt":"2025-03-06T16:56:26","guid":{"rendered":"https:\/\/brand24.com\/blog\/?p=173047"},"modified":"2026-04-13T12:44:15","modified_gmt":"2026-04-13T10:44:15","slug":"metricas-de-exito-del-cliente","status":"publish","type":"post","link":"https:\/\/brand24.com\/blog\/es\/customer-success-metrics\/","title":{"rendered":"Las 10 m\u00e9tricas clave del \u00e9xito de los clientes que debes seguir en 2026"},"content":{"rendered":"<p><strong>En el competitivo mercado actual, ofrecer un servicio al cliente excepcional es fundamental para retener y ampliar su base de clientes. Las m\u00e9tricas adecuadas marcan la diferencia y le gu\u00edan en cada paso del camino. Estas son las m\u00e9tricas esenciales de \u00e9xito de los clientes para los profesionales del marketing en 2026.<\/strong><\/p>\n\n\n\n<p class=\"has-background\" style=\"background-color:#eeffee\"><strong>M\u00e9tricas de \u00e9xito del cliente<\/strong> muestran hasta qu\u00e9 punto una empresa contribuye al \u00e9xito de sus clientes. Van m\u00e1s all\u00e1 de las cifras: muestran la satisfacci\u00f3n del cliente, su fidelidad y el valor real aportado por la empresa. Mediante el seguimiento de estos indicadores clave, las empresas pueden ver lo que funciona, solucionar los puntos d\u00e9biles y crear una experiencia de cliente m\u00e1s satisfactoria y fluida. Como resultado, pueden reforzar las relaciones, aumentar la retenci\u00f3n e impulsar el crecimiento sostenible.<\/p>\n\n\n\n<p>Hay muchas m\u00e9tricas de \u00e9xito del cliente entre las que elegir.&nbsp;<\/p>\n\n\n\n<p>La mayor\u00eda nos preguntamos \"c\u00f3mo elegir eficazmente las m\u00e9tricas de \u00e9xito del cliente adecuadas\" y \"c\u00f3mo adaptar estos indicadores a nuestro sector y a nuestros objetivos exclusivos\".<\/p>\n\n\n\n<p>En este art\u00edculo he recopilado 10 indicadores clave que miden el \u00e9xito de los clientes como un profesional. Tanto si se trata de una startup como de una gran empresa, dominar estas m\u00e9tricas es esencial para fidelizar a los clientes y aumentar los ingresos.<\/p>\n\n\n\n<p>PS. Tambi\u00e9n hay partes especiales para las empresas SaaS que requieren un enfoque ligeramente diferente.<\/p>\n\n\n\n<p>Analicemos las m\u00e9tricas esenciales para el \u00e9xito de los clientes.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"key\"><strong>M\u00e9tricas clave del \u00e9xito de los clientes:<\/strong><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"id01\"><strong>01 \u00cdndice de satisfacci\u00f3n del cliente (CSAT)<\/strong><\/h3>\n\n\n\n<p>Cuando hablamos de m\u00e9tricas de \u00e9xito del cliente, en \u00faltima instancia todo se reduce a las puntuaciones de satisfacci\u00f3n del cliente. Esta m\u00e9trica permite medir la satisfacci\u00f3n del cliente con una determinada interacci\u00f3n, producto o servicio.&nbsp;<\/p>\n\n\n\n<p>Se expresa en porcentajes, y el principio es sencillo:<strong> Cuanto mayor sea el porcentaje, mayor ser\u00e1 la satisfacci\u00f3n del cliente.&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>\ud83d\udcaa C\u00f3mo me ayuda esto:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Proporciona informaci\u00f3n r\u00e1pida y directa a los clientes.<\/li>\n\n\n\n<li>Eval\u00fae r\u00e1pidamente el grado de satisfacci\u00f3n.<\/li>\n\n\n\n<li>Identificar \u00e1reas de mejora.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\ud83d\udcca C\u00f3mo medirlo:<\/strong><\/h4>\n\n\n\n<p>\u00bfCu\u00e1l es la mejor manera de medir la satisfacci\u00f3n del cliente?&nbsp;<\/p>\n\n\n\n<p>Muy sencillo: \u00a1preg\u00fanteles!<\/p>\n\n\n\n<p class=\"has-text-align-center has-background\" style=\"background-color:#eeffee\"><em>\"\u00bfC\u00f3mo de satisfecho est\u00e1 hoy con su experiencia con nuestra empresa?\".<\/em><\/p>\n\n\n\n<p>Los clientes suelen responder utilizando una escala de Likert: de <strong>1<\/strong> (muy insatisfecho) a <strong>5<\/strong> (muy satisfecho).<\/p>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a03c45902334&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a03c45902334\" class=\"wp-block-image aligncenter size-full wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"501\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-satisfaction-score-1.png\" alt=\"C\u00f3mo medir la puntuaci\u00f3n de satisfacci\u00f3n del cliente\" class=\"wp-image-173080\" srcset=\"https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-satisfaction-score-1.png 700w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-satisfaction-score-1-18x12.png 18w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-satisfaction-score-1-300x215.png 300w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-satisfaction-score-1-222x159.png 222w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ampliar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<p>Si ofreces un producto espec\u00edfico, merece la pena complementar tu encuesta con el <strong>Puntuaci\u00f3n de satisfacci\u00f3n del producto (PSAT)<\/strong>lo que significa preguntar a los clientes sobre su satisfacci\u00f3n con el producto.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Consejos:<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Sea breve y directo:<\/strong> No abrume a sus clientes: aseg\u00farese de que las preguntas son sencillas y claras, y an\u00edmelos a responder.<\/li>\n\n\n\n<li><strong>Elige el momento adecuado:<\/strong> Lo ideal es pedirle su opini\u00f3n al final de la interacci\u00f3n o poco despu\u00e9s de la compra, cuando su opini\u00f3n a\u00fan est\u00e1 fresca.<\/li>\n\n\n\n<li><strong>Mantener el equilibrio:<\/strong> A nadie le gusta responder repetidamente a la misma pregunta, \u00bfverdad? Evite preguntar con demasiada frecuencia para evitar la fatiga de la encuesta y respetar el tiempo de sus clientes.<\/li>\n<\/ul>\n\n\n<style>.acf-simple-cta{border-radius:20px;background-color:#fff;max-width:640px;margin:auto;margin-bottom:30px;padding:30px 15px}@media(min-width: 768px){.acf-simple-cta{padding:48px 62px 46px 62px}}.acf-simple-cta__title{font-size:22px !important;font-weight:600;line-height:23px !important;color:#000;text-align:center;margin-top:10px}@media(min-width: 576px){.acf-simple-cta__title{max-width:280px;text-align:left;margin-top:0}}.acf-simple-cta__title span{color:#00ef88}.acf-simple-cta__row{text-align:center}@media(min-width: 768px){.acf-simple-cta__row{display:flex;align-items:center;justify-content:space-between;gap:10px;text-align:left}}.acf-simple-cta__content{margin-bottom:20px;text-align:center}@media(min-width: 576px){.acf-simple-cta__content{display:flex;justify-content:center;align-items:center;gap:10px;width:100%;max-width:100%}}@media(min-width: 768px){.acf-simple-cta__content{align-items:center;justify-content:space-between;margin-bottom:0;max-width:66%}}.acf-simple-cta__btn{flex-shrink:0;border-radius:30px;padding:11px 21px;font-size:14px;line-height:18px;font-weight:500 !important;color:#000 !important;letter-spacing:-0.14px;background-color:#00ef88;border:none;transition:background-color .3s ease,opacity .3s ease;display:inline-block}.acf-simple-cta__btn:hover{background-color:#4bffae;text-decoration:none;opacity:.9}.acf-simple-cta__btn:focus-visible{outline:2px solid #00ef88}.acf-simple-cta--primary{background-color:#00ef88}.acf-simple-cta--primary .acf-simple-cta__title{color:#fff}.acf-simple-cta--primary .acf-simple-cta__title span{color:#000}.acf-simple-cta--primary .acf-simple-cta__btn{background-color:#000;color:#fff !important;transition:background-color .3s ease-in-out}.acf-simple-cta--primary .acf-simple-cta__btn:hover{background-color:#171717}.acf-simple-cta--violet{background-color:#000}.acf-simple-cta--violet .acf-simple-cta__title{color:#fff}.acf-simple-cta--violet .acf-simple-cta__title span{color:#bf00ff}.acf-simple-cta--violet .acf-simple-cta__btn{background-color:#bf00ff;color:#000 !important;transition:background-color .3s ease-in-out}.acf-simple-cta--violet .acf-simple-cta__btn:hover{background-color:#bf00ff}.acf-simple-cta--small{padding:20px 15px}@media(min-width: 768px){.acf-simple-cta--small{padding:33px 45px 31px 56px}}.acf-simple-cta--no-icon .acf-simple-cta__content{max-width:100%;width:auto}.acf-simple-cta--no-icon .acf-simple-cta__title{max-width:100%}@media(min-width: 768px){.acf-simple-cta--no-icon.acf-simple-cta--small .acf-simple-cta__content{max-width:55%}}<\/style>\n<div class=\"acf-simple-cta acf-simple-cta--primary acf-simple-cta--no-icon\">\n    <div class=\"acf-simple-cta__wrapper\">\n        <div class=\"acf-simple-cta__row\">\n            <div class=\"acf-simple-cta__content\">\n                                                    <div class=\"acf-simple-cta__title\">Realice un seguimiento de las principales m\u00e9tricas de \u00e9xito de los clientes.<\/div>\n                            <\/div>\n                            <a href=\"https:\/\/app.brand24.com\/user\/register-account\/?custom_form=334\" class=\"acf-simple-cta__btn\" target=\"_blank\">Comienza la prueba<\/a>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"id02\"><strong>02 El volumen de menciones<\/strong><\/h3>\n\n\n\n<p>Sospecho que este indicador no siempre es obvio, \u00a1lo cual es una pena!<\/p>\n\n\n\n<p>Al fin y al cabo, si la gente habla de algo, significa que le importa: \u00a1despierta emociones y compromiso!<\/p>\n\n\n\n<p>Lo mismo ocurre cuando mention su marca, producto o servicio.<\/p>\n\n\n\n<p>En <strong>volumen de menciones<\/strong> refleja la frecuencia con la que la gente habla de su marca o hace referencia a ella, lo que le ofrece una valiosa informaci\u00f3n sobre su marca. <a href=\"https:\/\/brand24.com\/blog\/es\/notoriedad-de-marca\/\" target=\"_blank\" rel=\"noopener\" title=\"notoriedad de marca\"><strong>notoriedad de marca<\/strong><\/a>inter\u00e9s y compromiso.<\/p>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a03c45903025&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a03c45903025\" class=\"wp-block-image aligncenter size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1140\" height=\"505\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-mentions-filtered-by-Brand24-1140x505.jpg\" alt=\"El volumen de mention detectado por Brand24\" class=\"wp-image-173076\" srcset=\"https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-mentions-filtered-by-Brand24-1140x505.jpg 1140w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-mentions-filtered-by-Brand24-1536x681.jpg 1536w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-mentions-filtered-by-Brand24-18x8.jpg 18w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-mentions-filtered-by-Brand24-300x133.jpg 300w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-mentions-filtered-by-Brand24-248x110.jpg 248w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-mentions-filtered-by-Brand24.jpg 1300w\" sizes=\"auto, (max-width: 1140px) 100vw, 1140px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ampliar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\ud83d\udcaa C\u00f3mo me ayuda esto:<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Comprender el contexto<\/strong> - Analizar d\u00f3nde y c\u00f3mo la gente mention mi marca para obtener una visi\u00f3n m\u00e1s profunda de la percepci\u00f3n del cliente.<\/li>\n\n\n\n<li><strong>Medir la visibilidad de la marca<\/strong> - Evaluar mi <a href=\"https:\/\/brand24.com\/blog\/es\/presencia-de-marca\/\" target=\"_blank\" rel=\"noopener\" title=\"\">presencia de marca<\/a> dentro del nicho y el mercado para evaluar la eficacia de las estrategias.<\/li>\n\n\n\n<li><strong>Seguimiento de la posici\u00f3n de la marca y de la competencia<\/strong> - Comparar los mention de la marca con los de la competencia para identificar los puntos fuertes y d\u00e9biles y las oportunidades de crecimiento.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\ud83d\udcca C\u00f3mo medirlo:<\/strong><\/h4>\n\n\n\n<p>Hacer un seguimiento manual de todos los mention de la marca es casi imposible, sobre todo con un p\u00fablico tan numeroso y activo.<\/p>\n\n\n\n<p>Por eso el uso de <a href=\"https:\/\/brand24.com\/blog\/es\/herramientas-de-seguimiento-de-medios\/\" target=\"_blank\" rel=\"noopener\" title=\"\">herramientas de seguimiento de medios<\/a> es el enfoque inteligente. Estas herramientas recopilan autom\u00e1ticamente todos los mention, los analizan y proporcionan informaci\u00f3n clave sobre su audiencia.<\/p>\n\n\n\n<p>Con tantas opciones disponibles, es esencial elegir una herramienta que:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Cubre todos los <strong>canales sociales y no sociales<\/strong><\/li>\n\n\n\n<li>Utiliza <strong>Inteligencia artificial <\/strong>an\u00e1lisis para obtener informaci\u00f3n m\u00e1s r\u00e1pida y precisa<\/li>\n\n\n\n<li>Le ayuda a realizar un seguimiento eficaz de las tendencias, el sentimiento y la participaci\u00f3n de la audiencia.<\/li>\n<\/ul>\n\n\n\n<p>\u00a1Todo esto lo encontr\u00e9 aqu\u00ed!<\/p>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a03c45903a74&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a03c45903a74\" class=\"wp-block-image aligncenter size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1140\" height=\"333\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-mentions-and-reach-analysis-1140x333.jpg\" alt=\"Mentions&amp;Reach chart en Brand24 - la mejor herramienta de escucha social\" class=\"wp-image-173077\" srcset=\"https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-mentions-and-reach-analysis-1140x333.jpg 1140w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-mentions-and-reach-analysis-18x5.jpg 18w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-mentions-and-reach-analysis-300x88.jpg 300w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-mentions-and-reach-analysis-248x72.jpg 248w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-mentions-and-reach-analysis.jpg 1148w\" sizes=\"auto, (max-width: 1140px) 100vw, 1140px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ampliar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<p>El gr\u00e1fico ilustra la evoluci\u00f3n del volumen de mention en los \u00faltimos 30 d\u00edas.<\/p>\n\n\n\n<p>Una de las cosas que m\u00e1s me gusta de Brand24 es su <strong>Detector de eventos<\/strong>lo que facilita la detecci\u00f3n de picos o ca\u00eddas repentinas en mention. Esto resulta especialmente \u00fatil para supervisar los comentarios de los clientes durante nuevas campa\u00f1as, lanzamientos de productos u otros eventos clave.<\/p>\n\n\n\n<p>Basta con hacer clic en el signo de exclamaci\u00f3n del diagrama para ver la causa de la anomal\u00eda.<\/p>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a03c45904326&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a03c45904326\" class=\"wp-block-image aligncenter size-full wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1116\" height=\"311\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-events-detector.jpg\" alt=\"Detecci\u00f3n de un importante mention por Brand24 Detector de Sucesos\" class=\"wp-image-173075\" srcset=\"https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-events-detector.jpg 1116w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-events-detector-18x5.jpg 18w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-events-detector-300x84.jpg 300w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-events-detector-248x69.jpg 248w\" sizes=\"auto, (max-width: 1116px) 100vw, 1116px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ampliar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"id03\"><strong>03 Net Promoter Score (NPS)<\/strong><\/h3>\n\n\n\n<p>Tambi\u00e9n conocida como encuesta de fidelizaci\u00f3n de clientes.<\/p>\n\n\n\n<p>El boca a boca es una de las t\u00e1cticas de marketing m\u00e1s eficaces.<\/p>\n\n\n\n<p>Al fin y al cabo, es bien sabido que las recomendaciones de amigos o familiares tienen m\u00e1s peso que cualquier anuncio, algo que los estudios demuestran sistem\u00e1ticamente.<\/p>\n\n\n\n<p>Por eso es tan importante centrarse en el \u00e9xito de los clientes. Mantiene las relaciones con los clientes existentes y crea defensores de la marca que difunden el boca a boca positivo.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\ud83d\udcaa C\u00f3mo me ayuda esto:<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Medir la fidelidad de los clientes<\/strong> - determina la probabilidad de que los clientes recomienden mi empresa.<\/li>\n\n\n\n<li><strong>Identificar los puntos fuertes y d\u00e9biles<\/strong> - Detecte f\u00e1cilmente las \u00e1reas susceptibles de mejora.<\/li>\n\n\n\n<li><strong>Rendimiento de referencia<\/strong> - Comparar mi NPS con los est\u00e1ndares del sector o a lo largo del tiempo para realizar un seguimiento del progreso y seguir siendo competitivo.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\ud83d\udcca C\u00f3mo medirlo:<\/strong><\/h4>\n\n\n\n<p>La clave est\u00e1 en la sencillez.<\/p>\n\n\n\n<p>Una vez m\u00e1s, \u00a1pregunte a sus clientes!<\/p>\n\n\n\n<p class=\"has-text-align-center has-background\" style=\"background-color:#eeffee\"><em>\"En una escala de 0 a 10, \u00bfqu\u00e9 probabilidad hay de que recomiende nuestra empresa\/servicio\/producto a un amigo?\".<\/em><\/p>\n\n\n\n<p>Como puede ver, la escala es diferente: no 5, sino 10.&nbsp;<\/p>\n\n\n\n<p>\u00bfPor qu\u00e9?&nbsp;<\/p>\n\n\n\n<p>Porque las respuestas se dividen en tres categor\u00edas:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Promotores (9-10):<\/strong> Entusiastas leales que seguir\u00e1n comprando y recomendando a otros.<\/li>\n\n\n\n<li><strong>Pasivos (7-8):<\/strong> Los clientes satisfechos pero no entusiastas son vulnerables a las ofertas de la competencia.<\/li>\n\n\n\n<li><strong>Detractores (0-6):<\/strong> Clientes insatisfechos que podr\u00edan da\u00f1ar su marca a trav\u00e9s del boca a boca negativo.<\/li>\n<\/ul>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a03c45904dbd&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a03c45904dbd\" class=\"wp-block-image aligncenter size-full wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"501\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Net-Promoter-Score.png\" alt=\"C\u00f3mo medir la puntuaci\u00f3n neta de los promotores\" class=\"wp-image-173056\" srcset=\"https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Net-Promoter-Score.png 700w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Net-Promoter-Score-18x12.png 18w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Net-Promoter-Score-300x215.png 300w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Net-Promoter-Score-222x159.png 222w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ampliar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"id04\"><strong>04 Tasa de rotaci\u00f3n<\/strong><\/h3>\n\n\n\n<p>Seamos sinceros: es natural que los clientes busquen nuevas opciones y a veces abandonen un producto o servicio.&nbsp;<\/p>\n\n\n\n<p>Por eso, el c\u00e1lculo de las tasas de rotaci\u00f3n de clientes es clave para mantener el pulso y detectar los primeros indicios de cambios en el comportamiento de los clientes.&nbsp;<\/p>\n\n\n\n<p>Al fin y al cabo, prevenir los problemas antes de que se produzcan siempre es mejor, sobre todo en lo que respecta al \u00e9xito de los clientes.&nbsp;<\/p>\n\n\n\n<p>As\u00ed que, si observa un aumento constante de rechazos de clientes, t\u00f3melo como una llamada de atenci\u00f3n para revisar su estrategia de captaci\u00f3n de clientes.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\ud83d\udcaa C\u00f3mo me ayuda esto:<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Identificaci\u00f3n de tendencias:<\/strong> Una tasa de rotaci\u00f3n creciente indica que hay algo en el servicio o la asistencia que requiere atenci\u00f3n.<\/li>\n\n\n\n<li><strong>Mejorar la retenci\u00f3n:<\/strong> Mejorando la incorporaci\u00f3n, la asistencia o el producto, puedo reducir la rotaci\u00f3n y satisfacer a m\u00e1s clientes.<\/li>\n\n\n\n<li><strong>Seguimiento de la base de clientes:<\/strong> Comprender el comportamiento de los clientes y ajustar mi enfoque para cumplir los KPI de \u00e9xito.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\ud83d\udcca C\u00f3mo medirlo:<\/strong><\/h4>\n\n\n\n<p>Eso puede parecer aterrador, especialmente con la f\u00f3rmula. Pero te prometo que no lo es.&nbsp;<\/p>\n\n\n\n<p>En primer lugar, siempre determino el periodo en el que quiero medir la tasa de rotaci\u00f3n: mensual, trimestral o anual.&nbsp;<\/p>\n\n\n\n<p>A continuaci\u00f3n, cont\u00e9 el n\u00famero de clientes que dejaron de utilizar el producto o servicio durante ese periodo y lo compar\u00e9 con el n\u00famero total de clientes al principio.&nbsp;<\/p>\n\n\n\n<p>Teniendo todos estos datos, simplemente utilizo esta f\u00f3rmula:<\/p>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a03c459057d2&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a03c459057d2\" class=\"wp-block-image aligncenter size-full wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1050\" height=\"660\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Churn-Rate.png\" alt=\"C\u00f3mo medir la tasa de rotaci\u00f3n de clientes\" class=\"wp-image-173062\" srcset=\"https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Churn-Rate.png 1050w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Churn-Rate-18x12.png 18w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Churn-Rate-300x189.png 300w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Churn-Rate-248x156.png 248w\" sizes=\"auto, (max-width: 1050px) 100vw, 1050px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ampliar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<p>Y \u00a1voil\u00e1! Ahora puedo hacer un seguimiento de mi tasa de rotaci\u00f3n para controlar la retenci\u00f3n de clientes y detectar tendencias para mejorar el compromiso.<\/p>\n\n\n\n<p>Aunque una tasa de rotaci\u00f3n cero es poco realista, aspirar a una tasa de rotaci\u00f3n baja ayuda a mejorar las relaciones con los clientes y proporciona informaci\u00f3n para reducir la rotaci\u00f3n.<\/p>\n\n\n\n<div class=\"acf-simple-cta acf-simple-cta--primary acf-simple-cta--no-icon\">\n    <div class=\"acf-simple-cta__wrapper\">\n        <div class=\"acf-simple-cta__row\">\n            <div class=\"acf-simple-cta__content\">\n                                                    <div class=\"acf-simple-cta__title\">Pruebe la mejor herramienta para medir las m\u00e9tricas de \u00e9xito de los clientes.<\/div>\n                            <\/div>\n                            <a href=\"https:\/\/app.brand24.com\/user\/register-account\/?custom_form=334\" class=\"acf-simple-cta__btn\" target=\"_blank\">Comienza la prueba<\/a>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"id05\"><strong>05 Medios sociales y alcance no social<\/strong><\/h3>\n\n\n\n<p>Cada post que publicas en Internet es como volcar la primera ficha de domin\u00f3.<\/p>\n\n\n\n<p>Un suave empuj\u00f3n y la reacci\u00f3n se extiende, tocando a m\u00e1s y m\u00e1s gente.<\/p>\n\n\n\n<p>El alcance en las redes sociales mide hasta d\u00f3nde llega esa reacci\u00f3n y cu\u00e1ntas \"fichas de domin\u00f3\" derriba. Esto simplemente muestra cu\u00e1ntos espectadores \u00fanicos han visto tu contenido.<\/p>\n\n\n\n<p>Pero no te limites a una sola l\u00ednea de domin\u00f3. El alcance fuera de las redes sociales es como montar una pista que pasa por diferentes \"salas\": sitios web, boletines de noticias por correo electr\u00f3nico, comunicados de prensa, podcasts y foros.<\/p>\n\n\n\n<p>Mediante el seguimiento de estas m\u00e9tricas de marketing en todos estos canales, los responsables del \u00e9xito de los clientes pueden comprobar si su contenido crea un efecto domin\u00f3 o si las fichas s\u00f3lo caen al principio, seguidas de silencio.<\/p>\n\n\n\n<p>Controlar tanto el alcance social como el no social no es una m\u00e9trica obvia del \u00e9xito del cliente, aunque sean tan potentes.&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\ud83d\udcaa C\u00f3mo me ayuda esto:<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Spot Usuarios activos<\/strong>: En las redes sociales o fuera de ellas, para que mis esfuerzos den en el blanco correcto.<\/li>\n\n\n\n<li><strong>Convierta el alcance en satisfacci\u00f3n<\/strong>: Cuanto mayor sea el alcance, mayores ser\u00e1n las posibilidades de convertir a los espectadores pasivos en clientes satisfechos.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\ud83d\udcca C\u00f3mo medirlo:<\/strong><\/h4>\n\n\n\n<p>Espero que nadie lo haga manualmente hoy en d\u00eda, es una p\u00e9rdida de tiempo.<\/p>\n\n\n\n<p>El alcance en las redes sociales es f\u00e1cil de encontrar en el panel de an\u00e1lisis de cada plataforma nativa. El mayor reto es el alcance fuera de las redes sociales.<\/p>\n\n\n\n<p>Hacer un seguimiento de todos los foros, podcasts o blogs ser\u00eda casi imposible sin la ayuda de herramientas avanzadas.<\/p>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a03c45905df6&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a03c45905df6\" class=\"wp-block-image aligncenter size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1140\" height=\"505\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-mentions-filtered-by-Brand24-1140x505.jpg\" alt=\"Mention&amp;alcanza mention detectados por Brand24\" class=\"wp-image-173076\" srcset=\"https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-mentions-filtered-by-Brand24-1140x505.jpg 1140w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-mentions-filtered-by-Brand24-1536x681.jpg 1536w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-mentions-filtered-by-Brand24-18x8.jpg 18w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-mentions-filtered-by-Brand24-300x133.jpg 300w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-mentions-filtered-by-Brand24-248x110.jpg 248w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-mentions-filtered-by-Brand24.jpg 1300w\" sizes=\"auto, (max-width: 1140px) 100vw, 1140px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ampliar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<p>Sin embargo, tambi\u00e9n debe comparar los resultados a lo largo del tiempo para hacer un seguimiento de los cambios en su alcance social y no social. Esto le ayudar\u00e1 a identificar tendencias, medir el impacto de sus estrategias y ajustar su enfoque para mejorar la participaci\u00f3n y la visibilidad.&nbsp;<\/p>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a03c45906766&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a03c45906766\" class=\"wp-block-image aligncenter size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1140\" height=\"673\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-comparison-of-period-for-Fenty-Beuty-by-Brand24-1140x673.jpeg\" alt=\"Comparaci\u00f3n durante el periodo para Fenty Beauty por Brand24\" class=\"wp-image-173064\" srcset=\"https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-comparison-of-period-for-Fenty-Beuty-by-Brand24-1140x673.jpeg 1140w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-comparison-of-period-for-Fenty-Beuty-by-Brand24-18x12.jpeg 18w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-comparison-of-period-for-Fenty-Beuty-by-Brand24-300x177.jpeg 300w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-comparison-of-period-for-Fenty-Beuty-by-Brand24-248x146.jpeg 248w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-comparison-of-period-for-Fenty-Beuty-by-Brand24.jpeg 1199w\" sizes=\"auto, (max-width: 1140px) 100vw, 1140px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ampliar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"id06\"><strong>06 An\u00e1lisis de Sentimiento<\/strong><\/h3>\n\n\n\n<p>Ahora, cuando hablamos de coleccionar mentions, no podemos pasar por alto <a href=\"https:\/\/brand24.com\/blog\/es\/analisis-de-opiniones\/\" target=\"_blank\" rel=\"noopener\" title=\"\">an\u00e1lisis de opiniones<\/a>.<\/p>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a03c4590700d&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a03c4590700d\" class=\"wp-block-image aligncenter size-full wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1124\" height=\"268\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-mention-detected-by-Brand24.jpg\" alt=\"Menci\u00f3n detectada por Brand24\" class=\"wp-image-173072\" srcset=\"https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-mention-detected-by-Brand24.jpg 1124w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-mention-detected-by-Brand24-18x4.jpg 18w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-mention-detected-by-Brand24-300x72.jpg 300w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-mention-detected-by-Brand24-248x59.jpg 248w\" sizes=\"auto, (max-width: 1124px) 100vw, 1124px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ampliar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<p><br>Esto significa que, una vez que disponga de todos los mention en los canales sociales y no sociales, es fundamental comprender c\u00f3mo habla la gente de usted y sus emociones.&nbsp;<\/p>\n\n\n\n<p>\u00bfSon positivos, neutros o negativos? Esta informaci\u00f3n tiene un valor incalculable para configurar su estrategia y supervisar importantes indicadores clave de rendimiento (KPI) para el \u00e9xito de los clientes.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\ud83d\udcaa C\u00f3mo me ayuda esto:<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Comprender al p\u00fablico: <\/strong>Sus necesidades y expectativas, que es la clave para una medici\u00f3n eficaz del \u00e9xito de los clientes.<\/li>\n\n\n\n<li><strong>Gesti\u00f3n de crisis:<\/strong> Responder a tiempo a posibles crisis, protegiendo la satisfacci\u00f3n del cliente y <a href=\"https:\/\/brand24.com\/blog\/es\/reputacion-de-marca\/\" target=\"_blank\" rel=\"noopener\" title=\"\">reputaci\u00f3n de marca.<\/a><\/li>\n\n\n\n<li><strong>Reforzar la posici\u00f3n en el mercado:<\/strong> Abordar las inquietudes antes de que se agraven demuestra a los clientes que los escucho, lo cual es una ventaja para la estrategia de \u00e9xito del cliente.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\ud83d\udcca C\u00f3mo medirlo:<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Valiosos comentarios de los clientes:<\/strong> Encuestas, rese\u00f1as o comentarios cualitativos de los clientes que ayudan a medir su satisfacci\u00f3n.<\/li>\n\n\n\n<li><strong>An\u00e1lisis basado en herramientas:<\/strong> Utilice <a href=\"https:\/\/brand24.com\/blog\/es\/mejores-herramientas-de-analisis-de-opiniones\/\" target=\"_blank\" rel=\"noopener\" title=\"\">herramientas de an\u00e1lisis de opiniones<\/a> para rastrear emociones y sentimientos en los mention.<\/li>\n\n\n\n<li><strong>El boca a boca:<\/strong> Escuche lo que dice la gente en conversaciones, rese\u00f1as y mentions: esto es esencial para recopilar opiniones de calidad de los clientes.<\/li>\n<\/ul>\n\n\n\n<p>Al integrar el an\u00e1lisis de opiniones con las m\u00e9tricas de \u00e9xito de los clientes, aument\u00e9 el \u00e9xito de los clientes y, lo que es m\u00e1s importante, cre\u00e9 una comunidad s\u00f3lida y comprometida.&nbsp;<\/p>\n\n\n\n<p>Aqu\u00ed veo el gr\u00e1fico de sentimiento general.<\/p>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a03c45907a08&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a03c45907a08\" class=\"wp-block-image aligncenter size-full wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1119\" height=\"408\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-sentiment-analysis.jpeg\" alt=\"Sentiment by Brand24 la mejor herramienta de escucha social\" class=\"wp-image-173067\" srcset=\"https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-sentiment-analysis.jpeg 1119w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-sentiment-analysis-18x7.jpeg 18w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-sentiment-analysis-300x109.jpeg 300w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-sentiment-analysis-248x90.jpeg 248w\" sizes=\"auto, (max-width: 1119px) 100vw, 1119px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ampliar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<p>Sin embargo, realizar\u00e9 un an\u00e1lisis en profundidad del sentimiento en cada plataforma de medios sociales para profundizar en el an\u00e1lisis. Esto me ayuda a identificar los puntos d\u00e9biles, mejorar la satisfacci\u00f3n del cliente y reaccionar r\u00e1pidamente cuando surge una crisis.<\/p>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a03c45908261&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a03c45908261\" class=\"wp-block-image aligncenter size-full wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"552\" height=\"402\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-sentiment-by-categories.jpg\" alt=\"Sentimiento por categor\u00edas para Ryanair by Brand24\" class=\"wp-image-173073\" srcset=\"https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-sentiment-by-categories.jpg 552w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-sentiment-by-categories-16x12.jpg 16w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-sentiment-by-categories-300x218.jpg 300w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-sentiment-by-categories-218x159.jpg 218w\" sizes=\"auto, (max-width: 552px) 100vw, 552px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ampliar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<div class=\"wp-block-columns has-black-color has-text-color has-background is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\" style=\"background-color:#f9f9f9\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:65%\">\n<p class=\"has-medium-font-size\">Pruebe la mejor herramienta de an\u00e1lisis de opiniones<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-buttons is-horizontal is-content-justification-left is-layout-flex wp-container-core-buttons-is-layout-20be11b6 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button custom-text-hover-button\"><a class=\"wp-block-button__link has-white-color has-text-color has-background wp-element-button google-hidden-link\" data-href=\"https:\/\/app.brand24.com\/user\/register-account\/?custom_form=334\" style=\"border-radius:6px;background-color:#778ced\">Iniciar prueba<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"acf-simple-cta acf-simple-cta--primary acf-simple-cta--no-icon\">\n    <div class=\"acf-simple-cta__wrapper\">\n        <div class=\"acf-simple-cta__row\">\n            <div class=\"acf-simple-cta__content\">\n                                                    <div class=\"acf-simple-cta__title\">\u00a1Prueba una herramienta avanzada de an\u00e1lisis de opiniones!<\/div>\n                            <\/div>\n                            <a href=\"https:\/\/app.brand24.com\/user\/register-account\/?custom_form=334\" class=\"acf-simple-cta__btn\" target=\"_blank\">Comienza la prueba<\/a>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"id07\"><strong>07 Puntuaci\u00f3n de la salud del cliente&nbsp;<\/strong><\/h3>\n\n\n\n<p>En <strong>Puntuaci\u00f3n de la salud del cliente (CHS)<\/strong> es una de las m\u00e9tricas clave m\u00e1s esenciales para el \u00e9xito del cliente. Me ayuda a predecir la situaci\u00f3n de un cliente, su compromiso general, su satisfacci\u00f3n y su probabilidad de retenci\u00f3n.&nbsp;<\/p>\n\n\n\n<p>Esto me ha resultado especialmente \u00fatil para identificar a los clientes en riesgo antes de que se den de baja y detectar oportunidades de venta o expansi\u00f3n entre los clientes satisfechos.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\ud83d\udcaa C\u00f3mo me ayuda esto:<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Retenga m\u00e1s clientes:<\/strong> Detecte a tiempo a los clientes que no participan para que el equipo de asistencia pueda tomar medidas antes de que se marchen.<\/li>\n\n\n\n<li><strong>Mejorar la atenci\u00f3n al cliente:<\/strong> Unas consultas de asistencia elevadas pueden indicar problemas de salud del cliente.<\/li>\n\n\n\n<li><strong>Maximizar las oportunidades de crecimiento:<\/strong> Los clientes con una puntuaci\u00f3n de salud alta son m\u00e1s propensos a subir de categor\u00eda, lo que facilita las ventas adicionales.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\ud83d\udcca C\u00f3mo medirlo:<\/strong><\/h4>\n\n\n\n<p>Empiece por definir lo que significa \"saludable\" y establezca puntos de referencia para la satisfacci\u00f3n y el compromiso.&nbsp;<\/p>\n\n\n\n<p>A continuaci\u00f3n, establezca indicadores clave de productividad. La puntuaci\u00f3n de la salud del cliente var\u00eda seg\u00fan el sector, y su c\u00e1lculo depende de los indicadores de comportamiento del cliente que hayan mostrado m\u00e1s valor.&nbsp;<\/p>\n\n\n\n<p>Pero tambi\u00e9n hay m\u00e9tricas comunes al c\u00e1lculo de las puntuaciones de salud del cliente que se utilizan para todo el mundo, como:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Uso del producto y compromiso<\/li>\n\n\n\n<li>Opini\u00f3n de los clientes y puntuaci\u00f3n Net Promoter<\/li>\n\n\n\n<li>Actividad del sitio web<\/li>\n\n\n\n<li>Consultas de atenci\u00f3n al cliente<\/li>\n\n\n\n<li>Actualizaciones y renovaciones de productos<\/li>\n\n\n\n<li>Participaci\u00f3n comunitaria<\/li>\n<\/ul>\n\n\n\n<p>Ahora, cree un sistema de puntuaci\u00f3n asignando valores ponderados a diferentes m\u00e9tricas, categorizando <strong>clientes como sanos, en riesgo o cr\u00edticos.&nbsp;<\/strong><\/p>\n\n\n\n<p>Despu\u00e9s de todos esos pasos, puede visualizar CHS a trav\u00e9s de paneles y elementos esenciales y configurar alertas para las puntuaciones en descenso.&nbsp;<\/p>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a03c459091ab&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a03c459091ab\" class=\"wp-block-image aligncenter size-full wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"675\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/How-to-measure-Customer-Health-Score.png\" alt=\"C\u00f3mo medir la puntuaci\u00f3n de la salud del cliente\" class=\"wp-image-173079\" srcset=\"https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/How-to-measure-Customer-Health-Score.png 700w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/How-to-measure-Customer-Health-Score-12x12.png 12w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/How-to-measure-Customer-Health-Score-300x289.png 300w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/How-to-measure-Customer-Health-Score-165x159.png 165w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ampliar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<p>Medir la puntuaci\u00f3n de la salud del cliente es un proceso que merece la pena aplicar. Mediante el seguimiento y la optimizaci\u00f3n de la CHS, se obtiene una visi\u00f3n m\u00e1s profunda de la participaci\u00f3n del cliente, se identifican los riesgos en una fase temprana y se descubren oportunidades de crecimiento, lo que conduce a una mayor retenci\u00f3n y al \u00e9xito a largo plazo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"id08\"><strong>08 Tasa de retenci\u00f3n de clientes&nbsp;<\/strong><\/h3>\n\n\n\n<p>Centrarse en la tasa de retenci\u00f3n de clientes es una decisi\u00f3n inteligente si lo que busca es impulsar las m\u00e9tricas de \u00e9xito de sus clientes.<\/p>\n\n\n\n<p>Es una de las m\u00e9tricas fundamentales del \u00e9xito de los clientes, ya que muestra lo bien que se satisfacen sus necesidades y se mantiene el compromiso de los clientes activos.&nbsp;<\/p>\n\n\n\n<p>Una tasa de retenci\u00f3n baja suele indicar problemas en la experiencia del cliente, como un bajo nivel de compromiso, expectativas insatisfechas o falta de apoyo adecuado.<\/p>\n\n\n\n<p>Al medir y mejorar su tasa de retenci\u00f3n de clientes, est\u00e1 reduciendo el coste de retenci\u00f3n de clientes (el gasto que supone perder clientes y captar otros nuevos) y creando una base s\u00f3lida de satisfacci\u00f3n del cliente. Adem\u00e1s, un menor coste de captaci\u00f3n de clientes beneficia directamente a su cuenta de resultados.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\ud83d\udcaa C\u00f3mo me ayuda esto:<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Menores costes de retenci\u00f3n<\/strong>: Cuanto m\u00e1s tiempo permanezcan los clientes, menos gasto en esfuerzos de retenci\u00f3n, manteniendo controlados los costes de adquisici\u00f3n.<\/li>\n\n\n\n<li><strong>Optimizar los recursos<\/strong>: Comprender los esfuerzos de retenci\u00f3n me ayuda a asignar los recursos de forma m\u00e1s eficiente, centr\u00e1ndome en las actividades de mayor impacto.<\/li>\n\n\n\n<li><strong>Seguimiento de las m\u00e9tricas de \u00e9xito<\/strong>: La retenci\u00f3n es un KPI clave que me permite medir el progreso y mostrar el impacto de mis esfuerzos en las partes interesadas.<\/li>\n\n\n\n<li><strong>Maximizar el CLV<\/strong>: Una alta retenci\u00f3n aumenta el CLV, garantizando que los clientes sigan aportando valor para el crecimiento a largo plazo.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\ud83d\udcca C\u00f3mo medirlo:<\/strong><\/h4>\n\n\n\n<p>Para medir eficazmente su tasa de retenci\u00f3n de clientes, debe hacer un seguimiento de cu\u00e1ntos clientes permanecen en su empresa durante un periodo determinado. Esta medida proporciona informaci\u00f3n sobre la eficacia de sus esfuerzos de \u00e9xito del cliente para mantener a los usuarios activos contentos y comprometidos.<\/p>\n\n\n\n<p>He aqu\u00ed la f\u00f3rmula para calcular su tasa de retenci\u00f3n de clientes:<\/p>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a03c45909c06&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a03c45909c06\" class=\"wp-block-image aligncenter size-full wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1050\" height=\"662\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Retention-Rate-.png\" alt=\"C\u00f3mo medir la tasa de retenci\u00f3n de clientes\" class=\"wp-image-173059\" srcset=\"https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Retention-Rate-.png 1050w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Retention-Rate--18x12.png 18w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Retention-Rate--300x189.png 300w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Retention-Rate--248x156.png 248w\" sizes=\"auto, (max-width: 1050px) 100vw, 1050px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ampliar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<p>Tambi\u00e9n puede realizar un seguimiento de la tasa de rotaci\u00f3n, la satisfacci\u00f3n del cliente y las m\u00e9tricas del valor de vida del cliente (CLV) para obtener informaci\u00f3n m\u00e1s detallada sobre la retenci\u00f3n de clientes.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"id09\"><strong>09 Valor del ciclo de vida del cliente<\/strong><\/h3>\n\n\n\n<p>El valor del ciclo de vida del cliente (CLV) cuantifica los ingresos totales que un cliente puede esperar a lo largo de toda la relaci\u00f3n.&nbsp;<\/p>\n\n\n\n<p>Es un indicador clave del \u00e9xito de los clientes, que pone de relieve el valor a largo plazo de fomentar relaciones s\u00f3lidas con ellos.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\ud83d\udcaa C\u00f3mo me ayuda esto:<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Identifica a los clientes a los que merece la pena dedicar m\u00e1s tiempo y recursos.<\/li>\n\n\n\n<li><strong>Mide el impacto del compromiso<\/strong>cu\u00e1nto esfuerzo requieren las iniciativas de \u00e9xito del cliente, como el servicio personalizado y el compromiso proactivo con el cliente.<\/li>\n\n\n\n<li><strong>Menor coste de adquisici\u00f3n de clientes<\/strong> (CAC): Al aumentar el CLV, puedo permitirme gastar m\u00e1s en captar nuevos clientes, siempre que su CLV justifique el coste.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\ud83d\udcca C\u00f3mo medirlo:<\/strong><\/h4>\n\n\n\n<p>Basta con aplicar esta f\u00f3rmula para calcular el valor del ciclo de vida del cliente:<\/p>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a03c4590a5a0&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a03c4590a5a0\" class=\"wp-block-image aligncenter size-full wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"344\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Lifetime-Value.png\" alt=\"C\u00f3mo medir el valor del ciclo de vida del cliente (CVL)\" class=\"wp-image-173060\" srcset=\"https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Lifetime-Value.png 700w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Lifetime-Value-18x9.png 18w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Lifetime-Value-300x147.png 300w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Lifetime-Value-248x122.png 248w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ampliar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<p>Esto puede asustar, as\u00ed que aqu\u00ed van algunos ejemplos para aclarar el concepto.<\/p>\n\n\n\n<p>Digamos:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Valor medio de compra = $50<\/li>\n\n\n\n<li>Frecuencia media de compra = 4 veces al a\u00f1o<\/li>\n\n\n\n<li>Tiempo de vida del cliente = 5 a\u00f1os<\/li>\n<\/ul>\n\n\n\n<p>Entonces:<\/p>\n\n\n\n<p>CLV=50\u00d74\u00d75=1000CLV=50\u00d74\u00d75=1000<\/p>\n\n\n\n<p>Esto significa que cada cliente vale $1000 durante los 5 a\u00f1os que permanezca en su empresa.<\/p>\n\n\n\n<p>No es ciencia de cohetes, \u00bfverdad? \ud83d\ude80<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"id10\"><strong>10 Puntuaci\u00f3n del esfuerzo del cliente<\/strong><\/h3>\n\n\n\n<p>La puntuaci\u00f3n del esfuerzo del cliente (CES) mide lo f\u00e1cil o dif\u00edcil que les resulta a los clientes interactuar con una empresa, ya sea resolviendo un problema, realizando una compra o utilizando un producto.&nbsp;<\/p>\n\n\n\n<p>A diferencia de las m\u00e9tricas de satisfacci\u00f3n tradicionales, la puntuaci\u00f3n del esfuerzo del cliente se centra en reducir las fricciones en el recorrido del cliente, y esto es crucial para que sea la mejor experiencia posible.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\ud83d\udcaa C\u00f3mo me ayuda esto:<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Aumenta la retenci\u00f3n y la fidelidad:<\/strong> Las experiencias m\u00e1s sencillas hacen que los clientes vuelvan.<\/li>\n\n\n\n<li><strong>Identifica los puntos d\u00e9biles:<\/strong> Destaca las fricciones en el servicio, la aplicaci\u00f3n o la usabilidad.<\/li>\n\n\n\n<li><strong>Aumenta la eficacia de la asistencia:<\/strong> Reduce el volumen de tickets mejorando la resoluci\u00f3n de problemas.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\ud83d\udcca C\u00f3mo medirlo:<\/strong><\/h4>\n\n\n\n<p>Para medirlo, basta con preguntar a los clientes despu\u00e9s de interactuar con la empresa.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">He aqu\u00ed una lista de ejemplos de preguntas que hago regularmente a mis clientes:<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u00bfHa sido f\u00e1cil resolver su problema hoy?<\/li>\n\n\n\n<li>\u00bfCu\u00e1nto esfuerzo le cost\u00f3 completar su compra o registrarse?<\/li>\n\n\n\n<li>\u00bfLe result\u00f3 f\u00e1cil encontrar la informaci\u00f3n que necesitaba en nuestro sitio web o aplicaci\u00f3n?<\/li>\n\n\n\n<li>\u00bfHa encontrado alg\u00fan obst\u00e1culo al utilizar nuestro producto\/servicio? En caso afirmativo, especifique.<\/li>\n\n\n\n<li>\u00bfLe result\u00f3 f\u00e1cil obtener la ayuda que necesitaba de nuestro equipo?<\/li>\n<\/ul>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a03c4590b0ef&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a03c4590b0ef\" class=\"wp-block-image aligncenter size-full wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"400\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Effort-Score.png\" alt=\"C\u00f3mo medir la puntuaci\u00f3n del esfuerzo del cliente\" class=\"wp-image-173061\" srcset=\"https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Effort-Score.png 700w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Effort-Score-18x10.png 18w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Effort-Score-300x171.png 300w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Effort-Score-248x142.png 248w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ampliar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<p>D\u00f3nde:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Valoraciones de los clientes<\/strong> = Puntuaciones individuales dadas por los clientes (normalmente en una escala de 1 a 5 o de 1 a 7, donde m\u00e1s alto significa menos esfuerzo).<\/li>\n\n\n\n<li><strong>N\u00famero total de respuestas<\/strong> = Total de respuestas recogidas<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Ejemplo de c\u00e1lculo:<\/strong><\/h4>\n\n\n\n<p>Digamos que ha encuestado <strong>100 clientes<\/strong>y su puntuaci\u00f3n total combinada fue <strong>480<\/strong> (en una escala del 1 al 7).<\/p>\n\n\n\n<p>CES= 480 \/ 100 = 4,8 CES<\/p>\n\n\n\n<p>La interpretaci\u00f3n de la puntuaci\u00f3n depende de la escala adoptada. Si los consumidores eligen en una escala de 0- 7, como en este ejemplo, entonces:<\/p>\n\n\n\n<p><strong>\u2705 CES alto (m\u00e1s cercano a 7) \u2192 <\/strong>Los clientes encuentran las interacciones f\u00e1ciles y fluidas, lo que indica una experiencia sin problemas.<\/p>\n\n\n\n<p><strong>\u274c CES bajo (m\u00e1s cercano a 1) \u2192<\/strong> Los clientes tienen dificultades y experimentan fricciones, lo que indica la necesidad de mejorar los procesos.<\/p>\n\n\n\n<p>Si quiere mejorar el esfuerzo y la experiencia del cliente, aqu\u00ed tiene algunos consejos pr\u00e1cticos que me han funcionado y que pueden ayudarle a usted tambi\u00e9n:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Mejorar las opciones de autoservicio<\/strong> - Ofrezca preguntas frecuentes, bases de conocimientos y casos pr\u00e1cticos para ayudar a los clientes a encontrar respuestas r\u00e1pidamente.<\/li>\n\n\n\n<li><strong>Racionalizar los procesos<\/strong> - Simplifique las transacciones, la asistencia y la implantaci\u00f3n aprovechando la tecnolog\u00eda m\u00e1s avanzada.<\/li>\n\n\n\n<li><strong>Mejorar la resoluci\u00f3n en el primer contacto<\/strong> - Aseg\u00farese de que los problemas se resuelven a la primera, para que los clientes no tengan que seguir pidiendo ayuda.<\/li>\n<\/ul>\n\n\n\n<div class=\"acf-simple-cta acf-simple-cta--primary acf-simple-cta--no-icon\">\n    <div class=\"acf-simple-cta__wrapper\">\n        <div class=\"acf-simple-cta__row\">\n            <div class=\"acf-simple-cta__content\">\n                                                    <div class=\"acf-simple-cta__title\">Realice un seguimiento de las principales m\u00e9tricas de \u00e9xito de los clientes.<\/div>\n                            <\/div>\n                            <a href=\"https:\/\/app.brand24.com\/user\/register-account\/?custom_form=334\" class=\"acf-simple-cta__btn\" target=\"_blank\">Comienza la prueba<\/a>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"saas\"><strong>M\u00e9tricas de \u00e9xito de clientes de SaaS:<\/strong><\/h2>\n\n\n\n<p>En lugar de los modelos de compra \u00fanica, el \u00e9xito del SaaS depende de la retenci\u00f3n, el compromiso de los usuarios y los ingresos medios recurrentes, no s\u00f3lo de las ventas iniciales.&nbsp;<\/p>\n\n\n\n<p>Por eso las empresas de SaaS se centran en estas m\u00e9tricas:<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\ud83d\udcc8Ingresos recurrentes mensuales (MRR) e ingresos recurrentes anuales (ARR)<\/strong><\/h4>\n\n\n\n<p>Piense en ellos como el latido de su negocio. Muestran cu\u00e1ntos ingresos genera con las suscripciones mensuales o anuales. Si crecen de forma constante, es una clara se\u00f1al de que tu negocio est\u00e1 creciendo con \u00e9xito.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\ud83d\ude80 \u00cdndice de adopci\u00f3n del producto<\/strong><\/h4>\n\n\n\n<p>Ha creado un producto fant\u00e1stico, pero \u00bflo utiliza la gente? Este indicador le ayuda a comprender la frecuencia y eficacia con que los clientes utilizan las distintas funciones, lo que le permite saber qu\u00e9 funciona y qu\u00e9 puede necesitar mejoras. As\u00ed, introduzca constantemente las evaluaciones necesarias&nbsp;<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u23f3 Tiempo hasta el valor (TTV)<\/strong><\/h4>\n\n\n\n<p>\u00a1La primera impresi\u00f3n es importante! Mide la rapidez con la que un nuevo cliente comienza a ver los beneficios reales de su producto. Cuanto m\u00e1s corto sea el TTV, m\u00e1s probable ser\u00e1 que se queden con el producto y se conviertan en usuarios a largo plazo.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\ud83d\udcc8 \u00cdndice de ingresos por expansi\u00f3n<\/strong><\/h4>\n\n\n\n<p>Un indicador clave para el crecimiento del producto. Sus clientes actuales conf\u00edan en usted, as\u00ed que \u00bfest\u00e1n actualizando, comprando complementos o ampliando su uso? Este indicador realiza un seguimiento de los ingresos procedentes de ventas adicionales, ventas cruzadas y servicios adicionales, ayud\u00e1ndole a identificar oportunidades de crecimiento dentro de su base de usuarios actual.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\ud83c\udfaf Eficacia del proceso de incorporaci\u00f3n<\/strong><\/h4>\n\n\n\n<p>Una implantaci\u00f3n sin problemas puede contribuir a la retenci\u00f3n de clientes. Puede ayudarle a ver lo bien que se gu\u00eda a los nuevos clientes a trav\u00e9s de la configuraci\u00f3n y el aprendizaje, haciendo que el primer contacto sea lo m\u00e1s fluido posible.<\/p>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a03c4590c271&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a03c4590c271\" class=\"wp-block-image aligncenter size-full wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1050\" height=\"698\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/SaaS-customer-success-metrics.png\" alt=\"M\u00e9tricas clave del \u00e9xito de los clientes de SaaS\" class=\"wp-image-173055\" srcset=\"https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/SaaS-customer-success-metrics.png 1050w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/SaaS-customer-success-metrics-18x12.png 18w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/SaaS-customer-success-metrics-300x199.png 300w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/SaaS-customer-success-metrics-239x159.png 239w\" sizes=\"auto, (max-width: 1050px) 100vw, 1050px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ampliar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<p>Al realizar un seguimiento de estas m\u00e9tricas clave, no s\u00f3lo est\u00e1 controlando los n\u00fameros, sino que est\u00e1 dando forma a una estrategia para el \u00e9xito a largo plazo, unas relaciones m\u00e1s s\u00f3lidas con los clientes y un crecimiento sostenible.<br><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"tip\"><strong>Consejo: Aproveche las herramientas avanzadas para analizar las m\u00e9tricas de \u00e9xito del cliente sin esfuerzo<\/strong><\/h2>\n\n\n\n<p>La satisfacci\u00f3n del cliente puede cambiar r\u00e1pidamente y requiere atenci\u00f3n y ajustes constantes.&nbsp;<\/p>\n\n\n\n<p>Tanto si dirige un negocio SaaS, de comercio electr\u00f3nico o de servicios, las herramientas avanzadas pueden ayudarle. Eliminan las conjeturas mediante la automatizaci\u00f3n de la recopilaci\u00f3n, el an\u00e1lisis y la visualizaci\u00f3n de datos, lo que le proporciona informaci\u00f3n en tiempo real al alcance de la mano.&nbsp;<\/p>\n\n\n\n<p>Le mostrar\u00e9 c\u00f3mo funciona utilizando <a href=\"https:\/\/brand24.com\/blog\/es\/\" target=\"_blank\" rel=\"noopener\" title=\"\">Brand24<\/a> como ejemplo.<\/p>\n\n\n\n<p>Una vez abierto el <strong>An\u00e1lisis de m\u00e9tricas<\/strong> obtendr\u00e1 una r\u00e1pida visi\u00f3n general de su proyecto. Muestra cifras clave e interpretaciones basadas en IA, lo que facilita la comprensi\u00f3n del rendimiento de un vistazo.<\/p>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a03c4590cc44&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a03c4590cc44\" class=\"wp-block-image aligncenter size-full wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"735\" height=\"606\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-Brand-analysis-by-Brand24.jpg\" alt=\"An\u00e1lisis sumario basado en IA de Fenty Beauty por Brand24\" class=\"wp-image-173071\" srcset=\"https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-Brand-analysis-by-Brand24.jpg 735w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-Brand-analysis-by-Brand24-15x12.jpg 15w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-Brand-analysis-by-Brand24-300x247.jpg 300w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-Brand-analysis-by-Brand24-193x159.jpg 193w\" sizes=\"auto, (max-width: 735px) 100vw, 735px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ampliar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<p>Como se puede ver aqu\u00ed, incluso con los resultados abrumadoramente positivos que Fenty puede mostrar con orgullo, todav\u00eda hay \u00e1reas de mejora, como Twitter (X), que tiene el sentimiento negativo m\u00e1s alto y puede requerir m\u00e1s atenci\u00f3n.&nbsp;<\/p>\n\n\n\n<p>Adem\u00e1s, la nueva colaboraci\u00f3n de Fenty con GloRilla ha dado mucho que hablar: \u00a1buen trabajo, Fenty!<\/p>\n\n\n\n<p>Veamos m\u00e1s de cerca la situaci\u00f3n en Twitter (X).<\/p>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a03c4590d510&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a03c4590d510\" class=\"wp-block-image aligncenter size-full wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"719\" height=\"480\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-sentiment-by-social-media-channels.jpeg\" alt=\"An\u00e1lisis de sentimiento para Fenty Beauty por Brand24 - la mejor herramienta de monitorizaci\u00f3n social\" class=\"wp-image-173068\" srcset=\"https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-sentiment-by-social-media-channels.jpeg 719w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-sentiment-by-social-media-channels-18x12.jpeg 18w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-sentiment-by-social-media-channels-300x200.jpeg 300w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-sentiment-by-social-media-channels-238x159.jpeg 238w\" sizes=\"auto, (max-width: 719px) 100vw, 719px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ampliar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<p>\u00a1No tiene tan mala pinta! El sentimiento positivo en torno a Fenty Beauty en Twitter (X) sigue superando al negativo, \u00a1lo cual es una gran noticia para la marca!<\/p>\n\n\n\n<p>Brand24 reconoce si un mention es positivo, neutro o negativo y asigna emociones espec\u00edficas, como admiraci\u00f3n, alegr\u00eda, disgusto, tristeza, miedo o enfado. Esto me permite comprender mejor los estados de \u00e1nimo de los clientes y responder en consecuencia.&nbsp;<\/p>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a03c4590dd99&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a03c4590dd99\" class=\"wp-block-image aligncenter size-full wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"725\" height=\"548\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-emotion-analysis-by-Brand24.jpg\" alt=\"An\u00e1lisis de las emociones por Brand24\" class=\"wp-image-173070\" srcset=\"https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-emotion-analysis-by-Brand24.jpg 725w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-emotion-analysis-by-Brand24-16x12.jpg 16w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-emotion-analysis-by-Brand24-300x227.jpg 300w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-emotion-analysis-by-Brand24-210x159.jpg 210w\" sizes=\"auto, (max-width: 725px) 100vw, 725px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ampliar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<p><br>Adem\u00e1s, el an\u00e1lisis de m\u00e9tricas basado en IA identifica qu\u00e9 fuentes generan la mayor eficacia de alcance.<\/p>\n\n\n\n<p>Esta informaci\u00f3n me ayuda a asignar estrat\u00e9gicamente mi presupuesto de marketing y comunicaci\u00f3n para maximizar el impacto y el compromiso donde m\u00e1s importa.<\/p>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a03c4590e5f2&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a03c4590e5f2\" class=\"wp-block-image aligncenter size-full wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"733\" height=\"529\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-most-reach-efficient-by-Brand24.jpg\" alt=\"La mayor eficacia de alcance para Fenty Beauty\" class=\"wp-image-173069\" srcset=\"https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-most-reach-efficient-by-Brand24.jpg 733w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-most-reach-efficient-by-Brand24-18x12.jpg 18w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-most-reach-efficient-by-Brand24-300x217.jpg 300w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/Customer-Success-Metrics-most-reach-efficient-by-Brand24-220x159.jpg 220w\" sizes=\"auto, (max-width: 733px) 100vw, 733px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ampliar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<div class=\"acf-simple-cta acf-simple-cta--primary acf-simple-cta--no-icon\">\n    <div class=\"acf-simple-cta__wrapper\">\n        <div class=\"acf-simple-cta__row\">\n            <div class=\"acf-simple-cta__content\">\n                                                    <div class=\"acf-simple-cta__title\">Realice un seguimiento de las principales m\u00e9tricas de \u00e9xito de los clientes.<\/div>\n                            <\/div>\n                            <a href=\"https:\/\/app.brand24.com\/user\/register-account\/?custom_form=334\" class=\"acf-simple-cta__btn\" target=\"_blank\">Comienza la prueba<\/a>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"conclusion\"><strong>Conclusi\u00f3n<\/strong><\/h2>\n\n\n\n<p>El \u00e9xito del cliente se ha convertido en un factor esencial para construir e impulsar el crecimiento de la marca en el competitivo mercado actual.<\/p>\n\n\n\n<p>Debe realizar un seguimiento de los indicadores clave de \u00e9xito de los clientes para maximizar la productividad y mantenerse por delante de ellos. Y lo m\u00e1s importante, \u00a1selecci\u00f3nelos adecuadamente para su sector!\u00a0<\/p>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a03c4590efe8&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a03c4590efe8\" class=\"wp-block-image aligncenter size-full wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1050\" height=\"932\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/10-Key-Customer-Success-Metrics.png\" alt=\"Principales m\u00e9tricas de \u00e9xito de los clientes \" class=\"wp-image-173063\" srcset=\"https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/10-Key-Customer-Success-Metrics.png 1050w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/10-Key-Customer-Success-Metrics-14x12.png 14w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/10-Key-Customer-Success-Metrics-300x266.png 300w, https:\/\/brand24.com\/blog\/app\/uploads\/2025\/03\/10-Key-Customer-Success-Metrics-179x159.png 179w\" sizes=\"auto, (max-width: 1050px) 100vw, 1050px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ampliar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<p>Ponerlas en pr\u00e1ctica es mucho m\u00e1s f\u00e1cil de lo que parece, y espero que este breve tutorial paso a paso sobre cada una de ellas te facilite definitivamente todo el proceso.<\/p>\n\n\n\n<p>Debe aplicar las estrategias adecuadas y potenciar sus esfuerzos con <a href=\"https:\/\/brand24.com\/blog\/es\/que-es-el-seguimiento-y-analisis-de-los-medios-de-comunicacion\/\" target=\"_blank\" rel=\"noopener\" title=\"\">al siguiente nivel<\/a> para obtener informaci\u00f3n valiosa. Para mejorar las relaciones con los clientes y ayudar de inmediato a los gestores de \u00e9xito de clientes a hacer su trabajo m\u00e1s eficiente.\u00a0<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Principales conclusiones:<\/strong><\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>La estacionalidad afecta a las m\u00e9tricas -<\/strong> Ajusta tus objetivos y expectativas en consecuencia: no te asustes si tu \u00edndice baja en invierno al vender ba\u00f1adores \ud83d\ude09 .<\/li>\n\n\n\n<li><strong>S\u00e9 constante y haz un seguimiento regular -<\/strong> Identificar los patrones de comportamiento de los consumidores le ayuda a comprender mejor a su p\u00fablico y a mejorar su satisfacci\u00f3n.<\/li>\n\n\n\n<li><strong>Utilizar herramientas e IA -<\/strong> Automatice los procesos para agilizar la atenci\u00f3n al cliente y mejorar la eficacia.<\/li>\n\n\n\n<li><strong>Las m\u00e9tricas importan, pero las personas son lo primero -<\/strong> El objetivo final es la satisfacci\u00f3n real del cliente, no s\u00f3lo las cifras.<\/li>\n<\/ul>\n\n\n\n<p>Ya est\u00e1 casi listo para ver las m\u00e9tricas de \u00e9xito del cliente en acci\u00f3n. Para tener una visi\u00f3n completa, <a href=\"https:\/\/app.brand24.com\/user\/register-account\/?custom_form=334\" target=\"_blank\" rel=\"noopener\" title=\"\">Pruebe Brand24 gratis<\/a> \u00a1y empiece a medir lo que de verdad importa!<\/p>","protected":false},"excerpt":{"rendered":"<p>Las m\u00e9tricas de \u00e9xito del cliente muestran lo bien que est\u00e1 ayudando a los clientes a ganar. Haga un seguimiento de las m\u00e9tricas adecuadas para aumentar la fidelidad, la retenci\u00f3n y el crecimiento a largo plazo. He aqu\u00ed c\u00f3mo hacerlo<\/p>","protected":false},"author":89,"featured_media":173082,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[4148],"tags":[],"class_list":["post-173047","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-analytics-and-reporting"],"acf":[],"aioseo_notices":[],"cf_author_first_name":"Agata","cf_author_last_name":"Bernatek","_links":{"self":[{"href":"https:\/\/brand24.com\/blog\/es\/wp-json\/wp\/v2\/posts\/173047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/brand24.com\/blog\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/brand24.com\/blog\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/brand24.com\/blog\/es\/wp-json\/wp\/v2\/users\/89"}],"replies":[{"embeddable":true,"href":"https:\/\/brand24.com\/blog\/es\/wp-json\/wp\/v2\/comments?post=173047"}],"version-history":[{"count":5,"href":"https:\/\/brand24.com\/blog\/es\/wp-json\/wp\/v2\/posts\/173047\/revisions"}],"predecessor-version":[{"id":179520,"href":"https:\/\/brand24.com\/blog\/es\/wp-json\/wp\/v2\/posts\/173047\/revisions\/179520"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/brand24.com\/blog\/es\/wp-json\/wp\/v2\/media\/173082"}],"wp:attachment":[{"href":"https:\/\/brand24.com\/blog\/es\/wp-json\/wp\/v2\/media?parent=173047"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/brand24.com\/blog\/es\/wp-json\/wp\/v2\/categories?post=173047"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/brand24.com\/blog\/es\/wp-json\/wp\/v2\/tags?post=173047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}