{"id":131721,"date":"2022-08-07T08:41:00","date_gmt":"2022-08-07T06:41:00","guid":{"rendered":"https:\/\/brand24.com\/blog\/?p=131721"},"modified":"2026-05-04T13:31:09","modified_gmt":"2026-05-04T11:31:09","slug":"como-rastrear-compartilhamentos-sociais","status":"publish","type":"post","link":"https:\/\/brand24.com\/blog\/pt\/how-to-track-social-shares\/","title":{"rendered":"How to Track Social Shares: Step-by-Step Guide [2026]"},"content":{"rendered":"<p>Atualmente, existem <a href=\"https:\/\/backlinko.com\/social-media-users\" target=\"_blank\" rel=\"noopener nofollow\" title=\"\">5,79 bilh\u00f5es de usu\u00e1rios de m\u00eddias sociais<\/a> em todo o mundo. Com os gastos com an\u00fancios sociais atingindo $276 bilh\u00f5es, entender exatamente onde e como o seu conte\u00fado se espalha \u00e9 a diferen\u00e7a entre campanhas que crescem e or\u00e7amentos que desaparecem.<\/p>\n\n\n<style>.acf-key-takeaways__heading{padding:22px 30px 20px;margin:0;font-weight:600 !important;display:inline-flex;align-items:center;gap:1.1875rem;border:1px solid #c3e1d2;border-bottom:none;border-top-left-radius:1.25rem;border-top-right-radius:1.25rem}@media(min-width: 768px){.acf-key-takeaways__heading{padding:22px 40px 20px;gap:1.4375rem}}.acf-key-takeaways__icon{width:1.625rem;height:1.625rem;background-color:#9cbfaf;border-radius:50%;display:flex;align-items:center;justify-content:center}.acf-key-takeaways__list{border:1px solid #c3e1d2;border-top-right-radius:1.25rem;border-bottom-right-radius:1.25rem;border-bottom-left-radius:1.25rem;margin:0;padding:0;list-style:none;overflow:hidden}.acf-key-takeaways__item{padding:28px 34px 28px 61px;background-color:#e8f4ee;margin:0;border-bottom:1px solid #c3e1d2;position:relative}@media(min-width: 768px){.acf-key-takeaways__item{padding:28px 54px 28px 81px}}.acf-key-takeaways__item::before{content:\"\";position:absolute;top:35px;left:28px;width:.75rem;height:.75rem;background-color:#9cbfaf;border-radius:50%}@media(min-width: 768px){.acf-key-takeaways__item::before{top:39px;left:40px}}.acf-key-takeaways__item:nth-child(even){background-color:#dfefe7}.acf-key-takeaways__item:last-child{border-bottom:none}.acf-key-takeaways__title{font-weight:600 !important;margin-bottom:.625rem}.acf-key-takeaways__text{font-family:\"Inter\",sans-serif;font-size:16px;line-height:26px;margin:0}@media(min-width: 768px){.acf-key-takeaways__text{font-size:18px;line-height:30px}}.single-post-content__content .acf-key-takeaways__heading{font-family:\"Inter\",sans-serif;font-size:16px;line-height:26px}@media(min-width: 768px){.single-post-content__content .acf-key-takeaways__heading{font-size:18px;line-height:30px}}.single-post-content__content .acf-key-takeaways__title{font-family:\"Inter\",sans-serif;font-size:16px;line-height:26px}@media(min-width: 768px){.single-post-content__content .acf-key-takeaways__title{font-size:18px;line-height:30px}}.single-post-content__content p.acf-key-takeaways__text{line-height:1.875rem}@media(max-width: 768px){.single-post-content__content p.acf-key-takeaways__text{font-size:1rem !important}}<\/style>    <div class=\"acf-key-takeaways\">\n        <p class=\"acf-key-takeaways__heading\">\n            <span class=\"acf-key-takeaways__icon\">\n                <svg width=\"10\" height=\"12\" viewbox=\"0 0 10 12\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                    <path d=\"M8.41177 0C8.8341 0 9.17647 0.34237 9.17647 0.764706V11.0882C9.17647 11.3821 9.00815 11.6501                8.74334 11.7775C8.47839 11.9049 8.16337 11.8693 7.93382 11.6857L4.58824 9.00919L1.24265 11.6857C1.01311                11.8693 0.698079 11.9049 0.433134 11.7775C0.168324 11.6501 0 11.3821 0 11.0882V0.764706C0 0.561893                0.0806248 0.367445 0.224035 0.224035C0.367445 0.0806248 0.561893 0 0.764706 0H8.41177ZM1.52941                9.49609L4.11029 7.43199C4.38958 7.20856 4.78689 7.20856 5.06618 7.43199L7.64706                9.49609V1.52941H1.52941V9.49609Z\" fill=\"black\" \/>\n                <\/svg>\n            <\/span>\n            Principais conclus\u00f5es        <\/p>\n        <ul class=\"acf-key-takeaways__list\">\n                            <li class=\"acf-key-takeaways__item\">\n                    <p class=\"acf-key-takeaways__title\">Os compartilhamentos sociais divulgam ativamente seu conte\u00fado. <\/p>\n                    <p class=\"acf-key-takeaways__text\">Diferentemente de curtidas ou coment\u00e1rios, os compartilhamentos colocam seus posts de blog, v\u00eddeos ou p\u00e1ginas de produtos na frente de novos p\u00fablicos.<\/p>\n                <\/li>\n                            <li class=\"acf-key-takeaways__item\">\n                    <p class=\"acf-key-takeaways__title\">O rastreamento de compartilhamentos mostra qual conte\u00fado realmente circula. <\/p>\n                    <p class=\"acf-key-takeaways__text\">Isso ajuda voc\u00ea a ver quais t\u00f3picos, formatos e campanhas as pessoas querem repassar.<\/p>\n                <\/li>\n                            <li class=\"acf-key-takeaways__item\">\n                    <p class=\"acf-key-takeaways__title\">Hashtags e UTMs facilitam o rastreamento. <\/p>\n                    <p class=\"acf-key-takeaways__text\">Use uma hashtag de campanha exclusiva para mentions p\u00fablicos e links UTM para medir o tr\u00e1fego social no GA4.<\/p>\n                <\/li>\n                            <li class=\"acf-key-takeaways__item\">\n                    <p class=\"acf-key-takeaways__title\">Os dados de compartilhamento social devem levar \u00e0 a\u00e7\u00e3o. <\/p>\n                    <p class=\"acf-key-takeaways__text\">Reaja a mentions, amplifique o conte\u00fado viral, responda a conversas negativas e use insights para aprimorar campanhas futuras.<\/p>\n                <\/li>\n                    <\/ul>\n    <\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"whyshouldyoutracsocialshares\">O que s\u00e3o compartilhamentos sociais?<\/h2>\n\n\n\n<p class=\"has-background\" style=\"background-color:#e8f4ee\">A <strong>compartilhamento social<\/strong> acontece quando algu\u00e9m compartilha seu conte\u00fado - uma postagem de blog, p\u00e1gina de produto, v\u00eddeo ou artigo - do seu site para o pr\u00f3prio perfil de m\u00eddia social. <\/p>\n\n\n\n<p>Cada compartilhamento amplia o alcance org\u00e2nico do seu conte\u00fado para um p\u00fablico totalmente novo, sem nenhuma promo\u00e7\u00e3o paga.<\/p>\n\n\n\n<p>Os compartilhamentos sociais s\u00e3o diferentes de curtidas ou coment\u00e1rios: eles distribuem ativamente seu conte\u00fado, criando um efeito multiplicador na visibilidade da sua marca.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"why-track-social-shares\">Por que rastrear compartilhamentos sociais?<\/h2>\n\n\n\n<p>A m\u00eddia social se move rapidamente. As crises nas m\u00eddias sociais se espalham <a href=\"https:\/\/improvado.io\/blog\/social-media-monitoring-trends\" target=\"_blank\" rel=\"noopener nofollow\" title=\"1.200% mais r\u00e1pido\">1.200% mais r\u00e1pido<\/a> do que as not\u00edcias tradicionais, e 79% dos clientes esperam uma resposta da marca em 24 horas. Sem rastreamento, voc\u00ea est\u00e1 voando \u00e0s cegas.<\/p>\n\n\n\n<p>Veja o que o rastreamento de compartilhamentos sociais oferece a voc\u00ea:<\/p>\n\n\n<style>.acf-tools-table{border:1px solid #d4e5dc;border-radius:16px;overflow:hidden;overflow-x:auto}.acf-tools-table__table{width:100%;min-width:582px;border-collapse:collapse}.acf-tools-table__row:last-child td{border-bottom:none}.acf-tools-table__row:nth-child(even){background-color:#e8f4ee}.acf-tools-table__cell{padding:14px 20px;font-size:.875rem;line-height:1.125rem;border-bottom:1px solid #d4e5dc;border-right:1px solid #d4e5dc}.acf-tools-table__cell p{font-size:.875rem !important;line-height:1.125rem;margin-bottom:0}.acf-tools-table__cell:last-child{border-right:none}.acf-tools-table__cell--header{font-size:1rem;line-height:1.875rem;font-weight:700}@media(max-width: 768px){.acf-tools-table__cell--header{font-size:.875rem !important;line-height:1.125rem !important}}.acf-tools-table__cell--center{padding-left:70px}.acf-tools-table__cell strong{font-weight:700}.acf-tools-table__number{display:inline-flex;align-items:center;justify-content:center;width:32px;height:32px;border-radius:16px;background-color:#cbe7d9;font-size:.875rem;line-height:1em;font-weight:700}.acf-tools-table__logo{max-width:91px;margin-bottom:8px}.acf-tools-table__link{font-weight:400 !important;text-decoration:underline !important}.acf-tools-table__link:hover{text-decoration:none !important}.acf-tools-table__wrapper{display:flex;align-items:center;gap:17px}<\/style><div class=\"acf-tools-table\">\n    <table class=\"acf-tools-table__table\">\n        <thead class=\"acf-tools-table__thead\">\n            <tr class=\"acf-tools-table__row acf-tools-table__row--header\">\n                                    <th class=\"acf-tools-table__cell acf-tools-table__cell--header  acf-tools-table__cell--center\">\n                        A\u00e7\u00e3o                    <\/th>\n                                    <th class=\"acf-tools-table__cell acf-tools-table__cell--header\">\n                        Benef\u00edcio                    <\/th>\n                            <\/tr>\n        <\/thead>\n        <tbody class=\"acf-tools-table__tbody\">\n                    <tr class=\"acf-tools-table__row\">\n                                    <td class=\"acf-tools-table__cell\">\n                        <div class=\"acf-tools-table__wrapper\">\n                                                        <div class=\"acf-tools-table__number\">1<\/div>\n                                                                                        <p><!-- wp:list --><\/p>\n<p><strong>Visibilidade em tempo real do desempenho do conte\u00fado<\/strong><\/p>\n<p><!-- \/wp:list --> <!-- wp:paragraph --><\/p>\n<p>&nbsp;<\/p>\n<!-- \/wp:paragraph -->                                                    <\/div>\n                    <\/td>\n                                    <td class=\"acf-tools-table__cell\">\n                        <div class=\"acf-tools-table__wrapper\">\n                                                                                        <p>Voc\u00ea ver\u00e1 quais publica\u00e7\u00f5es geram mais compartilhamentos, em quais plataformas e por quais segmentos de p\u00fablico. Isso o ajudar\u00e1 a duplicar os formatos que funcionam.<\/p>\n                                                    <\/div>\n                    <\/td>\n                            <\/tr>\n                    <tr class=\"acf-tools-table__row\">\n                                    <td class=\"acf-tools-table__cell\">\n                        <div class=\"acf-tools-table__wrapper\">\n                                                        <div class=\"acf-tools-table__number\">2<\/div>\n                                                                                        <p><!-- wp:paragraph --><\/p>\n<p><strong>Informa\u00e7\u00f5es sobre o p\u00fablico e o sentimento<\/strong><\/p>\n<!-- \/wp:paragraph -->                                                    <\/div>\n                    <\/td>\n                                    <td class=\"acf-tools-table__cell\">\n                        <div class=\"acf-tools-table__wrapper\">\n                                                                                        <p>As m\u00e9tricas de engajamento - curtidas, coment\u00e1rios, compartilhamentos e taxas de engajamento - ajudam a avaliar a intera\u00e7\u00e3o do p\u00fablico e a resson\u00e2ncia do conte\u00fado. Os compartilhamentos, em particular, indicam um interesse forte o suficiente para recomendar ativamente seu conte\u00fado a outras pessoas.<\/p>\n                                                    <\/div>\n                    <\/td>\n                            <\/tr>\n                    <tr class=\"acf-tools-table__row\">\n                                    <td class=\"acf-tools-table__cell\">\n                        <div class=\"acf-tools-table__wrapper\">\n                                                        <div class=\"acf-tools-table__number\">3<\/div>\n                                                                                        <p><!-- wp:paragraph --><\/p>\n<p><strong>Medi\u00e7\u00e3o do ROI da campanha<\/strong><\/p>\n<!-- \/wp:paragraph -->                                                    <\/div>\n                    <\/td>\n                                    <td class=\"acf-tools-table__cell\">\n                        <div class=\"acf-tools-table__wrapper\">\n                                                                                        <p>Vincular as atividades de m\u00eddia social ao tr\u00e1fego do site, leads, vendas e retorno geral sobre o investimento usando m\u00e9tricas como taxas de cliques e taxas de convers\u00e3o \u00e9 muito mais f\u00e1cil quando os compartilhamentos est\u00e3o vinculados a par\u00e2metros UTM.<\/p>\n                                                    <\/div>\n                    <\/td>\n                            <\/tr>\n                    <tr class=\"acf-tools-table__row\">\n                                    <td class=\"acf-tools-table__cell\">\n                        <div class=\"acf-tools-table__wrapper\">\n                                                        <div class=\"acf-tools-table__number\">4<\/div>\n                                                                                        <p><!-- wp:paragraph --><\/p>\n<p><strong>Detec\u00e7\u00e3o de crises<\/strong><\/p>\n<!-- \/wp:paragraph -->                                                    <\/div>\n                    <\/td>\n                                    <td class=\"acf-tools-table__cell\">\n                        <div class=\"acf-tools-table__wrapper\">\n                                                                                        <p>Um pico repentino de compartilhamentos negativos ou mentions pode sinalizar uma crise de RP em forma\u00e7\u00e3o - o rastreamento permite que voc\u00ea reaja antes que o dano se espalhe.<\/p>\n                                                    <\/div>\n                    <\/td>\n                            <\/tr>\n                    <tr class=\"acf-tools-table__row\">\n                                    <td class=\"acf-tools-table__cell\">\n                        <div class=\"acf-tools-table__wrapper\">\n                                                        <div class=\"acf-tools-table__number\">5<\/div>\n                                                                                        <p><strong>Benchmarking competitivo<\/strong><\/p>\n                                                    <\/div>\n                    <\/td>\n                                    <td class=\"acf-tools-table__cell\">\n                        <div class=\"acf-tools-table__wrapper\">\n                                                                                        <p>Os recursos de monitoramento e benchmarking permitem que as marcas entendam sua parcela de voz e como est\u00e3o crescendo em rela\u00e7\u00e3o aos concorrentes.<\/p>\n                                                    <\/div>\n                    <\/td>\n                            <\/tr>\n                <\/tbody>\n    <\/table>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"howdoyoutracksocialshares\">Como rastrear compartilhamentos sociais?<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Etapa 1: Escolha uma hashtag de campanha dedicada<\/h3>\n\n\n\n<p>Antes de lan\u00e7ar qualquer campanha, crie uma hashtag exclusiva e memor\u00e1vel. Isso facilita muito o rastreamento em todas as plataformas.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Para campanhas de reconhecimento da marca:<\/strong> Use o nome de sua empresa ou o nome do produto (por exemplo, #YourBrandPL)<\/li>\n\n\n\n<li><strong>Para campanhas espec\u00edficas:<\/strong> Crie uma hashtag espec\u00edfica para a campanha (por exemplo, #BrandSummerSale2026)<\/li>\n<\/ul>\n\n\n\n<p>Uma hashtag de campanha centraliza todos os mentions p\u00fablicos do seu conte\u00fado, facilitando o rastreamento de compartilhamentos, alcance e sentimento em um \u00fanico painel.<\/p>\n\n\n\n<p><strong>Dica:<\/strong> Se estiver executando uma campanha maior, monitore cada hashtag da campanha separadamente. Isso facilita a compara\u00e7\u00e3o do desempenho, a identifica\u00e7\u00e3o do conte\u00fado mais forte e o relat\u00f3rio dos resultados com clareza ap\u00f3s o t\u00e9rmino da campanha.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Etapa 2: Adicione par\u00e2metros UTM a todos os links que voc\u00ea compartilha<\/h3>\n\n\n\n<p>O rastreamento UTM \u00e9 um dos m\u00e9todos mais confi\u00e1veis para medir o impacto dos compartilhamentos sociais em seu site. Adicione c\u00f3digos UTM a todos os URLs compartilhados nas m\u00eddias sociais e, em seguida, monitore-os no GA4.<\/p>\n\n\n\n<p class=\"has-background\" style=\"background-color:#e8f4ee\">Exemplo de estrutura UTM: <code>https:\/\/yoursite.pl\/blog\/post?utm_source=instagram&amp;utm_medium=social&amp;utm_campaign=spring2026<\/code><\/p>\n\n\n\n<p>O rastreamento de UTM adiciona um c\u00f3digo curto a todos os URLs que voc\u00ea compartilha nas redes sociais - como postagens de blog ou links de produtos - para que voc\u00ea possa ver no Google Analytics exatamente quanto tr\u00e1fego cada canal, postagem ou an\u00fancio envia para o seu site. <\/p>\n\n\n\n<p>Use a ferramenta gratuita do Google <a href=\"https:\/\/ga-dev-tools.google\/campaign-url-builder\/\" target=\"_blank\" rel=\"noopener nofollow\" title=\"\">Criador de URL de campanha<\/a> para gerar links sem erros de digita\u00e7\u00e3o. Os cinco par\u00e2metros mais importantes para as redes sociais s\u00e3o:<\/p>\n\n\n<div class=\"acf-tools-table\">\n    <table class=\"acf-tools-table__table\">\n        <thead class=\"acf-tools-table__thead\">\n            <tr class=\"acf-tools-table__row acf-tools-table__row--header\">\n                                    <th class=\"acf-tools-table__cell acf-tools-table__cell--header  acf-tools-table__cell--center\">\n                        Par\u00e2metro                    <\/th>\n                                    <th class=\"acf-tools-table__cell acf-tools-table__cell--header\">\n                        O que ele captura                    <\/th>\n                                    <th class=\"acf-tools-table__cell acf-tools-table__cell--header\">\n                        Exemplo de valor                    <\/th>\n                            <\/tr>\n        <\/thead>\n        <tbody class=\"acf-tools-table__tbody\">\n                    <tr class=\"acf-tools-table__row\">\n                                    <td class=\"acf-tools-table__cell\">\n                        <div class=\"acf-tools-table__wrapper\">\n                                                        <div class=\"acf-tools-table__number\">1<\/div>\n                                                                                        <p>utm_source<\/p>\n                                                    <\/div>\n                    <\/td>\n                                    <td class=\"acf-tools-table__cell\">\n                        <div class=\"acf-tools-table__wrapper\">\n                                                                                        <p>Qual plataforma enviou o tr\u00e1fego<\/p>\n                                                    <\/div>\n                    <\/td>\n                                    <td class=\"acf-tools-table__cell\">\n                        <div class=\"acf-tools-table__wrapper\">\n                                                                                        <p>instagram<\/p>\n                                                    <\/div>\n                    <\/td>\n                            <\/tr>\n                    <tr class=\"acf-tools-table__row\">\n                                    <td class=\"acf-tools-table__cell\">\n                        <div class=\"acf-tools-table__wrapper\">\n                                                        <div class=\"acf-tools-table__number\">2<\/div>\n                                                                                        <p>utm_medium<\/p>\n                                                    <\/div>\n                    <\/td>\n                                    <td class=\"acf-tools-table__cell\">\n                        <div class=\"acf-tools-table__wrapper\">\n                                                                                        <p>O tipo de canal<\/p>\n                                                    <\/div>\n                    <\/td>\n                                    <td class=\"acf-tools-table__cell\">\n                        <div class=\"acf-tools-table__wrapper\">\n                                                                                        <p>social<\/p>\n                                                    <\/div>\n                    <\/td>\n                            <\/tr>\n                    <tr class=\"acf-tools-table__row\">\n                                    <td class=\"acf-tools-table__cell\">\n                        <div class=\"acf-tools-table__wrapper\">\n                                                        <div class=\"acf-tools-table__number\">3<\/div>\n                                                                                        <p>utm_campaign<\/p>\n                                                    <\/div>\n                    <\/td>\n                                    <td class=\"acf-tools-table__cell\">\n                        <div class=\"acf-tools-table__wrapper\">\n                                                                                        <p>O nome da campanha<\/p>\n                                                    <\/div>\n                    <\/td>\n                                    <td class=\"acf-tools-table__cell\">\n                        <div class=\"acf-tools-table__wrapper\">\n                                                                                        <p>primavera2026<\/p>\n                                                    <\/div>\n                    <\/td>\n                            <\/tr>\n                    <tr class=\"acf-tools-table__row\">\n                                    <td class=\"acf-tools-table__cell\">\n                        <div class=\"acf-tools-table__wrapper\">\n                                                        <div class=\"acf-tools-table__number\">4<\/div>\n                                                                                        <p>utm_content<\/p>\n                                                    <\/div>\n                    <\/td>\n                                    <td class=\"acf-tools-table__cell\">\n                        <div class=\"acf-tools-table__wrapper\">\n                                                                                        <p>Qual post ou criativo espec\u00edfico<\/p>\n                                                    <\/div>\n                    <\/td>\n                                    <td class=\"acf-tools-table__cell\">\n                        <div class=\"acf-tools-table__wrapper\">\n                                                                                        <p>carrossel_dia3<\/p>\n                                                    <\/div>\n                    <\/td>\n                            <\/tr>\n                    <tr class=\"acf-tools-table__row\">\n                                    <td class=\"acf-tools-table__cell\">\n                        <div class=\"acf-tools-table__wrapper\">\n                                                        <div class=\"acf-tools-table__number\">5<\/div>\n                                                                                        <p>utm_term<\/p>\n                                                    <\/div>\n                    <\/td>\n                                    <td class=\"acf-tools-table__cell\">\n                        <div class=\"acf-tools-table__wrapper\">\n                                                                                        <p>Opcional - \u00fatil para redes sociais pagas para marcar o conjunto de an\u00fancios<\/p>\n                                                    <\/div>\n                    <\/td>\n                                    <td class=\"acf-tools-table__cell\">\n                        <div class=\"acf-tools-table__wrapper\">\n                                                                                        <p>redirecionamento<\/p>\n                                                    <\/div>\n                    <\/td>\n                            <\/tr>\n                <\/tbody>\n    <\/table>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Localizando os dados no GA4<\/h3>\n\n\n\n<p>Ir para <strong>Relat\u00f3rios \u2192 Aquisi\u00e7\u00e3o \u2192 Aquisi\u00e7\u00e3o de tr\u00e1fego<\/strong>. Altere a dimens\u00e3o prim\u00e1ria de <em>Grupo de canais padr\u00e3o da sess\u00e3o<\/em> para <strong>Campanha de sess\u00e3o<\/strong> para ver seus valores exatos de UTM. Clique em qualquer nome de campanha para filtrar o relat\u00f3rio completo para essa campanha e ver as sess\u00f5es, a taxa de engajamento e as convers\u00f5es lado a lado.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Quando uma campanha supera a outra<\/h3>\n\n\n\n<p>Dica: N\u00e3o espere at\u00e9 o fim. Verifique o <code>utm_content<\/code> valores dentro da campanha vencedora para identificar se o formato, o texto ou o tempo de postagem est\u00e1 fazendo a diferen\u00e7a e, em seguida, mude as postagens restantes ou o or\u00e7amento pago para o que estiver funcionando. <\/p>\n\n\n\n<p>Ap\u00f3s o t\u00e9rmino da campanha, observe a taxa de engajamento e a taxa de convers\u00e3o vencedoras como a linha de base que sua pr\u00f3xima campanha precisa superar.<\/p>\n\n\n\n<p>Um aspecto a ser observado: altas contagens de sess\u00f5es significam pouco se a taxa de engajamento for baixa. Uma campanha que gera 500 sess\u00f5es com 70% de engajamento \u00e9 sempre melhor do que 2.000 sess\u00f5es com 15%.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Etapa 3: Configure um projeto de monitoramento de m\u00eddia social<\/h3>\n\n\n\n<p>Cada <a href=\"https:\/\/brand24.com\/blog\/pt\/o-que-e-monitoramento-e-analise-de-midia\/\" target=\"_blank\" rel=\"noopener\" title=\"\">monitoramento de m\u00eddia<\/a> O plano come\u00e7a com a cria\u00e7\u00e3o do projeto. <\/p>\n\n\n\n<p>Em Brand24, insira as hashtags e palavras-chave que voc\u00ea deseja rastrear na configura\u00e7\u00e3o do projeto.<\/p>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04017e5fb68&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04017e5fb68\" class=\"wp-block-image aligncenter size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1140\" height=\"392\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/brand24.com\/blog\/app\/uploads\/2022\/08\/image-1140x392.png\" alt=\"\" class=\"wp-image-183585\" srcset=\"https:\/\/brand24.com\/blog\/app\/uploads\/2022\/08\/image-1140x392.png 1140w, https:\/\/brand24.com\/blog\/app\/uploads\/2022\/08\/image-1536x528.png 1536w, https:\/\/brand24.com\/blog\/app\/uploads\/2022\/08\/image-18x6.png 18w, https:\/\/brand24.com\/blog\/app\/uploads\/2022\/08\/image-300x103.png 300w, https:\/\/brand24.com\/blog\/app\/uploads\/2022\/08\/image-248x85.png 248w, https:\/\/brand24.com\/blog\/app\/uploads\/2022\/08\/image-90x31.png 90w, https:\/\/brand24.com\/blog\/app\/uploads\/2022\/08\/image.png 1300w\" sizes=\"auto, (max-width: 1140px) 100vw, 1140px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ampliar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\">Configura\u00e7\u00e3o do projeto no Brand24<\/figcaption><\/figure>\n\n\n\n<p>Algumas dicas aqui: <\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Configurar <strong>projetos separados<\/strong>Para obter mais informa\u00e7\u00f5es sobre a hashtag de sua marca, consulte: uma para a hashtag geral de sua marca e outra para hashtags espec\u00edficas da campanha. Isso mant\u00e9m seus dados limpos e facilita muito a gera\u00e7\u00e3o de relat\u00f3rios.<\/li>\n\n\n\n<li>Selecione o <strong>idioma<\/strong> que voc\u00ea gostaria de monitorar. Isso ajuda a minimizar os resultados de spam em seu painel, portanto, vale a pena configur\u00e1-lo adequadamente.<\/li>\n<\/ul>\n\n\n\n<p>A partir desse momento, o Brand24 come\u00e7ar\u00e1 a coletar todos os mentions dispon\u00edveis publicamente que contenham sua palavra-chave em mais de 25 milh\u00f5es de fontes em tempo real. <\/p>\n\n\n<style>.acf-simple-cta{border-radius:20px;background-color:#fff;max-width:640px;margin:auto;margin-bottom:30px;padding:30px 15px}@media(min-width: 768px){.acf-simple-cta{padding:48px 62px 46px 62px}}.acf-simple-cta__title{font-size:22px !important;font-weight:600;line-height:23px !important;color:#000;text-align:center;margin-top:10px}@media(min-width: 576px){.acf-simple-cta__title{max-width:280px;text-align:left;margin-top:0}}.acf-simple-cta__title span{color:#00ef88}.acf-simple-cta__row{text-align:center}@media(min-width: 768px){.acf-simple-cta__row{display:flex;align-items:center;justify-content:space-between;gap:10px;text-align:left}}.acf-simple-cta__content{margin-bottom:20px;text-align:center}@media(min-width: 576px){.acf-simple-cta__content{display:flex;justify-content:center;align-items:center;gap:10px;width:100%;max-width:100%}}@media(min-width: 768px){.acf-simple-cta__content{align-items:center;justify-content:space-between;margin-bottom:0;max-width:66%}}.acf-simple-cta__btn{flex-shrink:0;border-radius:30px;padding:11px 21px;font-size:14px;line-height:18px;font-weight:500 !important;color:#000 !important;letter-spacing:-0.14px;background-color:#00ef88;border:none;transition:background-color .3s ease,opacity .3s ease;display:inline-block}.acf-simple-cta__btn:hover{background-color:#4bffae;text-decoration:none;opacity:.9}.acf-simple-cta__btn:focus-visible{outline:2px solid #00ef88}.acf-simple-cta--primary{background-color:#00ef88}.acf-simple-cta--primary .acf-simple-cta__title{color:#fff}.acf-simple-cta--primary .acf-simple-cta__title span{color:#000}.acf-simple-cta--primary .acf-simple-cta__btn{background-color:#000;color:#fff !important;transition:background-color .3s ease-in-out}.acf-simple-cta--primary .acf-simple-cta__btn:hover{background-color:#171717}.acf-simple-cta--violet{background-color:#000}.acf-simple-cta--violet .acf-simple-cta__title{color:#fff}.acf-simple-cta--violet .acf-simple-cta__title span{color:#bf00ff}.acf-simple-cta--violet .acf-simple-cta__btn{background-color:#bf00ff;color:#000 !important;transition:background-color .3s ease-in-out}.acf-simple-cta--violet .acf-simple-cta__btn:hover{background-color:#bf00ff}.acf-simple-cta--small{padding:20px 15px}@media(min-width: 768px){.acf-simple-cta--small{padding:33px 45px 31px 56px}}.acf-simple-cta--no-icon .acf-simple-cta__content{max-width:100%;width:auto}.acf-simple-cta--no-icon .acf-simple-cta__title{max-width:100%}@media(min-width: 768px){.acf-simple-cta--no-icon.acf-simple-cta--small .acf-simple-cta__content{max-width:55%}}<\/style>\n<div class=\"acf-simple-cta acf-simple-cta--default acf-simple-cta--no-icon\">\n    <div class=\"acf-simple-cta__wrapper\">\n        <div class=\"acf-simple-cta__row\">\n            <div class=\"acf-simple-cta__content\">\n                                                    <div class=\"acf-simple-cta__title\">Acompanhe os compartilhamentos sociais!<\/div>\n                            <\/div>\n                            <a href=\"https:\/\/app.brand24.com\/user\/register-account\/?custom_form=55\" class=\"acf-simple-cta__btn\" target=\"_blank\">Inicie o teste!<\/a>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Etapa 4: Analise seu painel de controle<\/h3>\n\n\n\n<p>O Brand24 coleta todos os mentions e os exibe em um painel limpo e filtr\u00e1vel. Voc\u00ea pode filtrar os resultados por autor, dom\u00ednio, data ou fonte e salvar esses filtros para uso futuro.<\/p>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04017e60773&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04017e60773\" class=\"wp-block-image aligncenter size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1140\" height=\"651\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/brand24.com\/blog\/app\/uploads\/2022\/08\/image-1-1140x651.png\" alt=\"\" class=\"wp-image-183586\" srcset=\"https:\/\/brand24.com\/blog\/app\/uploads\/2022\/08\/image-1-1140x651.png 1140w, https:\/\/brand24.com\/blog\/app\/uploads\/2022\/08\/image-1-1536x878.png 1536w, https:\/\/brand24.com\/blog\/app\/uploads\/2022\/08\/image-1-2048x1170.png 2048w, https:\/\/brand24.com\/blog\/app\/uploads\/2022\/08\/image-1-18x10.png 18w, https:\/\/brand24.com\/blog\/app\/uploads\/2022\/08\/image-1-300x171.png 300w, https:\/\/brand24.com\/blog\/app\/uploads\/2022\/08\/image-1-248x142.png 248w, https:\/\/brand24.com\/blog\/app\/uploads\/2022\/08\/image-1-90x51.png 90w, https:\/\/brand24.com\/blog\/app\/uploads\/2022\/08\/image-1-scaled.png 1300w\" sizes=\"auto, (max-width: 1140px) 100vw, 1140px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ampliar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\">Guia An\u00e1lise no Brand24<\/figcaption><\/figure>\n\n\n\n<p>No <strong>Guia An\u00e1lise<\/strong>, voc\u00ea encontrar\u00e1 as m\u00e9tricas que realmente importam para suas campanhas:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Alcance estimado de m\u00eddia social (ESMR)<\/strong> informa quantas pessoas poderiam ter visto seu conte\u00fado com hashtag. Quanto mais pessoas virem suas publica\u00e7\u00f5es, maior ser\u00e1 o reconhecimento de sua marca - esse \u00e9 o n\u00famero mais importante a ser observado.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Intera\u00e7\u00f5es<\/strong> (compartilhamentos, curtidas, coment\u00e1rios) medem o grau de envolvimento real do seu p\u00fablico. Quanto mais engajamento seu conte\u00fado gerar, mais pessoas o ver\u00e3o - \u00e9 assim que funcionam os algoritmos das redes sociais.<\/li>\n<\/ul>\n\n\n<style>.acf-quote-square{padding:40px 30px;background-color:#e8f4ee;border-radius:20px;max-width:640px;margin-left:auto;margin-right:auto}@media(min-width: 768px){.acf-quote-square{padding:62px 91px}}.acf-quote-square__icon{margin-bottom:20px}@media(min-width: 768px){.acf-quote-square__icon{margin-bottom:36px}}.acf-quote-square__quote{font-family:\"Inter\",sans-serif;font-size:16px;line-height:26px;margin-bottom:20px}@media(min-width: 768px){.acf-quote-square__quote{font-size:18px;line-height:30px}}@media(min-width: 576px){.acf-quote-square__quote{margin-bottom:44px}}.acf-quote-square__quote:last-child{margin-bottom:0}@media(min-width: 576px){.acf-quote-square__row{display:flex;gap:25px;align-items:center}}.acf-quote-square__author-image{width:60px;height:60px;border-radius:50%;overflow:hidden;flex-shrink:0;margin-bottom:10px}@media(min-width: 768px){.acf-quote-square__author-image{width:80px;height:80px;margin-bottom:0}}.acf-quote-square__author-image img{width:100%;height:100%;object-fit:cover}.acf-quote-square__author-name{font-size:16px;line-height:140%;font-weight:700;margin-bottom:4px}@media(min-width: 768px){.acf-quote-square__author-name{font-size:18px;line-height:140%}}.acf-quote-square__author-linkedin{display:inline-block;position:relative;top:-4px;margin-left:8px}.acf-quote-square__author-position{font-size:16px;line-height:100%}@media(min-width: 768px){.acf-quote-square__author-position{font-size:18px}}.acf-quote-square--primary{background-color:#00ef88}.acf-quote-square--primary .acf-quote-square__quote,.acf-quote-square--primary .acf-quote-square__author-name,.acf-quote-square--primary .acf-quote-square__author-position{color:#000}.acf-quote-square--primary .acf-quote-square__icon svg path{fill:#000}.acf-quote-square--violet{background-color:#000}.acf-quote-square--violet .acf-quote-square__quote,.acf-quote-square--violet .acf-quote-square__author-name,.acf-quote-square--violet .acf-quote-square__author-position{color:#fff}.acf-quote-square--violet .acf-quote-square__icon svg path{fill:#bf00ff}<\/style><div class=\"acf-quote-square acf-quote-square--default\">\n            <div class=\"acf-quote-square__icon\">\n            <svg width=\"53\" height=\"46\" viewbox=\"0 0 53 46\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path d=\"M52.9064 22.6459H41.2236C41.4114 25.3738 42.318 27.7372 43.9479 29.7374C45.5763 31.7361 48.5625 33.7452 52.9064 35.7631L47.5716 45.7405C40.6068 42.676 35.6846 39.145 32.8005 35.1461C29.9178 31.1471 28.4758 25.6912 28.4758 18.7783V0H52.9079V22.6459H52.9064ZM24.4321 22.6459H12.7492C12.9371 25.3738 13.8437 27.7372 15.4736 29.7374C17.102 31.7361 20.0882 33.7452 24.4321 35.7631L19.0972 45.7405C12.1325 42.676 7.21028 39.145 4.32617 35.1461C1.44206 31.1471 0 25.6912 0 18.7783V0H24.4321V22.6459Z\" fill=\"#00EF88\"\/>\n<\/svg>        <\/div>\n                <div class=\"acf-quote-square__quote\">O uso do AI Insights do Brand24 revolucionou minha abordagem como gerente de m\u00eddia social. Ele identifica com precis\u00e3o os picos de engajamento, permitindo que eu responda em tempo real com conte\u00fado e estrat\u00e9gias direcionados, o que acaba gerando maior engajamento e fidelidade \u00e0 marca.<\/div>\n        <div class=\"acf-quote-square__row\">\n                <div class=\"acf-quote-square__author-content\">\n                            <div class=\"acf-quote-square__author-name\">\n                    Haily Moulton                                            <a class=\"acf-quote-square__author-linkedin\" href=\"https:\/\/www.linkedin.com\/in\/hailymoulton\/\" target=\"_blank\"><svg width=\"20\" height=\"22\" viewbox=\"0 0 20 22\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<g clip-path=\"url(#clip0_2734_535)\">\n<mask id=\"mask0_2734_535\" style=\"mask-type:luminance\" maskunits=\"userSpaceOnUse\" x=\"0\" y=\"0\" width=\"20\" height=\"22\">\n<path d=\"M20 0H0V21.1111H20V0Z\" fill=\"white\"\/>\n<\/mask>\n<g mask=\"url(#mask0_2734_535)\">\n<path d=\"M18.5195 0H1.47656C0.660156 0 0 0.680338 0 1.52149V19.5855C0 20.4267 0.660156 21.1111 1.47656 21.1111H18.5195C19.3359 21.1111 20 20.4267 20 19.5896V1.52149C20 0.680338 19.3359 0 18.5195 0ZM5.93359 17.9898H2.96484V7.91254H5.93359V17.9898ZM4.44922 6.53949C3.49609 6.53949 2.72656 5.72721 2.72656 4.72526C2.72656 3.7233 3.49609 2.91102 4.44922 2.91102C5.39844 2.91102 6.16797 3.7233 6.16797 4.72526C6.16797 5.7231 5.39844 6.53949 4.44922 6.53949ZM17.043 17.9898H14.0781V13.0913C14.0781 11.9245 14.0586 10.4195 12.5352 10.4195C10.9922 10.4195 10.7578 11.6936 10.7578 13.0089V17.9898H7.79688V7.91254H10.6406V9.28971H10.6797C11.0742 8.49805 12.043 7.66102 13.4844 7.66102C16.4883 7.66102 17.043 9.7474 17.043 12.4605V17.9898Z\" fill=\"#2058B7\"\/>\n<\/g>\n<\/g>\n<defs>\n<clippath id=\"clip0_2734_535\">\n<rect width=\"20\" height=\"21.1111\" fill=\"white\"\/>\n<\/clippath>\n<\/defs>\n<\/svg><\/a>\n                                    <\/div>\n                                        <div class=\"acf-quote-square__author-position\">Gerente de m\u00eddias sociais<\/div>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><a href=\"https:\/\/brand24.com\/blog\/pt\/analise-de-sentimento-de-midia-social\/\">An\u00e1lise de sentimento<\/a><\/strong> mostra se a conversa em torno de sua marca \u00e9 positiva, negativa ou neutra. Um alto alcance estimado combinado com um sentimento negativo predominante \u00e9 um sinal de alerta de um <a href=\"https:\/\/brand24.com\/blog\/pt\/gerenciamento-de-crises-nas-midias-sociais\/\">crise nas m\u00eddias sociais<\/a> - n\u00e3o \u00e9 uma m\u00e9trica de sucesso. \u00c9 por isso que voc\u00ea deve sempre acompanhar os compartilhamentos e o sentimento juntos.<\/li>\n<\/ul>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04017e61417&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04017e61417\" class=\"wp-block-image aligncenter size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1140\" height=\"345\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/brand24.com\/blog\/app\/uploads\/2022\/08\/image-2-1140x345.png\" alt=\"\" class=\"wp-image-183587\" srcset=\"https:\/\/brand24.com\/blog\/app\/uploads\/2022\/08\/image-2-1140x345.png 1140w, https:\/\/brand24.com\/blog\/app\/uploads\/2022\/08\/image-2-1536x465.png 1536w, https:\/\/brand24.com\/blog\/app\/uploads\/2022\/08\/image-2-2048x620.png 2048w, https:\/\/brand24.com\/blog\/app\/uploads\/2022\/08\/image-2-18x5.png 18w, https:\/\/brand24.com\/blog\/app\/uploads\/2022\/08\/image-2-300x91.png 300w, https:\/\/brand24.com\/blog\/app\/uploads\/2022\/08\/image-2-248x75.png 248w, https:\/\/brand24.com\/blog\/app\/uploads\/2022\/08\/image-2-90x27.png 90w, https:\/\/brand24.com\/blog\/app\/uploads\/2022\/08\/image-2-scaled.png 1300w\" sizes=\"auto, (max-width: 1140px) 100vw, 1140px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ampliar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\">An\u00e1lise de sentimento no Brand24<\/figcaption><\/figure>\n\n\n\n<p>Dica: voc\u00ea tamb\u00e9m pode monitorar os picos de volume do mention. Um salto repentino geralmente sinaliza um momento viral que merece ser ampliado ou um problema emergente que merece ser tratado rapidamente.<\/p>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04017e61c90&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04017e61c90\" class=\"wp-block-image aligncenter size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1140\" height=\"430\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/brand24.com\/blog\/app\/uploads\/2022\/08\/image-3-1140x430.png\" alt=\"\" class=\"wp-image-183588\" srcset=\"https:\/\/brand24.com\/blog\/app\/uploads\/2022\/08\/image-3-1140x430.png 1140w, https:\/\/brand24.com\/blog\/app\/uploads\/2022\/08\/image-3-1536x580.png 1536w, https:\/\/brand24.com\/blog\/app\/uploads\/2022\/08\/image-3-18x7.png 18w, https:\/\/brand24.com\/blog\/app\/uploads\/2022\/08\/image-3-300x113.png 300w, https:\/\/brand24.com\/blog\/app\/uploads\/2022\/08\/image-3-248x94.png 248w, https:\/\/brand24.com\/blog\/app\/uploads\/2022\/08\/image-3-90x34.png 90w, https:\/\/brand24.com\/blog\/app\/uploads\/2022\/08\/image-3.png 1300w\" sizes=\"auto, (max-width: 1140px) 100vw, 1140px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ampliar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\">Eventos de IA no Brand24 que explicam os picos de alcance e os mentions<\/figcaption><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Etapa 5: Reaja aos compartilhamentos sociais<\/h3>\n\n\n\n<p>O rastreamento de compartilhamentos sociais n\u00e3o se trata apenas de coletar dados - trata-se de agir com base neles. O Brand24 permite que voc\u00ea reaja rapidamente a todos os mentions sobre a sua marca, mesmo aqueles que aparecem fora dos seus canais de m\u00eddia.<\/p>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a04017e62535&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a04017e62535\" class=\"wp-block-image aligncenter size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1140\" height=\"381\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/brand24.com\/blog\/app\/uploads\/2022\/08\/image-4-1140x381.png\" alt=\"\" class=\"wp-image-183589\" srcset=\"https:\/\/brand24.com\/blog\/app\/uploads\/2022\/08\/image-4-1140x381.png 1140w, https:\/\/brand24.com\/blog\/app\/uploads\/2022\/08\/image-4-1536x513.png 1536w, https:\/\/brand24.com\/blog\/app\/uploads\/2022\/08\/image-4-18x6.png 18w, https:\/\/brand24.com\/blog\/app\/uploads\/2022\/08\/image-4-300x100.png 300w, https:\/\/brand24.com\/blog\/app\/uploads\/2022\/08\/image-4-248x83.png 248w, https:\/\/brand24.com\/blog\/app\/uploads\/2022\/08\/image-4-90x30.png 90w, https:\/\/brand24.com\/blog\/app\/uploads\/2022\/08\/image-4.png 1300w\" sizes=\"auto, (max-width: 1140px) 100vw, 1140px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ampliar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\">Mention em Brand24<\/figcaption><\/figure>\n\n\n\n<p>Agradecer aos usu\u00e1rios por mentions positivos e reconhecer publicamente os negativos constr\u00f3i sua presen\u00e7a on-line e posiciona sua marca como responsiva e confi\u00e1vel. <\/p>\n\n\n<div class=\"acf-quote-square acf-quote-square--default\">\n            <div class=\"acf-quote-square__icon\">\n            <svg width=\"53\" height=\"46\" viewbox=\"0 0 53 46\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path d=\"M52.9064 22.6459H41.2236C41.4114 25.3738 42.318 27.7372 43.9479 29.7374C45.5763 31.7361 48.5625 33.7452 52.9064 35.7631L47.5716 45.7405C40.6068 42.676 35.6846 39.145 32.8005 35.1461C29.9178 31.1471 28.4758 25.6912 28.4758 18.7783V0H52.9079V22.6459H52.9064ZM24.4321 22.6459H12.7492C12.9371 25.3738 13.8437 27.7372 15.4736 29.7374C17.102 31.7361 20.0882 33.7452 24.4321 35.7631L19.0972 45.7405C12.1325 42.676 7.21028 39.145 4.32617 35.1461C1.44206 31.1471 0 25.6912 0 18.7783V0H24.4321V22.6459Z\" fill=\"#00EF88\"\/>\n<\/svg>        <\/div>\n                <div class=\"acf-quote-square__quote\">O Brand24 tem sido uma ferramenta essencial para a parte do meu neg\u00f3cio que \u00e9 a organiza\u00e7\u00e3o de eventos. A coleta de dados para poss\u00edveis patrocinadores e a exibi\u00e7\u00e3o do engajamento em uma hashtag espec\u00edfica para meus eventos criam FOMO e me fornecem dados espec\u00edficos para meu p\u00fablico e incentivam a participa\u00e7\u00e3o.<\/div>\n        <div class=\"acf-quote-square__row\">\n                <div class=\"acf-quote-square__author-content\">\n                            <div class=\"acf-quote-square__author-name\">\n                    Samantha Kelly                                            <a class=\"acf-quote-square__author-linkedin\" href=\"https:\/\/www.linkedin.com\/in\/samanthakellymedia\/\" target=\"_blank\"><svg width=\"20\" height=\"22\" viewbox=\"0 0 20 22\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<g clip-path=\"url(#clip0_2734_535)\">\n<mask id=\"mask0_2734_535\" style=\"mask-type:luminance\" maskunits=\"userSpaceOnUse\" x=\"0\" y=\"0\" width=\"20\" height=\"22\">\n<path d=\"M20 0H0V21.1111H20V0Z\" fill=\"white\"\/>\n<\/mask>\n<g mask=\"url(#mask0_2734_535)\">\n<path d=\"M18.5195 0H1.47656C0.660156 0 0 0.680338 0 1.52149V19.5855C0 20.4267 0.660156 21.1111 1.47656 21.1111H18.5195C19.3359 21.1111 20 20.4267 20 19.5896V1.52149C20 0.680338 19.3359 0 18.5195 0ZM5.93359 17.9898H2.96484V7.91254H5.93359V17.9898ZM4.44922 6.53949C3.49609 6.53949 2.72656 5.72721 2.72656 4.72526C2.72656 3.7233 3.49609 2.91102 4.44922 2.91102C5.39844 2.91102 6.16797 3.7233 6.16797 4.72526C6.16797 5.7231 5.39844 6.53949 4.44922 6.53949ZM17.043 17.9898H14.0781V13.0913C14.0781 11.9245 14.0586 10.4195 12.5352 10.4195C10.9922 10.4195 10.7578 11.6936 10.7578 13.0089V17.9898H7.79688V7.91254H10.6406V9.28971H10.6797C11.0742 8.49805 12.043 7.66102 13.4844 7.66102C16.4883 7.66102 17.043 9.7474 17.043 12.4605V17.9898Z\" fill=\"#2058B7\"\/>\n<\/g>\n<\/g>\n<defs>\n<clippath id=\"clip0_2734_535\">\n<rect width=\"20\" height=\"21.1111\" fill=\"white\"\/>\n<\/clippath>\n<\/defs>\n<\/svg><\/a>\n                                    <\/div>\n                                <\/div>\n    <\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"real-results\"><strong>Resultados reais: Como a Mercedes-Benz monitorou os compartilhamentos sociais com o Brand24<\/strong><\/h2>\n\n\n\n<p>Um bom exemplo de rastreamento de compartilhamento social em a\u00e7\u00e3o \u00e9 o <strong>Campanha do Mercedes-Benz Classe T<\/strong> com a BBDO WWA.<\/p>\n\n\n\n<p>A campanha incentivou as pessoas a compartilharem momentos familiares emocionais e cotidianos on-line usando hashtags espec\u00edficas. A Mercedes-Benz usou o Brand24 para monitorar essas hashtags da campanha em tempo real, acompanhar como a conversa se espalhou e entender o sentimento por tr\u00e1s dos mentions.<\/p>\n\n\n\n<p>Em apenas duas semanas, a campanha gerou:<\/p>\n\n\n<div class=\"acf-tools-table\">\n    <table class=\"acf-tools-table__table\">\n        <thead class=\"acf-tools-table__thead\">\n            <tr class=\"acf-tools-table__row acf-tools-table__row--header\">\n                                    <th class=\"acf-tools-table__cell acf-tools-table__cell--header\">\n                        M\u00e9trico                    <\/th>\n                                    <th class=\"acf-tools-table__cell acf-tools-table__cell--header\">\n                        Resultado                    <\/th>\n                            <\/tr>\n        <\/thead>\n        <tbody class=\"acf-tools-table__tbody\">\n                    <tr class=\"acf-tools-table__row\">\n                                    <td class=\"acf-tools-table__cell\">\n                        <div class=\"acf-tools-table__wrapper\">\n                                                                                        <p class=\"p1\">Social mentions rastreado<\/p>\n<p>&nbsp;<\/p>\n                                                    <\/div>\n                    <\/td>\n                                    <td class=\"acf-tools-table__cell\">\n                        <div class=\"acf-tools-table__wrapper\">\n                                                                                        <p class=\"p1\">Quase 200.000<\/p>\n<p>&nbsp;<\/p>\n                                                    <\/div>\n                    <\/td>\n                            <\/tr>\n                    <tr class=\"acf-tools-table__row\">\n                                    <td class=\"acf-tools-table__cell\">\n                        <div class=\"acf-tools-table__wrapper\">\n                                                                                        <p class=\"p1\">Visualiza\u00e7\u00f5es no YouTube<\/p>\n<p>&nbsp;<\/p>\n                                                    <\/div>\n                    <\/td>\n                                    <td class=\"acf-tools-table__cell\">\n                        <div class=\"acf-tools-table__wrapper\">\n                                                                                        <p class=\"p1\">600,000<\/p>\n<p>&nbsp;<\/p>\n                                                    <\/div>\n                    <\/td>\n                            <\/tr>\n                    <tr class=\"acf-tools-table__row\">\n                                    <td class=\"acf-tools-table__cell\">\n                        <div class=\"acf-tools-table__wrapper\">\n                                                                                        <p class=\"p1\">Engajamento da p\u00e1gina de destino<\/p>\n<p>&nbsp;<\/p>\n                                                    <\/div>\n                    <\/td>\n                                    <td class=\"acf-tools-table__cell\">\n                        <div class=\"acf-tools-table__wrapper\">\n                                                                                        <p class=\"p1\">4x mais tempo gasto na p\u00e1gina<\/p>\n                                                    <\/div>\n                    <\/td>\n                            <\/tr>\n                <\/tbody>\n    <\/table>\n<\/div>\n\n\n\n<p>A principal conclus\u00e3o?<\/p>\n\n\n\n<p>O acompanhamento dos compartilhamentos sociais ajudou a equipe a ver n\u00e3o apenas <strong>quanto a campanha estava divulgando<\/strong>mas tamb\u00e9m <strong>quais emo\u00e7\u00f5es as pessoas associam a ele<\/strong>. Isso deu \u00e0 Mercedes-Benz e \u00e0 BBDO WWA uma vis\u00e3o mais clara do desempenho da campanha, al\u00e9m das curtidas ou cliques b\u00e1sicos.<\/p>\n\n\n\n<p>Em vez de tentar adivinhar se o conte\u00fado repercutiu, eles podiam rastrear:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>quantas pessoas participaram da conversa,<\/li>\n\n\n\n<li>quais hashtags e publica\u00e7\u00f5es ganharam for\u00e7a,<\/li>\n\n\n\n<li>como o p\u00fablico reagiu emocionalmente,<\/li>\n\n\n\n<li>se o buzz social se traduziu em maior engajamento na p\u00e1gina de destino.<\/li>\n<\/ul>\n\n\n\n<ol start=\"1\" class=\"wp-block-list\">\n<li><\/li>\n<\/ol>\n\n\n\n<p><a href=\"https:\/\/brand24.com\/pt\/estudo-de-caso\/mercedes-benz\/\" target=\"_blank\" rel=\"noopener\" title=\"Leia o estudo de caso completo &gt;\">Leia o estudo de caso completo &gt;<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"summary\">Resumo<\/h2>\n\n\n\n<p>Os compartilhamentos sociais ocorrem quando as pessoas compartilham seu conte\u00fado em seus pr\u00f3prios perfis de m\u00eddia social. Eles ajudam a divulgar seu conte\u00fado organicamente, aumentam o alcance e mostram o que repercute em seu p\u00fablico.<\/p>\n\n\n\n<p>O rastreamento dos compartilhamentos sociais ajuda a medir o desempenho da campanha, identificar momentos virais ou crises, entender o sentimento e reagir rapidamente aos mentions da marca.<\/p>\n\n\n<style>.acf-numeric-list__list{list-style:none;padding:0;margin:0}.acf-numeric-list__item{display:grid;grid-template-columns:1.875rem 1fr;grid-template-rows:1fr;align-items:center;gap:1.5625rem;margin-bottom:.9375rem}.acf-numeric-list__item:last-child{margin-bottom:0}.acf-numeric-list__number{background-color:#00ef88;color:#000;border-radius:50%;width:1.875rem;height:1.875rem;display:flex;align-items:center;justify-content:center;font-weight:600}<\/style><div class=\"acf-numeric-list\">\n    <ul class=\"acf-numeric-list__list\">\n                    <li class=\"acf-numeric-list__item\">\n                <span class=\"acf-numeric-list__number\">1<\/span>\n                <span class=\"acf-numeric-list__text\">Crie uma hashtag de campanha exclusiva.<\/span>\n            <\/li>\n                    <li class=\"acf-numeric-list__item\">\n                <span class=\"acf-numeric-list__number\">2<\/span>\n                <span class=\"acf-numeric-list__text\">Adicione par\u00e2metros UTM a todos os links sociais.<\/span>\n            <\/li>\n                    <li class=\"acf-numeric-list__item\">\n                <span class=\"acf-numeric-list__number\">3<\/span>\n                <span class=\"acf-numeric-list__text\">Configure projetos Brand24 separados para rastreamento de marca e campanha.<\/span>\n            <\/li>\n                    <li class=\"acf-numeric-list__item\">\n                <span class=\"acf-numeric-list__number\">4<\/span>\n                <span class=\"acf-numeric-list__text\">Monitore o alcance, as intera\u00e7\u00f5es, o sentimento e os picos de mention.<\/span>\n            <\/li>\n                    <li class=\"acf-numeric-list__item\">\n                <span class=\"acf-numeric-list__number\">5<\/span>\n                <span class=\"acf-numeric-list__text\">Verifique o sentimento junto com o alcance, n\u00e3o separadamente.<\/span>\n            <\/li>\n                    <li class=\"acf-numeric-list__item\">\n                <span class=\"acf-numeric-list__number\">6<\/span>\n                <span class=\"acf-numeric-list__text\">Reagir rapidamente a mentions positivos e negativos.<\/span>\n            <\/li>\n                    <li class=\"acf-numeric-list__item\">\n                <span class=\"acf-numeric-list__number\">7<\/span>\n                <span class=\"acf-numeric-list__text\">Use os insights para melhorar o conte\u00fado e as campanhas futuras.<\/span>\n            <\/li>\n            <\/ul>\n<\/div>\n\n\n\n<div class=\"acf-simple-cta acf-simple-cta--default acf-simple-cta--no-icon\">\n    <div class=\"acf-simple-cta__wrapper\">\n        <div class=\"acf-simple-cta__row\">\n            <div class=\"acf-simple-cta__content\">\n                                                    <div class=\"acf-simple-cta__title\">Acompanhe os compartilhamentos sociais!<\/div>\n                            <\/div>\n                            <a href=\"https:\/\/app.brand24.com\/user\/register-account\/?custom_form=55\" class=\"acf-simple-cta__btn\" target=\"_blank\">Inicie o teste!<\/a>\n                    <\/div>\n    <\/div>\n<\/div>\n\n\n\n<h2 class=\"wp-block-heading\">PERGUNTAS FREQUENTES<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">Quais s\u00e3o os benef\u00edcios de monitorar os compartilhamentos sociais?<\/h3>\n\n\n\n<p>Esperamos que agora voc\u00ea possa ver que rastrear seus compartilhamentos sociais pode ser t\u00e3o f\u00e1cil quanto uma torta. <\/p>\n\n\n\n<p>O rastreamento de compartilhamentos de m\u00eddia social tem v\u00e1rias aplica\u00e7\u00f5es no marketing de m\u00eddia social. Ele ir\u00e1:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>fornecer insights sobre como seu conte\u00fado se espalha pela Web<\/li>\n\n\n\n<li>indicar que tipo de conte\u00fado repercute melhor no seu p\u00fablico-alvo, tanto em termos de engajamento na m\u00eddia social quanto de sentimento<\/li>\n\n\n\n<li>ajud\u00e1-lo a medir os resultados de suas campanhas de m\u00eddia social<\/li>\n\n\n\n<li>permitem reagir rapidamente a mentions sobre sua marca que aparecem al\u00e9m de seus canais de m\u00eddia social<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">O que \u00e9 um exemplo de compartilhamento social?<\/h3>\n\n\n\n<p>Um compartilhamento social \u00e9 o ato de compartilhar conte\u00fado de um site ou plataforma no perfil pessoal de m\u00eddia social de um usu\u00e1rio. Isso pode incluir o compartilhamento de uma publica\u00e7\u00e3o de blog, um artigo de not\u00edcias, um infogr\u00e1fico, um v\u00eddeo ou at\u00e9 mesmo uma simples publica\u00e7\u00e3o ou coment\u00e1rio. <\/p>\n\n\n\n<p>Por exemplo, se voc\u00ea encontrar uma publica\u00e7\u00e3o de blog no site da Brand24 que considere interessante e clicar no bot\u00e3o \u2018Compartilhar\u2019 para public\u00e1-la em seu perfil do Facebook, Twitter ou LinkedIn, isso ser\u00e1 considerado um \u2018compartilhamento social\u2019. <\/p>\n\n\n\n<p>O objetivo \u00e9 exibir compartilhamentos de m\u00eddia social e disseminar o conte\u00fado para um p\u00fablico mais amplo al\u00e9m da plataforma original.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Voc\u00ea pode monitorar os compartilhamentos sociais gratuitamente? <\/strong><\/h3>\n\n\n\n<p>Sim, at\u00e9 certo ponto. O Google Analytics rastreia o tr\u00e1fego de refer\u00eancia da m\u00eddia social sem nenhum custo. Para um rastreamento de compartilhamento mais detalhado, ferramentas como Brand24 ou Hootsuite oferecem testes gratuitos. <\/p>\n\n\n\n<p>Observe que o X e o LinkedIn descontinuaram suas APIs de contagem de compartilhamentos, o que significa que n\u00e3o \u00e9 mais poss\u00edvel para nenhum servi\u00e7o recuperar contagens de compartilhamentos diretamente dessas plataformas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">O que \u00e9 o rastreador social?<\/h3>\n\n\n\n<p>Um rastreador social \u00e9 uma ferramenta que monitora as atividades em v\u00e1rias plataformas de m\u00eddia social. Ele captura dados sociais e interpreta m\u00e9tricas de envolvimento, como curtidas, compartilhamentos, coment\u00e1rios e seguidores. <\/p>\n\n\n\n<p>Essa ferramenta ajuda as empresas a entender suas <a href=\"https:\/\/brand24.com\/blog\/pt\/desempenho-on-line\/\" target=\"_blank\" rel=\"noopener\" title=\"\">desempenho on-line<\/a> e informa futuras estrat\u00e9gias de m\u00eddia social para melhorar o envolvimento do p\u00fablico.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Como rastrear compartilhamentos sociais no Google Analytics?<\/h3>\n\n\n\n<p>Uso <strong>Eventos GA4<\/strong>: O Google recomenda o <code>compartilhar<\/code> evento para casos em que um usu\u00e1rio compartilha conte\u00fado do seu site ou aplicativo.&nbsp;<\/p>\n\n\n<div class=\"acf-numeric-list\">\n    <ul class=\"acf-numeric-list__list\">\n                    <li class=\"acf-numeric-list__item\">\n                <span class=\"acf-numeric-list__number\">1<\/span>\n                <span class=\"acf-numeric-list__text\">Configure-o com o Gerenciador de tags do Google para que o evento seja acionado quando algu\u00e9m clicar em seus bot\u00f5es de compartilhamento social e adicione par\u00e2metros como m\u00e9todo - Facebook, LinkedIn, X - e content_type ou item_id.<\/span>\n            <\/li>\n                    <li class=\"acf-numeric-list__item\">\n                <span class=\"acf-numeric-list__number\">2<\/span>\n                <span class=\"acf-numeric-list__text\">Em seguida, verifique os dados em GA4 \u2192 Relat\u00f3rios \u2192 Engajamento \u2192 Eventos ou crie um relat\u00f3rio do Explore filtrado pelo evento de compartilhamento.<\/span>\n            <\/li>\n                    <li class=\"acf-numeric-list__item\">\n                <span class=\"acf-numeric-list__number\">3<\/span>\n                <span class=\"acf-numeric-list__text\">Para rastrear o tr\u00e1fego de publica\u00e7\u00f5es sociais para o seu site, use links com tags UTM, pois a detec\u00e7\u00e3o autom\u00e1tica de fontes sociais do GA4 \u00e9 \u00fatil, mas nem sempre perfeita.<\/span>\n            <\/li>\n            <\/ul>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Como \u00e9 calculada a contagem de compartilhamentos sociais?<\/h3>\n\n\n\n<p>A forma como a contagem de compartilhamentos \u00e9 calculada varia de acordo com a rede social. Algumas redes contam apenas o n\u00famero de vezes que um link foi compartilhado, enquanto outras incluem a\u00e7\u00f5es sociais como curtidas e coment\u00e1rios no total.<\/p>\n\n\n\n<div class=\"acf-simple-cta acf-simple-cta--default acf-simple-cta--no-icon\">\n    <div class=\"acf-simple-cta__wrapper\">\n        <div class=\"acf-simple-cta__row\">\n            <div class=\"acf-simple-cta__content\">\n                                                    <div class=\"acf-simple-cta__title\">Acompanhe os compartilhamentos sociais!<\/div>\n                            <\/div>\n                            <a href=\"https:\/\/app.brand24.com\/user\/register-account\/?custom_form=55\" class=\"acf-simple-cta__btn\" target=\"_blank\">Inicie o teste!<\/a>\n                    <\/div>\n    <\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Acompanhe os compartilhamentos sociais para ver quem compartilha seu conte\u00fado e qual plataforma seu p\u00fablico escolhe!<\/p>","protected":false},"author":78,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[112],"tags":[3930,3924,3927],"class_list":["post-131721","post","type-post","status-publish","format-standard","hentry","category-social-listening","tag-social-shares","tag-track-social-shares","tag-tracking-social-shares"],"acf":[],"aioseo_notices":[],"cf_author_first_name":"Waleria","cf_author_last_name":"P\u0105gowska","_links":{"self":[{"href":"https:\/\/brand24.com\/blog\/pt\/wp-json\/wp\/v2\/posts\/131721","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/brand24.com\/blog\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/brand24.com\/blog\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/brand24.com\/blog\/pt\/wp-json\/wp\/v2\/users\/78"}],"replies":[{"embeddable":true,"href":"https:\/\/brand24.com\/blog\/pt\/wp-json\/wp\/v2\/comments?post=131721"}],"version-history":[{"count":40,"href":"https:\/\/brand24.com\/blog\/pt\/wp-json\/wp\/v2\/posts\/131721\/revisions"}],"predecessor-version":[{"id":183634,"href":"https:\/\/brand24.com\/blog\/pt\/wp-json\/wp\/v2\/posts\/131721\/revisions\/183634"}],"wp:attachment":[{"href":"https:\/\/brand24.com\/blog\/pt\/wp-json\/wp\/v2\/media?parent=131721"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/brand24.com\/blog\/pt\/wp-json\/wp\/v2\/categories?post=131721"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/brand24.com\/blog\/pt\/wp-json\/wp\/v2\/tags?post=131721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}