{"id":152725,"date":"2022-03-03T14:32:30","date_gmt":"2022-03-03T13:32:30","guid":{"rendered":"https:\/\/brand24.com\/blog\/?p=152725"},"modified":"2026-04-10T12:23:09","modified_gmt":"2026-04-10T10:23:09","slug":"como-detectar-a-desinformacao-on-line","status":"publish","type":"post","link":"https:\/\/brand24.com\/blog\/pt\/how-to-spot-disinformation-online\/","title":{"rendered":"Como identificar a desinforma\u00e7\u00e3o on-line? Um breve guia para detectar bots, trolls e falsifica\u00e7\u00f5es"},"content":{"rendered":"<p>Como agora quase todo mundo pode ter acesso \u00e0 Internet, h\u00e1 muitas pessoas (ou <em>coisas<\/em>) que talvez n\u00e3o devessem. Essa situa\u00e7\u00e3o cria possibilidades infinitas para a dissemina\u00e7\u00e3o de desinforma\u00e7\u00e3o, not\u00edcias falsas e propaganda prejudicial. Aqui est\u00e3o algumas coisas que voc\u00ea deve saber ao navegar na Web para se proteger de informa\u00e7\u00f5es falsas.<\/p>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a03f5112b1ff&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a03f5112b1ff\" class=\"wp-block-image size-full wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"300\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/brand24.com\/blog\/wp-content\/uploads\/2022\/03\/fake_news_trolle_boty-2.png\" alt=\"\" class=\"wp-image-152742\" srcset=\"https:\/\/brand24.com\/blog\/app\/uploads\/2022\/03\/fake_news_trolle_boty-2.png 750w, https:\/\/brand24.com\/blog\/app\/uploads\/2022\/03\/fake_news_trolle_boty-2-300x120.png 300w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ampliar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"#whats-this-article-about\">Sobre o que \u00e9 esse artigo?<\/a><\/li>\n\n\n\n<li><a href=\"#why-does-it-matter\">Por que isso \u00e9 importante?<\/a><\/li>\n\n\n\n<li><a href=\"#follow-only-trusted-sources\">Siga apenas fontes confi\u00e1veis<\/a><\/li>\n\n\n\n<li><a href=\"#be-careful-reading-news-on-social-media\">Tenha cuidado ao ler not\u00edcias nas m\u00eddias sociais<\/a><\/li>\n\n\n\n<li><a href=\"#verify-influencers-and-activists\">Verificar influenciadores e ativistas <\/a><\/li>\n\n\n\n<li><a href=\"#pay-extra-attention-to-emotional-messages\">Preste mais aten\u00e7\u00e3o \u00e0s mensagens emocionais<\/a><\/li>\n\n\n\n<li><a href=\"#lengthy-analyses-are-much-more-reliable\">An\u00e1lises longas s\u00e3o muito mais confi\u00e1veis<\/a><\/li>\n\n\n\n<li><a href=\"#fact-checking-sites-are-your-friends\">Os sites de verifica\u00e7\u00e3o de fatos s\u00e3o seus amigos<\/a><\/li>\n\n\n\n<li><a href=\"#dont-believe-every-video-or-photo-you-see\">N\u00e3o acredite em todos os v\u00eddeos ou fotos que voc\u00ea v\u00ea<\/a><\/li>\n\n\n\n<li><a href=\"#read-full-articles\">Leia artigos completos, n\u00e3o apenas os t\u00edtulos<\/a><\/li>\n\n\n\n<li><a href=\"#how-to-spot-bots-and-trolls\">Como identificar bots e trolls que espalham informa\u00e7\u00f5es<\/a><\/li>\n\n\n\n<li><a href=\"#our-commentary\">Nosso coment\u00e1rio<\/a><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"whats-this-article-about\">Sobre o que \u00e9 esse artigo?<\/h2>\n\n\n\n<p>Agora, n\u00e3o me entenda mal. N\u00e3o quero lhe dizer que esta e aquela informa\u00e7\u00e3o s\u00e3o falsas ou que voc\u00ea deve denunciar este e aquele bot ao Twitter. Quero lhe dar conselhos diretos sobre como identificar poss\u00edveis not\u00edcias falsas ou um bot espalhando desinforma\u00e7\u00e3o.<\/p>\n\n\n\n<p>Acho que todos concordamos que h\u00e1 muito conte\u00fado potencialmente prejudicial na Internet. \u00c9 muito f\u00e1cil ser v\u00edtima de propaganda falsa e espalhar not\u00edcias falsas sem querer. Especialmente em tempos de crise, podemos observar um aumento maci\u00e7o de desinforma\u00e7\u00e3o, muitas vezes compartilhada por pessoas que n\u00e3o est\u00e3o cientes disso. Isso acontece quando as emo\u00e7\u00f5es s\u00e3o mais fortes do que o bom senso. \u00c9 compreens\u00edvel.&nbsp;<\/p>\n\n\n\n<p>Como \u00e9 muito f\u00e1cil cair em uma espiral de emo\u00e7\u00f5es negativas e, sem querer, espalhar informa\u00e7\u00f5es falsas, preparamos algumas dicas que podem ajud\u00e1-lo a identificar fakes, bots e trolls on-line.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"why-does-it-matter\">Por que isso \u00e9 importante?<\/h2>\n\n\n\n<p>Para ter uma compreens\u00e3o completa do que est\u00e1 acontecendo, voc\u00ea deve ter acesso a informa\u00e7\u00f5es objetivas para poder desenvolver sua opini\u00e3o pessoal. Algumas not\u00edcias podem ser tendenciosas e mostrar apenas uma fra\u00e7\u00e3o do que realmente est\u00e1 acontecendo. Outras s\u00e3o totalmente falsas e seu objetivo \u00e9 provocar p\u00e2nico, mudar a opini\u00e3o sobre alguns assuntos ou causar distra\u00e7\u00e3o.<\/p>\n\n\n\n<p>Voc\u00ea precisa estar ciente de como alguns mecanismos funcionam para n\u00e3o se tornar v\u00edtima de desinforma\u00e7\u00e3o e espalhar fatos falsos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"follow-only-trusted-sources\">Siga apenas fontes confi\u00e1veis<\/h2>\n\n\n\n<p>O primeiro conselho, e talvez o mais importante, \u00e9: tenha uma lista de fontes confi\u00e1veis e consuma suas informa\u00e7\u00f5es somente l\u00e1.&nbsp;<\/p>\n\n\n\n<p>Servi\u00e7os de informa\u00e7\u00f5es populares como BBC News, CNN ou Huffington Post t\u00eam menos probabilidade de divulgar informa\u00e7\u00f5es n\u00e3o confirmadas do que alguns sites desconhecidos. Eles tamb\u00e9m podem ser tendenciosos, mas t\u00eam uma grande reputa\u00e7\u00e3o a proteger e sempre tentam verificar as fontes para apresentar a vers\u00e3o mais precisa do que est\u00e1 acontecendo.&nbsp;<\/p>\n\n\n\n<p>No entanto, mesmo sites como a BBC podem, \u00e0s vezes, disseminar informa\u00e7\u00f5es err\u00f4neas de forma n\u00e3o intencional. Foi o que aconteceu durante a atual guerra na Ucr\u00e2nia, quando a empresa de radiodifus\u00e3o compartilhou not\u00edcias sobre refugiados n\u00e3o ucranianos que escapavam da zona de guerra e que poderiam ser prejudiciais \u00e0 Pol\u00f4nia. O tweet foi corrigido posteriormente.<\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">\"O \u00faltimo dia na Ucr\u00e2nia foi muito, muito dif\u00edcil para mim... Os militares de l\u00e1 eram muito maus\"<br><br>O estudante nigeriano Gabriel descreve como foi tratado quando tentou embarcar em um trem para tentar sair da Ucr\u00e2nia<a href=\"https:\/\/t.co\/bO31PWu6wW\">https:\/\/t.co\/bO31PWu6wW<\/a> <a href=\"https:\/\/t.co\/4wp2UcqcAB\">https:\/\/t.co\/4wp2UcqcAB<\/a> <a href=\"https:\/\/t.co\/O2NzJZ6GrT\">pic.twitter.com\/O2NzJZ6GrT<\/a><\/p>- BBC News (Mundo) (@BBCWorld) <a href=\"https:\/\/twitter.com\/BBCWorld\/status\/1498372430498340869?ref_src=twsrc%5Etfw\">28 de fevereiro de 2022<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"be-careful-reading-news-on-social-media\">Tenha cuidado ao ler not\u00edcias nas m\u00eddias sociais<\/h2>\n\n\n\n<p>Por mais que eu goste do Twitter, ele pode ser um caso desagrad\u00e1vel de dissemina\u00e7\u00e3o de desinforma\u00e7\u00e3o. Os tweets s\u00e3o relativamente curtos e raramente s\u00e3o respaldados por fontes e confirma\u00e7\u00f5es. \u00c9 uma excelente ferramenta para que bots e trolls compartilhem not\u00edcias falsas.<\/p>\n\n\n\n<p>O mesmo vale para outras m\u00eddias sociais. \u00c9 f\u00e1cil publicar um coment\u00e1rio dizendo: \"Acabei de saber que aconteceu xxx. N\u00e3o tenho confirma\u00e7\u00e3o da not\u00edcia, mas minha fonte \u00e9 muito confi\u00e1vel\". Essa mensagem \u00e9 confi\u00e1vel? Bem, qualquer pessoa pode dizer qualquer coisa na Internet. Ela pode ser precisa, mas tamb\u00e9m pode ser apenas um troll da Internet que quer causar confus\u00e3o.<\/p>\n\n\n\n<p>Sempre, SEMPRE, verifique as fontes confi\u00e1veis de informa\u00e7\u00e3o antes de encaminhar as not\u00edcias para outra pessoa. \u00c9 muito f\u00e1cil espalhar informa\u00e7\u00f5es err\u00f4neas, mas \u00e9 muito dif\u00edcil retir\u00e1-las. As not\u00edcias falsas come\u00e7am a circular, podem ser muito emocionais (e, portanto, mais propensas a serem compartilhadas) e causar p\u00e2nico. A corre\u00e7\u00e3o n\u00e3o \u00e9 t\u00e3o interessante, n\u00e3o \u00e9 emocional e tem muito menos probabilidade de se tornar viral.&nbsp;<\/p>\n\n\n\n<p>Isso tamb\u00e9m \u00e9 problem\u00e1tico quando as celebridades compartilham informa\u00e7\u00f5es. Isso nos leva \u00e0 pr\u00f3xima parte.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"verify-influencers-and-activists\">Verificar influenciadores e ativistas<\/h2>\n\n\n\n<p>No mundo de hoje, muitas informa\u00e7\u00f5es v\u00eam de nossas celebridades, influenciadores e ativistas favoritos. E isso n\u00e3o tem problema, desde que voc\u00ea verifique as not\u00edcias. Provavelmente, h\u00e1 algumas pessoas em quem podemos confiar mais, mas lembre-se de que muitos influenciadores do Instagram podem ser facilmente comprados.&nbsp;<\/p>\n\n\n\n<p>Se voc\u00ea notar uma mudan\u00e7a repentina de opini\u00e3o ou se uma pessoa que normalmente se abst\u00e9m de not\u00edcias pol\u00edticas se envolver intensamente em algum t\u00f3pico, verifique se o que ela diz n\u00e3o \u00e9 muito diferente do que as fontes oficiais e os servi\u00e7os de not\u00edcias populares anunciam.<\/p>\n\n\n\n<p>N\u00e3o \u00e9 que eles possam ter se tornado trolls pagos para espalhar propaganda falsa - suas contas tamb\u00e9m poderiam ter sido facilmente hackeadas.&nbsp;<\/p>\n\n\n\n<p>N\u00e3o estou dizendo que voc\u00ea nunca deve confiar em influenciadores e celebridades, mas, a menos que confie neles 100%, talvez seja melhor fazer uma verifica\u00e7\u00e3o dos fatos por conta pr\u00f3pria. Felizmente, h\u00e1 muitos sites que verificam not\u00edcias virais.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"pay-extra-attention-to-emotional-messages\">Preste mais aten\u00e7\u00e3o \u00e0s mensagens emocionais<\/h2>\n\n\n\n<p>As not\u00edcias falsas, a propaganda e a desinforma\u00e7\u00e3o dependem muito das emo\u00e7\u00f5es. Elas pretendem despertar emo\u00e7\u00f5es fortes (positivas ou negativas) para que algu\u00e9m fique mais disposto a compartilhar as informa\u00e7\u00f5es. Relat\u00f3rios objetivos com muitas fontes e confirma\u00e7\u00f5es podem parecer ma\u00e7antes.&nbsp;<\/p>\n\n\n\n<p>J\u00e1 escrevi sobre tweets curtos antes - \u00e9 muito f\u00e1cil simplesmente repassar uma mensagem no Twitter. Suas curtidas tamb\u00e9m podem ficar vis\u00edveis para seus seguidores. Basta um tweet emocionado dizendo que algo est\u00e1 acontecendo no momento e milhares de pessoas podem v\u00ea-lo antes de ser verificado.&nbsp;<\/p>\n\n\n\n<p>N\u00e3o estou dizendo que tudo o que \u00e9 emocional n\u00e3o \u00e9 v\u00e1lido, mas antes de curtir ou retuitar (isso tamb\u00e9m se aplica a outras m\u00eddias sociais - observe o que voc\u00ea compartilha no Facebook, no Linkedin ou em chats como Whatsapp ou Telegram), certifique-se de conhecer a fonte das informa\u00e7\u00f5es. Se for um blogueiro, pol\u00edtico ou ativista em quem voc\u00ea confia e sabe que ele n\u00e3o \u00e9 propenso a mentir e faz sua pr\u00f3pria verifica\u00e7\u00e3o de fatos, provavelmente voc\u00ea est\u00e1 seguro. Mas se for um perfil desconhecido, considere o que ele diz com cautela.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"lengthy-analyses-are-much-more-reliable\">An\u00e1lises longas s\u00e3o muito mais confi\u00e1veis<\/h2>\n\n\n\n<p>Como eu disse antes, \u00e9 f\u00e1cil manipular o receptor com uma mensagem emocional curta. Ainda assim, uma an\u00e1lise profunda com links para fontes, cita\u00e7\u00f5es de especialistas e sentimentos n\u00e3o t\u00e3o acalorados s\u00e3o muito mais valiosos.&nbsp;<\/p>\n\n\n\n<p>Em primeiro lugar, eles analisam o problema de uma perspectiva mais ampla. Essa an\u00e1lise omite menos fatos e mostra mais aspectos da quest\u00e3o.&nbsp;<\/p>\n\n\n\n<p>Em segundo lugar, eles geralmente incluem opini\u00f5es de especialistas, o que significa que voc\u00ea absorve o conhecimento de algu\u00e9m que estudou o problema anteriormente e tem anos de forma\u00e7\u00e3o para respaldar o que tem a dizer.<\/p>\n\n\n\n<p>Por \u00faltimo, mas n\u00e3o menos importante, mesmo que sejam formadores de opini\u00e3o, pelo menos s\u00e3o baseados em fatos, n\u00e3o em emo\u00e7\u00f5es.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"fact-checking-sites-are-your-friends\">Os sites de verifica\u00e7\u00e3o de fatos s\u00e3o seus amigos<\/h2>\n\n\n\n<p>Embora muitas pessoas tentem desacredit\u00e1-las, h\u00e1 muitos sites de verifica\u00e7\u00e3o de fatos que verificam as not\u00edcias virais que circulam na Internet.&nbsp;<\/p>\n\n\n\n<p>Se uma informa\u00e7\u00e3o parecer boa demais para ser verdade, for muito emocional ou atacar algu\u00e9m, isso deve ser um sinal de alerta para voc\u00ea antes de come\u00e7ar a divulgar materiais prejudiciais. Sempre verifique os fatos de tudo o que vem de uma fonte desconhecida e n\u00e3o confi\u00e1vel.&nbsp;<\/p>\n\n\n\n<p>Aqui est\u00e3o alguns dos sites de verifica\u00e7\u00e3o de fatos que voc\u00ea pode experimentar:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.poynter.org\/news\/fact-checking\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Poynter<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/edition.cnn.com\/specials\/politics\/fact-check-politics\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Verifica\u00e7\u00e3o de fatos da CNN<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.truthorfiction.com\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">Verdade ou fic\u00e7\u00e3o<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.politifact.com\/\" target=\"_blank\" rel=\"noopener nofollow\" title=\"\">PolitiFact<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.snopes.com\/\" target=\"_blank\" rel=\"noopener nofollow\" title=\"\">Snopes<\/a><\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"dont-believe-every-video-or-photo-you-see\">N\u00e3o acredite em todos os v\u00eddeos ou fotos que voc\u00ea v\u00ea<\/h2>\n\n\n\n<p>\u00c9 claro que uma foto \u00e9 uma evid\u00eancia muito melhor do que um tweet aleat\u00f3rio ou um coment\u00e1rio no Facebook, mas voc\u00ea deve saber que v\u00e1rias fontes as usam no contexto errado para divulgar propaganda.&nbsp;<\/p>\n\n\n\n<p>V\u00eddeos e fotos tamb\u00e9m podem ser facilmente fabricados.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"read-full-articles\">Leia artigos completos, n\u00e3o apenas os t\u00edtulos<\/h2>\n\n\n\n<p>Atualmente, muitos sites dependem de artigos clickbait para obter o maior n\u00famero poss\u00edvel de visitantes. Isso \u00e9 um pouco inc\u00f4modo, mas \u00e0s vezes o tiro pode sair pela culatra. Como muitas pessoas leem apenas os t\u00edtulos, elas podem n\u00e3o ter uma vis\u00e3o completa do assunto.<\/p>\n\n\n\n<p>Por exemplo, houve uma corrida entre dois atletas. Vamos cham\u00e1-los de Josh e Adam. Josh chegou em primeiro lugar e Adam em segundo, e ambos tiveram um tempo semelhante. Essas duas afirma\u00e7\u00f5es s\u00e3o factuais:<\/p>\n\n\n\n<p>\"Os resultados do Adam foram perfeitos. Ele ficou em segundo lugar.\"<\/p>\n\n\n\n<p>\"Adam teve um desempenho ruim. Ele ficou em \u00faltimo lugar.\"<\/p>\n\n\n\n<p>Est\u00e1 vendo? Com base apenas nessas duas declara\u00e7\u00f5es, voc\u00ea pode pensar que Adam \u00e9 um \u00f3timo corredor ou um mau corredor. Somente quando voc\u00ea conhecer toda a hist\u00f3ria e o contexto \u00e9 que sua opini\u00e3o n\u00e3o ser\u00e1 tendenciosa.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"how-to-spot-bots-and-trolls\">Como identificar bots e trolls que espalham informa\u00e7\u00f5es<\/h2>\n\n\n\n<p>\u00c0s vezes, \u00e9 dif\u00edcil distinguir um bot ou um troll pago de uma pessoa que est\u00e1 espalhando desinforma\u00e7\u00e3o por acreditar nela. Alguns fatores, no entanto, podem ajud\u00e1-lo a identificar um bot criado para espalhar propaganda prejudicial.<\/p>\n\n\n\n<p>Lembre-se de que, atualmente, a intelig\u00eancia artificial pode escrever artigos inteiros e, \u00e0s vezes, eles s\u00e3o indistingu\u00edveis daqueles escritos por uma pessoa real. J\u00e1 se foi o tempo em que os textos da IA eram repletos de erros gramaticais e estruturas de frases estranhas.<\/p>\n\n\n\n<p>Antes de tudo, verifique o nome da conta. Os bots primitivos geralmente t\u00eam uma sequ\u00eancia de n\u00fameros ou letras aleat\u00f3rias no URL do perfil. Isso n\u00e3o significa automaticamente que a conta \u00e9 falsa, mas \u00e9 um sinal de alerta.<\/p>\n\n\n\n<p>A segunda coisa que vale a pena verificar \u00e9 a idade da conta. Os bots geralmente t\u00eam vida curta, pois s\u00e3o banidos quando denunciados. Perfis novos com pequeno n\u00famero de seguidores s\u00e3o definitivamente suspeitos.&nbsp;<\/p>\n\n\n\n<p>Veja sobre o que eles t\u00eam falado recentemente. Alguns assuntos s\u00e3o obviamente mais importantes, de modo que as pessoas podem estar falando apenas de um assunto durante um curto per\u00edodo de tempo. Mas se uma pessoa discute constantemente apenas um assunto e usa frases e palavras semelhantes em cada publica\u00e7\u00e3o, esse pode ser um perfil criado para divulgar propaganda.&nbsp;<\/p>\n\n\n\n<p>Os trolls e bots falsos geralmente usam palavras extremas, mensagens emocionais e espalham o p\u00e2nico. Se voc\u00ea vir uma publica\u00e7\u00e3o que possa ser polarizadora, tenha muito cuidado antes de compartilh\u00e1-la.&nbsp;<\/p>\n\n\n\n<p>Se voc\u00ea acha que isso pode ser um bot ou um troll, a melhor coisa a fazer \u00e9 denunciar o fato aos moderadores. N\u00e3o reaja \u00e0 publica\u00e7\u00e3o, n\u00e3o comente, n\u00e3o tente discutir. Isso s\u00f3 ajudar\u00e1 a atingir um p\u00fablico mais amplo.<\/p>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a03f5112c2be&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a03f5112c2be\" class=\"wp-block-image size-full wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1112\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/brand24.com\/blog\/wp-content\/uploads\/2022\/03\/reporting-1.png\" alt=\"\" class=\"wp-image-152737\" srcset=\"https:\/\/brand24.com\/blog\/app\/uploads\/2022\/03\/reporting-1.png 1080w, https:\/\/brand24.com\/blog\/app\/uploads\/2022\/03\/reporting-1-300x309.png 300w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ampliar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><figcaption class=\"wp-element-caption\">Denunciar uma publica\u00e7\u00e3o no Twitter.<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"our-commentary\">Nosso coment\u00e1rio<\/h2>\n\n\n\n<p>Embora existam v\u00e1rias maneiras de identificar not\u00edcias falsas e desinforma\u00e7\u00e3o, algumas hist\u00f3rias s\u00e3o dif\u00edceis de verificar e circulam pela Internet compartilhadas por pessoas desavisadas. Esperamos que, com nossas dicas, voc\u00ea consiga distinguir entre uma fonte confi\u00e1vel e uma propaganda.&nbsp;<\/p>\n\n\n\n<p>No contexto dos \u00faltimos acontecimentos, a Brand24 est\u00e1 ao lado da Ucr\u00e2nia e estamos profundamente preocupados com a invas\u00e3o russa. Como uma empresa polonesa, onde a guerra est\u00e1 acontecendo do outro lado da nossa fronteira leste, nos sentimos obrigados a ajudar os necessitados de todas as formas poss\u00edveis.&nbsp;<\/p>\n\n\n\n<p>Usamos nossa ferramenta em uma campanha para combater bots falsos que espalham desinforma\u00e7\u00e3o e trabalhamos com dezenas de organiza\u00e7\u00f5es verificadas que fazem o mesmo. Juntos, conseguimos identificar rapidamente o conte\u00fado nocivo e denunciar as contas. Al\u00e9m disso, nos envolvemos pessoalmente e em equipe para organizar ajuda, transporte e suporte material.<\/p>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a03f5112cbbf&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a03f5112cbbf\" class=\"wp-block-image aligncenter size-full wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"2000\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/brand24.com\/blog\/wp-content\/uploads\/2022\/03\/disinformation-infographic.png\" alt=\"\" class=\"wp-image-152732\" srcset=\"https:\/\/brand24.com\/blog\/app\/uploads\/2022\/03\/disinformation-infographic.png 800w, https:\/\/brand24.com\/blog\/app\/uploads\/2022\/03\/disinformation-infographic-614x1536.png 614w, https:\/\/brand24.com\/blog\/app\/uploads\/2022\/03\/disinformation-infographic-300x750.png 300w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ampliar\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewbox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>","protected":false},"excerpt":{"rendered":"<p>Aqui est\u00e3o algumas coisas que voc\u00ea deve saber ao navegar na Web para se proteger de informa\u00e7\u00f5es falsas.<\/p>","protected":false},"author":77,"featured_media":152742,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[3951],"tags":[],"class_list":["post-152725","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-media-monitoring"],"acf":[],"aioseo_notices":[],"cf_author_first_name":"Kuba","cf_author_last_name":"Spiryn","_links":{"self":[{"href":"https:\/\/brand24.com\/blog\/pt\/wp-json\/wp\/v2\/posts\/152725","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/brand24.com\/blog\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/brand24.com\/blog\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/brand24.com\/blog\/pt\/wp-json\/wp\/v2\/users\/77"}],"replies":[{"embeddable":true,"href":"https:\/\/brand24.com\/blog\/pt\/wp-json\/wp\/v2\/comments?post=152725"}],"version-history":[{"count":20,"href":"https:\/\/brand24.com\/blog\/pt\/wp-json\/wp\/v2\/posts\/152725\/revisions"}],"predecessor-version":[{"id":162666,"href":"https:\/\/brand24.com\/blog\/pt\/wp-json\/wp\/v2\/posts\/152725\/revisions\/162666"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/brand24.com\/blog\/pt\/wp-json\/wp\/v2\/media\/152742"}],"wp:attachment":[{"href":"https:\/\/brand24.com\/blog\/pt\/wp-json\/wp\/v2\/media?parent=152725"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/brand24.com\/blog\/pt\/wp-json\/wp\/v2\/categories?post=152725"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/brand24.com\/blog\/pt\/wp-json\/wp\/v2\/tags?post=152725"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}